{"id":22234,"date":"2021-11-29T18:57:41","date_gmt":"2021-11-29T21:57:41","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/?p=22234"},"modified":"2021-11-29T19:02:08","modified_gmt":"2021-11-29T22:02:08","slug":"barroso-autoriza-concursos-publicos-em-estados-e-municipios-em-recuperacao-fiscal","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/barroso-autoriza-concursos-publicos-em-estados-e-municipios-em-recuperacao-fiscal\/","title":{"rendered":"Barroso autoriza concursos p\u00fablicos em estados e munic\u00edpios em recupera\u00e7\u00e3o fiscal"},"content":{"rendered":"<h2>O ministro argumentou que a demora para repor as vagas abertas, em alguns casos, &#8220;compromete a presta\u00e7\u00e3o de servi\u00e7os p\u00fablicos essenciais \u00e0 coletividade<\/h2>\n<div><\/div>\n<div>O ministro Lu\u00eds Roberto Barroso, do Supremo Tribunal Federal (STF), concedeu nesta segunda-feira, 29, decis\u00e3o liminar (provis\u00f3ria) para permitir a realiza\u00e7\u00e3o de concursos em estados e munic\u00edpios que aderiram ao Regime de Recupera\u00e7\u00e3o Fiscal (RRF). A decis\u00e3o autoriza apenas a reposi\u00e7\u00e3o de cargos vagos &#8211; e n\u00e3o novas contrata\u00e7\u00f5es.<\/div>\n<div><span style=\"color: #ffffff;\">.<\/span><\/div>\n<div><\/div>\n<div>O ministro argumentou que a demora para repor as vagas abertas, em alguns casos, &#8220;compromete a presta\u00e7\u00e3o de servi\u00e7os p\u00fablicos essenciais \u00e0 coletividade&#8221;. O ministro enfatizou n\u00e3o se tratar de autoriza\u00e7\u00e3o para que prefeitos e governadores em situa\u00e7\u00e3o de recupera\u00e7\u00e3o fiscal nomeiem servidores para novos cargos, mas sim garantam que cargos vagos sejam ocupados com o objetivo de dar continuidade \u00e0s atividades essenciais.<\/div>\n<div><span style=\"color: #ffffff;\">.<\/span><\/div>\n<div><\/div>\n<div>&#8220;Restaria muito pouco da autonomia de estados, do Distrito Federal e de munic\u00edpios se n\u00e3o pudessem sequer admitir pessoal para manter seus quadros est\u00e1veis quando aderissem ao Regime de Recupera\u00e7\u00e3o Fiscal&#8221;, escreveu na decis\u00e3o.<\/div>\n<div><span style=\"color: #ffffff;\">.<\/span><\/div>\n<div><\/div>\n<div>No despacho, Barroso tamb\u00e9m autoriza excluir do teto de gastos de estados e munic\u00edpios os investimentos executados com recursos de fundos p\u00fablicos especiais. O dinheiro contido nesses fundos s\u00e3o vinculados por lei \u00e0 aplica\u00e7\u00e3o em obras, servi\u00e7os e objetivos previamente determinados. O ministro avalia que a vincula\u00e7\u00e3o ao teto de gastos produz contrassenso.<\/div>\n<div><span style=\"color: #ffffff;\">.<\/span><\/div>\n<div><\/div>\n<div>&#8220;A reten\u00e7\u00e3o, pela aplica\u00e7\u00e3o do teto de gastos, de recursos afetados aos fundos especiais impedir\u00e1 a execu\u00e7\u00e3o de investimentos em melhorias efetivas nos respectivos servi\u00e7os p\u00fablicos, sem fomentar a responsabilidade fiscal dos entes subnacionais, j\u00e1 que as verbas p\u00fablicas n\u00e3o retornar\u00e3o ao caixa \u00fanico do Tesouro por expressa veda\u00e7\u00e3o legal&#8221;, escreveu na decis\u00e3o.<\/div>\n<div><\/div>\n<div><span style=\"color: #ffffff;\">.<\/span><\/div>\n<div>O ministro imp\u00f5e como ressalva a obrigatoriedade de os gastos com recursos de fundos p\u00fablicos especiais n\u00e3o serem utilizados no pagamento de despesas obrigat\u00f3rias, tampouco aquelas relacionadas a gastos com custeio de funcion\u00e1rios. Ele argumenta ser prejudicial impedir o uso do dinheiro pelos governos, porque a lei restringe a aplica\u00e7\u00e3o em outras finalidades e imp\u00f5e destina\u00e7\u00e3o certa para determinadas \u00e1reas.<\/div>\n<div><\/div>\n<div><span style=\"color: #ffffff;\">.<\/span><\/div>\n<div>A decis\u00e3o foi imediatamente remetida para an\u00e1lise dos demais membros do Supremo em sess\u00e3o no plen\u00e1rio virtual.<\/div>\n<div><\/div>\n<div><span style=\"color: #ffffff;\">.<\/span><\/div>\n<div><\/div>\n<div><em>Da Ag\u00eancia Estado\u00a0<\/em><\/div>\n","protected":false},"excerpt":{"rendered":"<p>O ministro argumentou que a demora para repor as vagas abertas, em alguns casos, &#8220;compromete a presta\u00e7\u00e3o de servi\u00e7os p\u00fablicos essenciais \u00e0 coletividade O ministro Lu\u00eds Roberto Barroso, do Supremo Tribunal Federal (STF), concedeu nesta segunda-feira, 29, decis\u00e3o liminar (provis\u00f3ria) para permitir a realiza\u00e7\u00e3o de concursos em estados e munic\u00edpios que aderiram ao Regime de Recupera\u00e7\u00e3o Fiscal (RRF). A decis\u00e3o [&hellip;]<\/p>\n","protected":false},"author":32,"featured_media":16453,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[282],"tags":[1473,3472,33],"class_list":["post-22234","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-concursos","tag-barroso","tag-recuperacao-fiscal","tag-stf"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/22234","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/comments?post=22234"}],"version-history":[{"count":5,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/22234\/revisions"}],"predecessor-version":[{"id":22239,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/22234\/revisions\/22239"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/media\/16453"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/media?parent=22234"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/categories?post=22234"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/tags?post=22234"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}