{"id":19623,"date":"2021-07-08T08:18:20","date_gmt":"2021-07-08T11:18:20","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/?p=19623"},"modified":"2021-07-08T08:18:20","modified_gmt":"2021-07-08T11:18:20","slug":"banca-organizadora-e-condenada-a-pagar-indenizacao-apos-adiar-provas-sem-aviso-previo","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/banca-organizadora-e-condenada-a-pagar-indenizacao-apos-adiar-provas-sem-aviso-previo\/","title":{"rendered":"Banca organizadora \u00e9 condenada a pagar indeniza\u00e7\u00e3o ap\u00f3s adiar provas sem aviso pr\u00e9vio"},"content":{"rendered":"<h2>Ju\u00edza da 11\u00aa Vara Federal de Curitiba considerou que banca organizadora \u00e9 culpada por negligenciar problemas nos locais de aplica\u00e7\u00e3o<\/h2>\n<p>A 11\u00aa Vara Federal de Curitiba ordenou que a Universidade Federal do Paran\u00e1 (UFPR) pague cerca de cerca de R$5.400 para reparar danos materiais e morais contra um dos candidatos afetados pela suspens\u00e3o da prova do concurso para a Pol\u00edcia Civil do Paran\u00e1. A senten\u00e7a proferida pela ju\u00edza Silvia Regina Salau Brollo \u00e9 da \u00faltima segunda-feira (5\/7) e cabe recurso.<\/p>\n<p>O candidato processou a banca organizadora ap\u00f3s as provas do concurso p\u00fablico, <a href=\"http:\/\/concursos.correioweb.com.br\/app\/noticias\/2020\/11\/19\/noticiasinterna,41216\/policia-civil-do-parana-remarca-provas-do-concurso-com-400-vagas.shtml\">previstas para acontecer em 21 de fevereiro deste ano<\/a>, terem sido canceladas na madrugada do dia de aplica\u00e7\u00e3o do exame. O comunicado publicado \u00e0s 5h42 circulou nas redes sociais e gerou revolta nos participantes.<\/p>\n<p>Em sua defesa, a UFPR argumentou que alguns locais n\u00e3o estavam aptos para executar esta etapa, algo que impactaria 750 participantes. Dessa forma, a organiza\u00e7\u00e3o decidiu suspender o concurso.<\/p>\n<p>Na decis\u00e3o, a ju\u00edza diz que essas situa\u00e7\u00f5es j\u00e1 eram de conhecimento deles h\u00e1, pelo menos, seis meses. Sendo, portanto, poss\u00edveis de resolver antes da data de realiza\u00e7\u00e3o. Al\u00e9m disso, no edital do concurso, uma das diretrizes institui que qualquer condi\u00e7\u00e3o de realiza\u00e7\u00e3o da prova seria anunciada 72 horas antes da aplica\u00e7\u00e3o.<\/p>\n<p><strong>Novo cronograma<\/strong><br \/>\nEm maio, <a href=\"http:\/\/concursos.correioweb.com.br\/app\/noticias\/2021\/05\/04\/noticiasinterna,41798\/pcpr-retoma-oficialmente-concurso-publico-com-400-vagas.shtml\">a banca organizadora publicou em seu portal um novo calend\u00e1rio para o concurso PC PR<\/a>. A previs\u00e3o \u00e9 a de que as provas objetivas sejam realizadas no dia 3 de outubro de 2021 \u00e0s 13h30 com dura\u00e7\u00e3o de cinco horas. J\u00e1 a avalia\u00e7\u00e3o de conhecimentos deve acontecer no dia 12 de novembro.<\/p>\n<p><strong>Sobre o concurso<\/strong><br \/>\nO concurso PC PR oferece 400 vagas, sendo 50 para delegado de pol\u00edcia, 300 para investigador de pol\u00edcia e 50 para papiloscopista. Segundo informa\u00e7\u00f5es do edital de abertura, os sal\u00e1rios variam de R$ 5.588,05 a R$ 18.280,05, para uma jornada de trabalho de 40 horas semanais.<\/p>\n<p>Al\u00e9m dos exames citados, os candidatos passar\u00e3o por provas de t\u00edtulos, higidez f\u00edsica, aptid\u00e3o f\u00edsica e exame de investiga\u00e7\u00e3o de conduta.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ju\u00edza da 11\u00aa Vara Federal de Curitiba considerou que banca organizadora \u00e9 culpada por negligenciar problemas nos locais de aplica\u00e7\u00e3o A 11\u00aa Vara Federal de Curitiba ordenou que a Universidade Federal do Paran\u00e1 (UFPR) pague cerca de cerca de R$5.400 para reparar danos materiais e morais contra um dos candidatos afetados pela suspens\u00e3o da prova do concurso para a Pol\u00edcia [&hellip;]<\/p>\n","protected":false},"author":129,"featured_media":9746,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[532,282,4],"tags":[142,3014,3015,191],"class_list":["post-19623","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-carreira-policial","category-concursos","category-concursos-publicos","tag-parana","tag-pc-pr","tag-policia-militar-do-parana","tag-santa-catarina"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/19623","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/users\/129"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/comments?post=19623"}],"version-history":[{"count":2,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/19623\/revisions"}],"predecessor-version":[{"id":19625,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/19623\/revisions\/19625"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/media\/9746"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/media?parent=19623"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/categories?post=19623"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/tags?post=19623"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}