{"id":19600,"date":"2021-07-07T10:43:37","date_gmt":"2021-07-07T13:43:37","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/?p=19600"},"modified":"2021-07-07T10:43:37","modified_gmt":"2021-07-07T13:43:37","slug":"candidatos-ao-itamaraty-sao-surpreendidos-por-locais-de-prova-em-lojas-maconicas","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/candidatos-ao-itamaraty-sao-surpreendidos-por-locais-de-prova-em-lojas-maconicas\/","title":{"rendered":"Candidatos ao Itamaraty s\u00e3o surpreendidos por locais de prova em lojas ma\u00e7\u00f4nicas"},"content":{"rendered":"<p>O Instituto Rio Branco divulgou novidades sobre os locais de provas da segunda fase do concurso para diplomatas. Os exames ser\u00e3o realizados no pr\u00f3ximo s\u00e1bado (10\/7) e domingo (11\/7).\u00a0 O documento, publicado no site da banca Iades, aponta que alguns candidatos far\u00e3o as provas nas depend\u00eancias de lojas ma\u00e7\u00f4nicas. O local foi escolhido para estudantes de Jo\u00e3o Pessoa, Recife e Boa Vistas. <a href=\"https:\/\/www.iades.com.br\/inscricao\/upload\/273\/202107051211096.pdf\">Confira aqui os locais de prova.<\/a><\/p>\n<p>Ao Papo de Concurseiro, o Itamaraty informou que a\u00a0sele\u00e7\u00e3o dos locais de prova das diferentes etapas do concurso \u00e9 realizada pelo Iades. E, o processo \u00e9 feito com base na avalia\u00e7\u00e3o de aspectos log\u00edsticos, como disponibilidade e adequa\u00e7\u00e3o dos espa\u00e7os em cada cidade onde o certame \u00e9 realizado.<\/p>\n<h3>Orienta\u00e7\u00f5es para a segunda fase<\/h3>\n<div>\n<div>\n<div>O candidato dever\u00e1 comparecer ao local designado para a realiza\u00e7\u00e3o das provas com anteced\u00eancia m\u00ednima de uma hora dos hor\u00e1rios fixados para o in\u00edcio destas, munido de caneta esferogr\u00e1fica de tinta preta, fabricada em material transparente, do comprovante de inscri\u00e7\u00e3o e do documento de identidade original.<\/div>\n<div><\/div>\n<div>\n<p>A banca recomenda que cada candidato leve \u00e1gua para o seu pr\u00f3prio consumo, em embalagem transparente, para evitar a utiliza\u00e7\u00e3o de bebedouros ou de qualquer outro dispositivo de fornecimento coletivo de \u00e1gua para beber, e os alimento(s) devem estar fora da embalagem original, acondicionado(s) em embalagem porta-objetos de material transparente.<\/p>\n<\/div>\n<\/div>\n<div>A prova escrita de l\u00edngua portuguesa ser\u00e1 aplicada nas capitais onde houver candidatos aprovados na primeira fase, na data prov\u00e1vel de 10 de julho de 2021, e ter\u00e1 dura\u00e7\u00e3o de 5 horas, com in\u00edcio \u00e0s 14 horas.<\/div>\n<div><\/div>\n<div>\n<p>J\u00e1 o exame de l\u00edngua inglesa, na data prov\u00e1vel de 11 de julho de 2021, e ter\u00e1 dura\u00e7\u00e3o de 5 horas, com in\u00edcio \u00e0s 14 horas.<\/p>\n<\/div>\n<div>O edital com o resultado provis\u00f3rio na segunda fase ser\u00e1 divulgado na data prov\u00e1vel de 2 de agosto de 2021.<\/div>\n<div><\/div>\n<div>O candidato, que desejar interpor recurso contra o resultado provis\u00f3rio nas provas da Segunda Fase, dispor\u00e1 do per\u00edodo compreendido entre as 8 horas de 3 de agosto de 2021 e as 23 horas e 59 minutos de 4 de agosto de 2021.<\/div>\n<div><\/div>\n<div>As respostas aos recursos contra o resultado provis\u00f3rio na Segunda Fase, o resultado final na Segunda Fase e a convoca\u00e7\u00e3o para a Terceira Fase ser\u00e3o divulgados no site da banca e publicados no Di\u00e1rio Oficial da Uni\u00e3o, na data prov\u00e1vel de 20 de agosto de 2021.<\/div>\n<div><\/div>\n<div>\n<h3>Terceira fase<\/h3>\n<\/div>\n<div>As provas da terceira fase s\u00e3o escritas e s\u00e3o compostas por hist\u00f3ria do Brasil, pol\u00edtica internacional, geogradia, economia, direito, l\u00edngua espanhola e francesa.<\/div>\n<div><\/div>\n<div>As provas escritas ter\u00e3o dura\u00e7\u00e3o de 4 horas cada e ser\u00e3o aplicadas nas capitais onde houver candidatos aprovados na Segunda Fase, nas datas prov\u00e1veis de:<\/div>\n<div><\/div>\n<div>a) 27 de agosto de 2021: Prova de hist\u00f3ria do Brasil, iniciando-se \u00e0s 9 horas;<\/div>\n<div><\/div>\n<div>b) 27 de agosto de 2021: Prova de geografia, iniciando-se \u00e0s 15 horas;<\/div>\n<div><\/div>\n<div>c) 28 de agosto de 2021: Prova de pol\u00edtica internacional, iniciando-se \u00e0s 9 horas;<\/div>\n<div><\/div>\n<div>d) 28 de agosto de 2021: Prova de economia, iniciando-se \u00e0s 15 horas;<\/div>\n<div><\/div>\n<div>e) 29 de agosto de 2021: Prova de direito, iniciando-se \u00e0s 9 horas; e<\/div>\n<div><\/div>\n<div>f) 29 de agosto de 2021: Prova de l\u00edngua espanhola e l\u00edngua francesa, iniciando-se \u00e0s 15 horas. [&#8230;]<\/div>\n<div><\/div>\n<div>Os resultados provis\u00f3rios da Terceira Fase ser\u00e3o divulgados no site da banca, na data prov\u00e1vel de 14 de setembro de 2021.<\/div>\n<div><\/div>\n<div>O candidato, que desejar interpor recurso contra o resultado provis\u00f3rio nas provas da Terceira Fase, dispor\u00e1 do per\u00edodo compreendido entre as 8 horas de 15 de setembro de 2021 e as 23 horas e 59 minutos de 16 de setembro de 2021.<\/div>\n<div><\/div>\n<div>As respostas aos recursos contra o resultado provis\u00f3rio na Terceira Fase, o resultado final na Terceira Fase, a convoca\u00e7\u00e3o para a per\u00edcia m\u00e9dica dos candidatos, que se declararam com defici\u00eancia, e a convoca\u00e7\u00e3o para o procedimento de heteroidentifica\u00e7\u00e3o dos candidatos, que se autodeclararam negros, ser\u00e3o divulgados no site da banca, na data prov\u00e1vel de 29 de setembro de 2021, e publicados no Di\u00e1rio Oficial da Uni\u00e3o.<\/div>\n<h3>Per\u00edcia m\u00e9dica<\/h3>\n<div>A per\u00edcia m\u00e9dica ser\u00e1 realizada aos candidatos que se declararem com defici\u00eancia, na cidade de Bras\u00edlia\/DF, \u00e0s expensas do candidato, na data prov\u00e1vel de 4 de outubro de 2021.<\/div>\n<div>O candidato que desejar interpor recurso contra o resultado provis\u00f3rio na per\u00edcia m\u00e9dica, a ser divulgado no site da banca, na data prov\u00e1vel de 6 de outubro de 2021, dispor\u00e1 do per\u00edodo prov\u00e1vel compreendido entre as 8 horas de 7 de outubro de 2021 e as 23 horas e 59 minutos de 8 de outubro de 2021.<\/div>\n<div><\/div>\n<div>\n<h3>Procedimento de heteroidentifica\u00e7\u00e3o<\/h3>\n<p>Se aprovado na Terceira Fase, o candidato que tiver optado, no ato da inscri\u00e7\u00e3o, por concorrer \u00e0s vagas reservadas nos termos da lei n\u00ba 12.990\/2014, ainda que tenha obtido nota suficiente para aprova\u00e7\u00e3o na ampla concorr\u00eancia ou nas vagas destinadas a pessoas com defici\u00eancia, respeitados os empates na \u00faltima coloca\u00e7\u00e3o, dever\u00e1 comparecer perante comiss\u00e3o de heteroidentifica\u00e7\u00e3o, designada especificamente para este concurso pela Conselheira do quadro de pessoal do Minist\u00e9rio das Rela\u00e7\u00f5es Exteriores, no uso das atribui\u00e7\u00f5es que lhe foram conferidas por portaria de delega\u00e7\u00e3o de compet\u00eancia da Diretora-Geral do Instituto Rio Branco, na cidade de Bras\u00edlia\/DF, \u00e0s expensas do candidato, na data prov\u00e1vel de 4 de outubro de 2021.<\/p>\n<\/div>\n<div><\/div>\n<div>O resultado provis\u00f3rio do procedimento de heteroidentifica\u00e7\u00e3o, do qual constar\u00e3o os dados de identifica\u00e7\u00e3o do candidato, a conclus\u00e3o do parecer da comiss\u00e3o de heteroidentifica\u00e7\u00e3o e as condi\u00e7\u00f5es para exerc\u00edcio do direito de recurso pelos interessados, ser\u00e1 divulgado no endere\u00e7o eletr\u00f4nico http:\/\/www.iades.com.br, na data prov\u00e1vel de 6 de outubro de 2021.<\/div>\n<div><\/div>\n<div>O candidato, que desejar interpor recurso contra decis\u00e3o da comiss\u00e3o de heteroidentifica\u00e7\u00e3o, dispor\u00e1 do per\u00edodo prov\u00e1vel compreendido entre as 8 horas de 7 de outubro de 2021 e as 23 horas e 59 minutos de 8 de outubro de 2021 e dever\u00e1 seguir as instru\u00e7\u00f5es do item 12 do edital n\u00ba 1, de 29 de junho de 2020.<\/div>\n<div><\/div>\n<div>\n<h3>Resultado final<\/h3>\n<\/div>\n<div>O resultado final no concurso, condicionado \u00e0 realiza\u00e7\u00e3o dos procedimentos descritos nos itens 9 e 10 do edital n\u00ba 1, de 29 de junho de 2020, ser\u00e1 publicado no Di\u00e1rio Oficial da Uni\u00e3o e divulgado no endere\u00e7o eletr\u00f4nico <a href=\"http:\/\/www.iades.com.br\">http:\/\/www.iades.com.br<\/a>, na data prov\u00e1vel de 14 de outubro de 2021.<\/div>\n<div>\n<h3>O concurso<\/h3>\n<\/div>\n<\/div>\n<div>De acordo com o regulamento, s\u00e3o 25 vagas para a classe inical de terceiro-secret\u00e1rio, sendo 18 para ampla concorr\u00eancia, cinco para negros e duas para candidatops com defici\u00eancia. O concurso \u00e9 realizado pelo Instituto Rio Branco (IRBr), com a colabora\u00e7\u00e3o do Instituto Americano de Desenvolvimento (Iades).<\/div>\n<div><\/div>\n<div>A remunera\u00e7\u00e3o inicial do posto no Brasil \u00e9 de R$ 19.199,06 (valor bruto). Para concorrer \u00e9 necess\u00e1rio ser brasileiro nato; apresentar diploma, devidamente registrado, de conclus\u00e3o de curso de gradua\u00e7\u00e3o de n\u00edvel superior, emitido por institui\u00e7\u00e3o de ensino credenciada pelo Minist\u00e9rio da Educa\u00e7\u00e3o (MEC); ter idade m\u00ednima de 18 anos; entre outros requisitos.<\/div>\n<div><\/div>\n<div><\/div>\n<div><a href=\"https:\/\/www.iades.com.br\/inscricao\/ProcessoSeletivo.aspx?id=12007ee1\">Saiba tudo sobre o concurso aqui!<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>O Instituto Rio Branco divulgou novidades sobre os locais de provas da segunda fase do concurso para diplomatas. Os exames ser\u00e3o realizados no pr\u00f3ximo s\u00e1bado (10\/7) e domingo (11\/7).\u00a0 O documento, publicado no site da banca Iades, aponta que alguns candidatos far\u00e3o as provas nas depend\u00eancias de lojas ma\u00e7\u00f4nicas. O local foi escolhido para estudantes de Jo\u00e3o Pessoa, Recife e [&hellip;]<\/p>\n","protected":false},"author":41,"featured_media":12640,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[282],"tags":[],"class_list":["post-19600","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-concursos"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/19600","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/users\/41"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/comments?post=19600"}],"version-history":[{"count":2,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/19600\/revisions"}],"predecessor-version":[{"id":19605,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/19600\/revisions\/19605"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/media\/12640"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/media?parent=19600"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/categories?post=19600"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/tags?post=19600"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}