{"id":1915,"date":"2012-08-31T15:48:00","date_gmt":"2012-08-31T18:48:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/concursos_turbinam_gastos_do_governo_no_2u_trimestre\/"},"modified":"2012-08-31T15:48:00","modified_gmt":"2012-08-31T18:48:00","slug":"concursos_turbinam_gastos_do_governo_no_2u_trimestre","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/concursos_turbinam_gastos_do_governo_no_2u_trimestre\/","title":{"rendered":"Concursos turbinam gastos do governo no 2\u00ba trimestre"},"content":{"rendered":"<p>  <b> <\/p>\n<p><\/b><b>Victor Martins \u2013 Do Correio Braziliense<\/b>  &nbsp;  <strong>Rio de Janeiro &#8211;<\/strong> <b>Sem conseguir destravar investimentos p\u00fablicos e estimular os privados, o governo ampliou as despesas de custeio da m\u00e1quina p\u00fablica. Enquanto os investimentos do pa\u00eds encolheram 2,9% no primeiro semestre do ano, o gasto p\u00fablico subiu 3,2%.<\/b>  &nbsp;  Na avalia\u00e7\u00e3o de Rebeca Palis, gerente de Contas Nacionais do Instituto Brasileiro de Geografia e Estat\u00edstica (IBGE), \u00e9 &#8220;natural&#8221; a amplia\u00e7\u00e3o desses gastos no segundo ano dos governos<b>. &#8220;Primeiro ano de governo segura mais as contas. Depois, no segundo, come\u00e7am a abrir concursos e a convocar aprovados, \u00e9 natural um aumento de gastos&#8221;<\/b>, disse.  &nbsp;  &#8220;O fator elei\u00e7\u00f5es tamb\u00e9m ajuda nesse movimento&#8221;, emendou. Roberto Olinto, coordenador de Contas Nacionais do IBGE, ressalva, por\u00e9m, que nessa conta est\u00e3o somados n\u00e3o apenas as despesas do governo federal, mas tamb\u00e9m todas as esferas e n\u00edveis do poder p\u00fablico, incluindo Justi\u00e7a e Legislativo.     <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Victor Martins \u2013 Do Correio Braziliense &nbsp; Rio de Janeiro &#8211; Sem conseguir destravar investimentos p\u00fablicos e estimular os privados, o governo ampliou as despesas de custeio da m\u00e1quina p\u00fablica. Enquanto os investimentos do pa\u00eds encolheram 2,9% no primeiro semestre do ano, o gasto p\u00fablico subiu 3,2%. &nbsp; Na avalia\u00e7\u00e3o de Rebeca Palis, gerente de Contas Nacionais do Instituto Brasileiro [&hellip;]<\/p>\n","protected":false},"author":33,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1915","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/1915","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/comments?post=1915"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/1915\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/media?parent=1915"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/categories?post=1915"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/tags?post=1915"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}