{"id":1856,"date":"2011-11-11T12:19:00","date_gmt":"2011-11-11T14:19:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/tse_lancara_edital_para_cr_no_dia_14_de_novembro\/"},"modified":"2011-11-11T12:19:00","modified_gmt":"2011-11-11T14:19:00","slug":"tse_lancara_edital_para_cr_no_dia_14_de_novembro","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/tse_lancara_edital_para_cr_no_dia_14_de_novembro\/","title":{"rendered":"TSE lan\u00e7ar\u00e1 edital para CR no dia 14 de novembro"},"content":{"rendered":"<p>  <b><i> <\/p>\n<p><\/i><\/b><b><i>Larissa Domingues \u2013 Do CorreioWeb<\/i><\/b><b><i> <\/p>\n<p><\/i><\/b>  <b>Quem aguarda pelo concurso do Tribunal Superior Eleitoral (TSE) pode comemorar. De acordo com informa\u00e7\u00f5es do \u00f3rg\u00e3o, o edital de abertura que prev\u00ea forma\u00e7\u00e3o de cadastro reserva em cargos de n\u00edveis m\u00e9dio e superior deve ser publicado nesta segunda-feira (14\/11).<\/b> A sele\u00e7\u00e3o ser\u00e1 organizada pela Consulplan. As provas est\u00e3o marcadas para acontecer no m\u00eas de fevereiro do ano que vem.  <\/p>\n<p>  As chances de analista judici\u00e1rio ser\u00e3o nas \u00e1reas judici\u00e1ria, administrativa (contabilidade e pedagogia) e de apoio especializado (psicologia, an\u00e1lise de sistemas, arquivologia, biblioteconomia, estat\u00edstica, engenharia el\u00e9trica e mec\u00e2nica). J\u00e1 os postos de t\u00e9cnico judici\u00e1rio contemplar\u00e3o os campos administrativo e de apoio especializado (programa\u00e7\u00e3o de sistemas).     <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Larissa Domingues \u2013 Do CorreioWeb Quem aguarda pelo concurso do Tribunal Superior Eleitoral (TSE) pode comemorar. De acordo com informa\u00e7\u00f5es do \u00f3rg\u00e3o, o edital de abertura que prev\u00ea forma\u00e7\u00e3o de cadastro reserva em cargos de n\u00edveis m\u00e9dio e superior deve ser publicado nesta segunda-feira (14\/11). A sele\u00e7\u00e3o ser\u00e1 organizada pela Consulplan. As provas est\u00e3o marcadas para acontecer no m\u00eas de [&hellip;]<\/p>\n","protected":false},"author":33,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1856","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/1856","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/comments?post=1856"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/1856\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/media?parent=1856"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/categories?post=1856"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/tags?post=1856"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}