{"id":1839,"date":"2011-10-26T13:32:00","date_gmt":"2011-10-26T15:32:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/camara_aprova_criacao_de_quadro_de_apoio_na_aeronautica\/"},"modified":"2011-10-26T13:32:00","modified_gmt":"2011-10-26T15:32:00","slug":"camara_aprova_criacao_de_quadro_de_apoio_na_aeronautica","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/camara_aprova_criacao_de_quadro_de_apoio_na_aeronautica\/","title":{"rendered":"C\u00e2mara aprova cria\u00e7\u00e3o de quadro de apoio na Aeron\u00e1utica"},"content":{"rendered":"<p>  <b><i> <\/p>\n<p><\/i><\/b><b><i>Murilo Souza \u2013 Da Ag\u00eancia C\u00e2mara<\/i><\/b><b><i> <\/p>\n<p><\/i><\/b>  <b>A Comiss\u00e3o de Constitui\u00e7\u00e3o e Justi\u00e7a e de Cidadania aprovou nesta quarta-feira (26) o Projeto de Lei<\/b><b> <a href=\"http:\/\/www2.camara.gov.br\/agencia\/noticias\/ADMINISTRACAO-PUBLICA\/150334-PROJETO-CRIA-QUADRO-DE-OFICIAIS-DE-APOIO-DA-AERONAUTICA.html\" target=\"_blank\">7521<\/a>\/10, do Executivo, que cria o Quadro de Oficiais de Apoio no Corpo de Oficiais da Ativa do Comando da Aeron\u00e1utica. <\/b>Como a proposta j\u00e1 havia sido aprovada anteriormente pelas comiss\u00f5es tem\u00e1ticas por que passara, o texto aprovado na CCJ segue agora para an\u00e1lise pelo Senado.<b> <\/p>\n<p><\/b>  O novo quadro ser\u00e1 composto por profissionais de n\u00edvel superior que exercer\u00e3o fun\u00e7\u00f5es de apoio \u00e0s atividades-fim nas \u00e1reas de sa\u00fade, de ci\u00eancias exatas e humanas, de infraestrutura e de atendimento sanit\u00e1rio. <\/p>\n<p>  <b>Os novos militares ser\u00e3o admitidos por meio de concurso p\u00fablico espec\u00edfico e de aprova\u00e7\u00e3o em est\u00e1gio de adapta\u00e7\u00e3o. Os alunos do est\u00e1gio ser\u00e3o equiparados a primeiro-tenente.<\/b> Atualmente, estas fun\u00e7\u00f5es s\u00e3o exercidas por servidores tempor\u00e1rios que fazem parte do Quadro Complementar de Oficiais da Aeron\u00e1utica. <\/p>\n<p>  O relator na comiss\u00e3o, deputado Arthur Oliveira Maia (PMDB-BA), apresentou parecer pela aprova\u00e7\u00e3o. \u201cA proposi\u00e7\u00e3o na~o colide com princi\u00b4pios juri\u00b4dicos do nosso ordenamento, motivo pelo qual entendemos que satisfaz aos aspectos de juridicidade e legalidade\u201d, afirmou. Maia tamb\u00e9m votou favoravelmente \u00e0s emendas apresentadas. <\/p>\n<p>  O relator acatou sugest\u00e3o do deputado Onyx Lorenzoni (DEM-RS) retirando do texto a previs\u00e3o de limite de idade para ingresso na carreira. O texto original determinava que o aluno no est\u00e1gio de adapta\u00e7\u00e3o deveria ter entre 18 e 32 anos em 25 de dezembro do ano da matr\u00edcula. Para Lorenzoni, a limita\u00e7\u00e3o de idade fere a Constitui\u00e7\u00e3o.  <\/p>\n<p> Com a altera\u00e7\u00e3o, o concurso p\u00fablico para ingresso na carreira poder\u00e1 incluir teste de aptid\u00e3o motora, prova oral ou prova pr\u00e1tica e limite de idade, desde que compat\u00edveis e necess\u00e1rios \u00e0 especialidade a que concorre o candidato. <\/p>\n<p>  <strong>Mudan\u00e7as<\/strong> <\/p>\n<p> Na Comiss\u00e3o de Trabalho, tamb\u00e9m foi aprovada emenda que garante a todos os militares que n\u00e3o forem aprovados no est\u00e1gio de adapta\u00e7\u00e3o o retorno \u00e0 situa\u00e7\u00e3o funcional anterior. <\/p>\n<p>  O deputado Arthur Maia tamb\u00e9m votou a favor de emenda apresentada na Comiss\u00e3o de Finan\u00e7as e Tributa\u00e7\u00e3o que limita a composi\u00e7\u00e3o do novo quadro \u00e0 correspondente redu\u00e7\u00e3o do Quadro Complementar de Oficiais da Aerona\u00b4utica (QCOA). Trata-se de um quadro de oficiais tempor\u00e1rios e com a gradual redu\u00e7\u00e3o das componentes do quadro Feminino de Oficiais.  <\/p>\n<p>  \u00cdntegra da proposta: <a href=\"http:\/\/www.camara.gov.br\/internet\/sileg\/Prop_Detalhe.asp?id=474924\">PL-7221\/2010<\/a>    <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Murilo Souza \u2013 Da Ag\u00eancia C\u00e2mara A Comiss\u00e3o de Constitui\u00e7\u00e3o e Justi\u00e7a e de Cidadania aprovou nesta quarta-feira (26) o Projeto de Lei 7521\/10, do Executivo, que cria o Quadro de Oficiais de Apoio no Corpo de Oficiais da Ativa do Comando da Aeron\u00e1utica. Como a proposta j\u00e1 havia sido aprovada anteriormente pelas comiss\u00f5es tem\u00e1ticas por que passara, o texto [&hellip;]<\/p>\n","protected":false},"author":33,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1839","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/1839","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/comments?post=1839"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/1839\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/media?parent=1839"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/categories?post=1839"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/tags?post=1839"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}