{"id":18100,"date":"2021-04-23T18:45:28","date_gmt":"2021-04-23T21:45:28","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/?p=18100"},"modified":"2021-04-23T18:45:28","modified_gmt":"2021-04-23T21:45:28","slug":"governo-federal-cancela-censo-2021-por-falta-de-recursos","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/governo-federal-cancela-censo-2021-por-falta-de-recursos\/","title":{"rendered":"Governo federal cancela Censo 2021 por falta de recursos"},"content":{"rendered":"<p><em>Estado de Minas-\u00a0<\/em>O secret\u00e1rio especial de Fazenda do Minist\u00e9rio da Economia, Waldery Rodrigues confirmou nesta sexta-feira (23\/4) que n\u00e3o h\u00e1 previs\u00e3o or\u00e7ament\u00e1ria para o Censo 2021 e o levantamento ficar\u00e1 para 2023.<\/p>\n<p>&#8220;Portanto, ele n\u00e3o se realizar\u00e1 em 2021. As consequ\u00eancias para um novo censo ser\u00e3o comunicadas ao longo deste ano&#8221;, limitou-se a responder Waldery.<\/p>\n<h3>Sindicato fez alerta<\/h3>\n<p>Ap\u00f3s o governo federal ter reduzido ainda mais a verba destinada \u00e0 realiza\u00e7\u00e3o do Censo Demogr\u00e1fico deste ano pelo Instituto Brasileiro de Geografia e Estat\u00edstica (IBGE), o sindicato de servidores do \u00f3rg\u00e3o alertou na manh\u00e3 desta sexta-feira, que os preparativos estavam amea\u00e7ados, o que poderia inviabilizar a coleta em campo em 2022, ou seja, o levantamento ficaria apenas para 2023.<\/p>\n<p>Dos R$ 2 bilh\u00f5es previstos, apenas R$ 71 milh\u00f5es foram aprovados pelo Congresso Nacional no m\u00eas passado. No entanto, o or\u00e7amento sancionado e publicado no Di\u00e1rio Oficial da Uni\u00e3o desta sexta-feira traz um veto do presidente Jair Bolsonaro que reduz esse valor para apenas R$ 53 milh\u00f5es, o que inviabiliza at\u00e9 os preparativos para o levantamento ir a campo em 2022, afirma o sindicato nacional dos servidores do IBGE, o Assibge.<\/p>\n<p>O texto aprovado no congresso previa R$ 53 milh\u00f5es de custeio e outros R$ 17,75 milh\u00f5es de investimento, que acabaram vetados pelo presidente, ressalta o sindicato.<\/p>\n<p>&#8220;A gente avalia que precisaria de pelo menos R$ 239 milh\u00f5es para manter o censo vivo e que ele pudesse ser executado ao menos em 2022. Desses R$ 53 milh\u00f5es aprovados, calculamos que R$ 20 milh\u00f5es j\u00e1 foram gastos, ent\u00e3o realmente o que nos preocupa n\u00e3o \u00e9 o censo n\u00e3o realizado em 2021, mas que ele n\u00e3o ocorra em 2022. Se os recursos necess\u00e1rios para os preparativos s\u00f3 vierem na LOA (Lei Or\u00e7ament\u00e1ria Anual) de 2022, significa que ele s\u00f3 ser\u00e1 realizado em 2023&#8221;, alertou Dalea Antunes, coordenadora do N\u00facleo Chile do Assibge.<\/p>\n<p>A verba \u00e9 necess\u00e1ria para a manuten\u00e7\u00e3o dos contratos de trabalhadores tempor\u00e1rios que j\u00e1 preparam o levantamento censit\u00e1rio e de servi\u00e7os e licita\u00e7\u00f5es em curso, aponta o sindicato.<\/p>\n<p>Realizado a cada 10 anos, o Censo Demogr\u00e1fico deveria ter ido a campo em 2020, mas foi adiado para 2021 em fun\u00e7\u00e3o da pandemia do novo coronav\u00edrus. O IBGE ter\u00e1 que cancelar pelo segundo ano consecutivo o concurso p\u00fablico aberto para preencher as mais de 200 mil vagas tempor\u00e1rias de recenseados e agentes censit\u00e1rios que trabalhariam no levantamento. As provas presenciais que seriam realizadas este m\u00eas j\u00e1 estavam canceladas, sem nova previs\u00e3o de data.<\/p>\n<p>O corte no or\u00e7amento do censo gerou uma crise na dire\u00e7\u00e3o do IBGE. No \u00faltimo 26 de mar\u00e7o, dia seguinte \u00e0 aprova\u00e7\u00e3o pelo congresso da redu\u00e7\u00e3o no or\u00e7amento do levantamento censit\u00e1rio, a presidente Susana Cordeiro Guerra informou ter pedido exonera\u00e7\u00e3o do cargo. Ela permaneceu \u00e0 frente do \u00f3rg\u00e3o por mais duas semanas, at\u00e9 9 de abril, quando foi substitu\u00edda interinamente pela ent\u00e3o diretora executiva do \u00f3rg\u00e3o, Marise Ferreira, servidora de carreira do IBGE h\u00e1 37 anos.<\/p>\n<p>O Minist\u00e9rio da Economia, a quem o IBGE \u00e9 subordinado, n\u00e3o emitiu qualquer nota at\u00e9 esta sexta-feira comentando nem o corte no or\u00e7amento do Censo Demogr\u00e1fico nem a mudan\u00e7a na dire\u00e7\u00e3o do \u00f3rg\u00e3o. H\u00e1 pouco mais de uma semana, no dia 14, o instituto anunciou que o atual diretor de Pesquisas, Eduardo Rios Neto, foi indicado pelo Minist\u00e9rio da Economia para assumir a presid\u00eancia, mas sua nomea\u00e7\u00e3o ainda n\u00e3o foi publicada no Di\u00e1rio Oficial.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estado de Minas-\u00a0O secret\u00e1rio especial de Fazenda do Minist\u00e9rio da Economia, Waldery Rodrigues confirmou nesta sexta-feira (23\/4) que n\u00e3o h\u00e1 previs\u00e3o or\u00e7ament\u00e1ria para o Censo 2021 e o levantamento ficar\u00e1 para 2023. &#8220;Portanto, ele n\u00e3o se realizar\u00e1 em 2021. As consequ\u00eancias para um novo censo ser\u00e3o comunicadas ao longo deste ano&#8221;, limitou-se a responder Waldery. Sindicato fez alerta Ap\u00f3s o [&hellip;]<\/p>\n","protected":false},"author":32,"featured_media":9141,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,109],"tags":[1855,2053,2747,1854,146,2746,2748],"class_list":["post-18100","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria","category-suspensao","tag-censo-2021","tag-censo-demografico","tag-censos-suspenso","tag-concurso-ibge","tag-ibge","tag-selecao-ibge","tag-suspensao-ibge"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/18100","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/comments?post=18100"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/18100\/revisions"}],"predecessor-version":[{"id":18101,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/18100\/revisions\/18101"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/media\/9141"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/media?parent=18100"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/categories?post=18100"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/tags?post=18100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}