{"id":1789,"date":"2011-09-20T14:02:00","date_gmt":"2011-09-20T17:02:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/oab_repudia_proposta_que_permite_cartorio_sem_concurso\/"},"modified":"2011-09-20T14:02:00","modified_gmt":"2011-09-20T17:02:00","slug":"oab_repudia_proposta_que_permite_cartorio_sem_concurso","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/oab_repudia_proposta_que_permite_cartorio_sem_concurso\/","title":{"rendered":"OAB repudia proposta que permite cart\u00f3rio sem concurso"},"content":{"rendered":"<p>  <b> <\/p>\n<p><\/b><b>Da Ag\u00eancia Brasil<\/b><b> <\/p>\n<p>&nbsp;  <\/p>\n<p><\/b><b> <\/p>\n<p><\/b>  <b>Bras\u00edlia &#8211;<\/b> <b>O Conselho Federal da Ordem dos Advogados do Brasil (OAB) decidiu ontem (19), em sess\u00e3o plen\u00e1ria, posicionar-se contra a Proposta de Emenda \u00e0 Constitui\u00e7\u00e3o (PEC) n\u00ba 471\/2005, a chamada PEC do &#8220;Trem da Alegria&#8221; dos cart\u00f3rios. A proposta prev\u00ea que os substitutos de serventias vagas em exerc\u00edcio interino por mais de cinco anos sejam investidos no cargo, sem concurso p\u00fablico.<\/b><b> <\/p>\n<p><\/b>  A PEC 471 pretende alterar o Artigo 236 da Constitui\u00e7\u00e3o, que determina que os servi\u00e7os notariais e de registros sejam exercidos em car\u00e1ter privado, por delega\u00e7\u00e3o do Poder P\u00fablico, ap\u00f3s aprova\u00e7\u00e3o em concurso de provas e t\u00edtulos. <\/p>\n<p>  Os membros do conselho da OAB entenderam, por unanimidade, que a PEC atenta contra princ\u00edpios constitucionais e a moralidade p\u00fablica. Uma nota de rep\u00fadio ser\u00e1 enviada ao Congresso Nacional.    <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Da Ag\u00eancia Brasil &nbsp; Bras\u00edlia &#8211; O Conselho Federal da Ordem dos Advogados do Brasil (OAB) decidiu ontem (19), em sess\u00e3o plen\u00e1ria, posicionar-se contra a Proposta de Emenda \u00e0 Constitui\u00e7\u00e3o (PEC) n\u00ba 471\/2005, a chamada PEC do &#8220;Trem da Alegria&#8221; dos cart\u00f3rios. A proposta prev\u00ea que os substitutos de serventias vagas em exerc\u00edcio interino por mais de cinco anos sejam [&hellip;]<\/p>\n","protected":false},"author":33,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1789","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/1789","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/comments?post=1789"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/1789\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/media?parent=1789"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/categories?post=1789"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/tags?post=1789"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}