{"id":17841,"date":"2021-04-07T08:41:48","date_gmt":"2021-04-07T11:41:48","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/?p=17841"},"modified":"2021-04-07T08:41:48","modified_gmt":"2021-04-07T11:41:48","slug":"governo-do-amapa-sanciona-lei-que-cria-carreira-de-policial-penal","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/governo-do-amapa-sanciona-lei-que-cria-carreira-de-policial-penal\/","title":{"rendered":"Governo do Amap\u00e1 sanciona lei que cria carreira de policial penal"},"content":{"rendered":"<p><em>Karolini Bandeira*- <\/em>O\u00a0Governo do Amap\u00e1 sancionou, nesta segunda-feira (05\/4), a Lei N\u00ba 2.542, de 5 de abril de 2021, que\u00a0cria a Pol\u00edcia Penal no estado. O cargo de policial penal dever\u00e1 substituir a atual fun\u00e7\u00e3o de agente penitenci\u00e1rio. A lei foi publicada no <a href=\"https:\/\/diario.portal.ap.gov.br\/pesquisa_avancada.php?view=181def7440d1604c0a0528b33792420d\">Di\u00e1rio Oficial do Estado<\/a>. De acordo com a decis\u00e3o, a carreira tem como pr\u00e9-requisito n\u00edvel superior e \u00e9 dividida em quatro classes.<\/p>\n<h3>Atribui\u00e7\u00f5es e remunera\u00e7\u00e3o<\/h3>\n<p>Cabe ao policial penal, segundo a lei,\u00a0fiscalizar a entrada e sa\u00edda de pessoas e ve\u00edculos nos pr\u00e9dios e estabelecimentos penais do sistema penitenci\u00e1rio estadual e \u00e1reas afetas, incluindo execu\u00e7\u00e3o de servi\u00e7os de revista;\u00a0controlar o fluxo de pessoas e ve\u00edculos em ambientes\u00a0onde ocorram a\u00e7\u00f5es da pol\u00edcia penal, no \u00e2mbito de suas atribui\u00e7\u00f5es, preferencialmente, em coopera\u00e7\u00e3o com os respons\u00e1veis pela seguran\u00e7a do local;\u00a0realizar o policiamento, incluindo a atividade de revista e prote\u00e7\u00e3o, do per\u00edmetro de todas as depend\u00eancias onde ocorram deslocamento de pessoas privadas de liberdade, bem como \u00e1reas de interesse da administra\u00e7\u00e3o<br \/>\npenitenci\u00e1ria; realizar escolta e recambiamento, inclu\u00eddas as interestaduais e internacionais, de pessoas privadas de liberdade e outras solicitadas por autoridade competente;\u00a0realizar busca e revista pessoal, nos termos da lei;\u00a0cuidar da disciplina e seguran\u00e7a dos presos e apenados;\u00a0efetuar a confer\u00eancia peri\u00f3dica da popula\u00e7\u00e3o carcer\u00e1ria;\u00a0realizar a identifica\u00e7\u00e3o cadastral e o controle legal dos presos e apenados;\u00a0fazer rondas peri\u00f3dicas;\u00a0realizar a recaptura de evadidos e foragidos;\u00a0conduzir viaturas, embarca\u00e7\u00f5es e aeronaves conforme habilita\u00e7\u00e3o espec\u00edfica; entre outros.<\/p>\n<p>A lei tamb\u00e9m ressalta que todas as atribui\u00e7\u00f5es s\u00e3o de natureza estritamente policial e devem ser realizadas nos estabelecimentos penais estaduais e durante a escolta de presos.<\/p>\n<p>A remunera\u00e7\u00e3o inicial do profissional da \u00e1rea \u00e9 de\u00a0R$ 3.318,64, para jornada de trabalho de 40 horas semanais. Os policias penais tamb\u00e9m poder\u00e3o ser submetidos a escala de plant\u00e3o de 24 horas consecutivas de trabalho.<\/p>\n<h3>Requisitos<\/h3>\n<ul>\n<li>Ser brasileiro;<\/li>\n<li>Possuir ensino superior;<\/li>\n<li>Estar no gozo dos direitos pol\u00edticos;<\/li>\n<li>A quita\u00e7\u00e3o com as obriga\u00e7\u00f5es militares e eleitorais;<\/li>\n<li>A idade m\u00ednima de dezoito anos;<\/li>\n<li>Gozar de boa sa\u00fade f\u00edsica e mental, comprovada em<br \/>\ninspe\u00e7\u00e3o m\u00e9dica oficial;<\/li>\n<li>Ter conduta social irrepreens\u00edvel, comprovada<br \/>\nidoneidade moral e n\u00e3o possuir antecedentes criminais;<\/li>\n<li>Ser previamente aprovado em concurso p\u00fablico de<br \/>\nprovas ou de provas e t\u00edtulos;<\/li>\n<li>Ser previamente aprovado em curso de forma\u00e7\u00e3o<br \/>\nt\u00e9cnico- policial;<\/li>\n<li>Possuir Carteira Nacional de Habilita\u00e7\u00e3o, no m\u00ednimo<br \/>\nB.<\/li>\n<\/ul>\n<p>Para ingressar na carreira, ser\u00e1 necess\u00e1ria aprova\u00e7\u00e3o em concurso p\u00fablico\u00a0com prova escrita, prova de t\u00edtulos, exame de aptid\u00e3o f\u00edsica, exame documental e m\u00e9dico, exame psicol\u00f3gico e investiga\u00e7\u00e3o social.<\/p>\n<h3>\u00daltimo concurso<\/h3>\n<p>O <a href=\"https:\/\/www.concursosfcc.com.br\/concursos\/iapen118\/index.html\">\u00faltimo concurso p\u00fablico<\/a> para a carreira de agente penitenci\u00e1rio foi realizado em 2018. O edital contou com 100 vagas de n\u00edvel m\u00e9dio, sendo 80 para o sexo masculino e 20 para o feminino. Organizado pela Funda\u00e7\u00e3o Carlos Chagas (FCC), os inscritos passaram por prova objetiva com\u00a060 quest\u00f5es distribu\u00eddas entre conhecimentos gerais (portugu\u00eas, racioc\u00ednio l\u00f3gico matem\u00e1tico, hist\u00f3ria e geografia do estado) e conhecimentos espec\u00edficos; teste de aptid\u00e3o f\u00edsica; exames documentais, psicol\u00f3gicos e de sa\u00fade; investiga\u00e7\u00e3o social; e, por fim, curso de forma\u00e7\u00e3o inicial.<\/p>\n<p><em>*Estagi\u00e1ria sob a supervis\u00e3o de Mariana Niederauer<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Karolini Bandeira*- O\u00a0Governo do Amap\u00e1 sancionou, nesta segunda-feira (05\/4), a Lei N\u00ba 2.542, de 5 de abril de 2021, que\u00a0cria a Pol\u00edcia Penal no estado. O cargo de policial penal dever\u00e1 substituir a atual fun\u00e7\u00e3o de agente penitenci\u00e1rio. A lei foi publicada no Di\u00e1rio Oficial do Estado. De acordo com a decis\u00e3o, a carreira tem como pr\u00e9-requisito n\u00edvel superior e [&hellip;]<\/p>\n","protected":false},"author":32,"featured_media":14100,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[532,282,134],"tags":[2676,496,1000,2677],"class_list":["post-17841","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-carreira-policial","category-concursos","category-seguranca","tag-agepen-amapa","tag-amapa","tag-policia-penal","tag-policia-penal-amapa"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/17841","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/comments?post=17841"}],"version-history":[{"count":2,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/17841\/revisions"}],"predecessor-version":[{"id":17846,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/17841\/revisions\/17846"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/media\/14100"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/media?parent=17841"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/categories?post=17841"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/tags?post=17841"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}