{"id":17654,"date":"2021-03-24T08:13:07","date_gmt":"2021-03-24T11:13:07","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/?p=17654"},"modified":"2021-03-24T08:13:07","modified_gmt":"2021-03-24T11:13:07","slug":"concursos-fiscais-saiba-quais-secretarias-devem-abrir-selecao-em-2021","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/concursos-fiscais-saiba-quais-secretarias-devem-abrir-selecao-em-2021\/","title":{"rendered":"Concursos fiscais: saiba quais secretarias devem abrir sele\u00e7\u00e3o em 2021"},"content":{"rendered":"<p><em>Karolini Bandeira*-<\/em> 2021 promete n\u00e3o passar em branco para quem pretende investir na carreira de auditor fiscal. Nestes primeiros tr\u00eas meses do ano, cinco Secretarias da Fazenda j\u00e1 confirmaram a realiza\u00e7\u00e3o de concursos p\u00fablicos \u2014 alguns, inclusive, com lan\u00e7amento previsto para o primeiro semestre. As chances s\u00e3o para Alagoas, Roraima, Par\u00e1, Esp\u00edrito Santo e Cear\u00e1. Saiba mais sobre cada previs\u00e3o:<\/p>\n<h3>Secretaria\u00a0da Fazenda do Estado de Alagoas (Sefaz\/AL)<\/h3>\n<p>Conforme autorizado, o concurso da Sefaz\/AL contar\u00e1 com 35 vagas! A autoriza\u00e7\u00e3o foi divulgada no Di\u00e1rio Oficial de Alagoas e, de acordo com o governador Renan Filho, ser\u00e3o 25 vagas para auditores fiscais e 10 vagas para auditor de finan\u00e7as e arrecada\u00e7\u00e3o. A\u00a0Secretaria j\u00e1 anunciou, inclusive, a escolha da banca organizadora: a escolhida foi o<strong><a href=\"https:\/\/www.cebraspe.org.br\/\">\u00a0Cebraspe<\/a><\/strong>! A informa\u00e7\u00e3o foi\u00a0<strong><a href=\"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/pge-emite-parecer-favoravel-a-realizacao-de-novo-concurso-para-a-sefaz-de-alagoas\/\">divulgada pelo secret\u00e1rio da fazenda<\/a><\/strong>, George Santoro, atrav\u00e9s das redes sociais. O secret\u00e1rio esclareceu tamb\u00e9m que os auditores ser\u00e3o lotados prioritariamente na capital do Estado e o edital ser\u00e1 o mesmo do\u00a0<strong><a href=\"http:\/\/concursos.correioweb.com.br\/app\/noticias\/2019\/11\/08\/noticiasinterna,40359\/sefaz-al-lanca-concurso-de-auditor-com-85-vagas-e-salarios-ate-r-9-4.shtml\">\u00faltimo concurso\u00a0<\/a><\/strong>\u00a0\u2014 sem nenhuma regra alterada. As mat\u00e9rias e conte\u00fados cobrados tamb\u00e9m ser\u00e3o as mesmas, apenas com algumas altera\u00e7\u00f5es pontuais de legisla\u00e7\u00e3o atualizada.<\/p>\n<p>De acordo com a pr\u00f3pria Secretaria, a expectativa \u00e9 de que os auditores sejam nomeados at\u00e9 dezembro deste ano.<\/p>\n<h3>Secretaria de Fazenda do Estado de Roraima (Sefaz\/RR)<\/h3>\n<p>O edital de abertura do pr\u00f3ximo concurso p\u00fablico da Sefaz\/RR tem publica\u00e7\u00e3o projetada para mar\u00e7o! A previs\u00e3o foi informada pela assessoria, que afirmou que \u201cest\u00e1 mantida a previs\u00e3o para o primeiro trimestre de 2021\u201d. O concurso ofertar\u00e1 30 vagas para o cargo de auditor fiscal, de n\u00edvel superior, sendo 20 imediatas e 10 para forma\u00e7\u00e3o de cadastro reserva. A comiss\u00e3o organizadora j\u00e1 foi oficializada.<\/p>\n<p>O \u00faltimo concurso contou com 30 vagas para a fun\u00e7\u00e3o e ofertou sal\u00e1rio inicial no valor de\u00a0R$ 5.484,09. Os candidatos tiveram que passar por prova objetiva com 60 quest\u00f5es distribu\u00eddas entre portugu\u00eas, conhecimentos gerais e espec\u00edficos. A segunda fase do concurso foi composta por curso de forma\u00e7\u00e3o profissional.\u00a0<strong><a href=\"https:\/\/www.cetapnet.com.br\/informacoes\/94\/\">Veja o edital!\u00a0<\/a><\/strong><\/p>\n<h3>Secretaria de Fazenda do Estado do Cear\u00e1 (Sefaz\/CE)<\/h3>\n<p>Segundo informa\u00e7\u00f5es publicadas nas redes sociais da secret\u00e1ria de\u00a0Fazenda do Estado do Cear\u00e1,\u00a0Fernanda Pacobahyba, o pr\u00f3ximo edital de abertura do concurso Sefaz\/CE poder\u00e1 ser publicado at\u00e9 31 de mar\u00e7o!\u00a0\u201cEstamos encaminhando o edital da Sefaz, j\u00e1 est\u00e1 sendo gestado. O prazo que me deram l\u00e1 na Sefaz para a gente terminar e encaminhar para publica\u00e7\u00e3o \u00e9 dia 31 de mar\u00e7o\u201d, informou a secret\u00e1ria.<\/p>\n<p>Est\u00e3o previstas 100 vagas para o cargo de auditor fiscal, que pode ter como remunera\u00e7\u00e3o inicial at\u00e9\u00a0R$16.045,30. As vagas ser\u00e3o imediatas e os aprovados dever\u00e3o atuar em carga hor\u00e1ria semanal de 40 horas. No \u00faltimo concurso, realizado em 2006, os candidatos foram avaliados por meio de prova objetiva com 135 perguntas distribu\u00eddas entre conhecimentos gerais (portugu\u00eas, matem\u00e1tica, inform\u00e1tica e \u00e9tica), espec\u00edficos (\u00e1reas do direito e contabilidade geral) e especializados (legisla\u00e7\u00e3o tribut\u00e1ria e auditoria e per\u00edcia). <strong><a href=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2017\/02\/10144510\/Edital-Sefaz-CE-2006.pdf\">Veja!<\/a><\/strong><\/p>\n<h3>Secretaria de Fazenda do Estado do Esp\u00edrito Santo (Sefaz\/ES)<\/h3>\n<p>O pr\u00f3ximo concurso p\u00fablico da Sefaz\/ES est\u00e1 prvisto na Lei Or\u00e7ament\u00e1ria Anual (LOA) de 2021 do Estado. O concurso ainda n\u00e3o tem data para ser publicado e segue em fase de contrata\u00e7\u00e3o de banca organizadora. Em dezembro de 2020, o presidente da comiss\u00e3o organizadora do certame,\u00a0Leandro Kuster, indicou que o edital poderia sair ainda no primeiro semestre do ano.\u00a0&#8220;Pelo nosso cronograma, a prova deve ser realizada ainda no primeiro semestre de 2021. Ent\u00e3o, assim que sair o edital, provavelmente de dois a tr\u00eas meses ser\u00e1 a realiza\u00e7\u00e3o da prova&#8221;, informou Kuster. O sal\u00e1rio inicial para o cargo na Secretaria \u00e9 de\u00a0R$12.492.<\/p>\n<h3>Secretaria de Fazenda do Estado do Par\u00e1 (Sefaz\/PA)<\/h3>\n<p>Em janeiro, o Governo do Par\u00e1 se comprometeu a realizar 19 concursos ainda este ano. Entre eles, um certame para a Sefaz\/PA. O \u00f3rg\u00e3o ainda est\u00e1 escolhendo a banca respons\u00e1vel pela sele\u00e7\u00e3o, que poder\u00e1 ofertar 110 vagas para fiscal\u00a0de receitas estaduais e\u00a0auditor fiscal de receitas estaduais. O sal\u00e1rio inicial das fun\u00e7\u00f5es varia de\u00a0R$11.910,51 a\u00a0R$15.076,58.\u00a0 \u201cTrabalhamos sempre em busca de mais excel\u00eancia nos servi\u00e7os p\u00fablicos oferecidos \u00e0 nossa popula\u00e7\u00e3o, al\u00e9m de incentivarmos o ingresso de novos servidores, por meio de concurso p\u00fablico, o que possibilita mais desenvolvimento e notoriedade ao nosso Estado\u201d, afirmou a secret\u00e1ria de Estado de Planejamento e Administra\u00e7\u00e3o, Hana Ghassan.<\/p>\n<p>&nbsp;<\/p>\n<h3>E para 2022?<\/h3>\n<p>N\u00e3o pense que os concursos previstos para fiscais s\u00e3o apenas para 2021. A\u00a0Secretaria da Fazenda do Paran\u00e1 (Sefaz\/PR) dever\u00e1 ter edital publicado em 2022. A previs\u00e3o foi confirmada pelo secret\u00e1rio da Fazenda Rene\u0302 Garcia Junior, em resposta a internautas nas redes sociais da Secretaria. Para trabalhar como auditor fiscal e agente tribut\u00e1rio, \u00e9 necess\u00e1rio possuir ensino superior completo em direito. Os sal\u00e1rios da carreiras variam e podem ultrapassar R$ 11.000.<\/p>\n<p>A Sefaz\/PR tem planos de abrir um novo concurso p\u00fablico desde 2019. No ano, uma\u00a0<a href=\"http:\/\/concursos.correioweb.com.br\/app\/noticias\/2019\/08\/15\/noticiasinterna,40038\/sefaz-pr-vai-abrir-novo-concurso-e-ja-define-comissao-organizadora.shtml\">comiss\u00e3o organizadora foi formada<\/a>\u00a0para dar in\u00edcio aos estudos do certame. De acordo com a assessoria do \u00f3rg\u00e3o, a Secretaria projetava abrir a sele\u00e7\u00e3o em 2020. O planejamento foi adiado devido \u00e0 pandemia de covid-19.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><em>*Estagi\u00e1ria sob a supervis\u00e3o de Mariana Niederauer<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Karolini Bandeira*- 2021 promete n\u00e3o passar em branco para quem pretende investir na carreira de auditor fiscal. Nestes primeiros tr\u00eas meses do ano, cinco Secretarias da Fazenda j\u00e1 confirmaram a realiza\u00e7\u00e3o de concursos p\u00fablicos \u2014 alguns, inclusive, com lan\u00e7amento previsto para o primeiro semestre. As chances s\u00e3o para Alagoas, Roraima, Par\u00e1, Esp\u00edrito Santo e Cear\u00e1. Saiba mais sobre cada previs\u00e3o: [&hellip;]<\/p>\n","protected":false},"author":32,"featured_media":12341,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[153,896,282,4],"tags":[40,398,785,219,2638,2636,111,142,954,461,2637],"class_list":["post-17654","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-autorizacao","category-carreira-fiscal","category-concursos","category-concursos-publicos","tag-espirito-santo","tag-alagoas","tag-auditor-fiscal","tag-ceara","tag-concursos-sefaz","tag-fiscal","tag-para","tag-parana","tag-roraima","tag-sefaz","tag-sefaz-2021"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/17654","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/comments?post=17654"}],"version-history":[{"count":2,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/17654\/revisions"}],"predecessor-version":[{"id":17667,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/17654\/revisions\/17667"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/media\/12341"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/media?parent=17654"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/categories?post=17654"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/tags?post=17654"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}