{"id":1754,"date":"2011-08-30T16:31:00","date_gmt":"2011-08-30T19:31:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/camara_analisa_proposta_para_criar_96_vagas_no_trt-3\/"},"modified":"2011-08-30T16:31:00","modified_gmt":"2011-08-30T19:31:00","slug":"camara_analisa_proposta_para_criar_96_vagas_no_trt-3","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/camara_analisa_proposta_para_criar_96_vagas_no_trt-3\/","title":{"rendered":"C\u00e2mara analisa proposta para criar 96 vagas no TRT-3"},"content":{"rendered":"<p>  <b>&nbsp;<\/b>  <b><i>Do CorreioWeb<\/i><\/b>  <b>&nbsp;<\/b>  <b>A C\u00e2mara dos Deputados atualmente estuda projeto de lei (1805\/11), do Tribunal Superior do Trabalho (TST), que visa criar 96 novos cargos na \u00e1rea de Tecnologia da Informa\u00e7\u00e3o (TI) para o Tribunal Regional do Trabalho da 3\u00aa Regi\u00e3o, em Belo Horizonte\/MG.<\/b> Do total de chances, 60 ser\u00e3o para o cargo de analista e 36 para o de t\u00e9cnico judici\u00e1rio.  &nbsp;  Segundo a ministra do TST, Maria Cristina Peduzzi, que assinou a proposta, o concurso poder\u00e1 adaptar o quadro de pessoal do TRT a uma portaria do Conselho Nacional de Justi\u00e7a (CNJ). A norma garante que fun\u00e7\u00f5es gerenciais e estrat\u00e9gicas de TI sejam executadas preferencialmente por servidores do quadro permanente.  &nbsp;  De acordo com a magistrada, o TRT da 3\u00aa Regi\u00e3o tem 3.841 usu\u00e1rios internos de computa\u00e7\u00e3o. A partir da resolu\u00e7\u00e3o do CNJ, pelo menos 3% devem ser profissionais de TI. O projeto ser\u00e1 analisado pelas comiss\u00f5es de Trabalho, de Administra\u00e7\u00e3o e Servi\u00e7o P\u00fablico; de Finan\u00e7as e Tributa\u00e7\u00e3o e de Constitui\u00e7\u00e3o e Justi\u00e7a e de Cidadania.    <\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Do CorreioWeb &nbsp; A C\u00e2mara dos Deputados atualmente estuda projeto de lei (1805\/11), do Tribunal Superior do Trabalho (TST), que visa criar 96 novos cargos na \u00e1rea de Tecnologia da Informa\u00e7\u00e3o (TI) para o Tribunal Regional do Trabalho da 3\u00aa Regi\u00e3o, em Belo Horizonte\/MG. Do total de chances, 60 ser\u00e3o para o cargo de analista e 36 para o [&hellip;]<\/p>\n","protected":false},"author":33,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1754","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/1754","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/comments?post=1754"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/1754\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/media?parent=1754"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/categories?post=1754"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/tags?post=1754"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}