{"id":1734,"date":"2011-08-17T16:06:00","date_gmt":"2011-08-17T19:06:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/governo_autoriza_o_ingresso_de_mais_92_gestores\/"},"modified":"2011-08-17T16:06:00","modified_gmt":"2011-08-17T19:06:00","slug":"governo_autoriza_o_ingresso_de_mais_92_gestores","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/governo_autoriza_o_ingresso_de_mais_92_gestores\/","title":{"rendered":"Governo autoriza o ingresso de mais 92 gestores"},"content":{"rendered":"<p>  &nbsp;  <b><i>Do CorreioWeb<\/i><\/b>  &nbsp;  A presidenta Dilma Roussef autorizou nesta semana o ingresso de mais 92 especialistas em Pol\u00edticas P\u00fablicas e Gest\u00e3o Governamental. As vagas s\u00e3o relativas ao concurso p\u00fablico realizado em 2009, com prazo de vencimento a expirar em dezembro de 2011. A autoriza\u00e7\u00e3o foi publicada na p\u00e1gina 68 da Se\u00e7\u00e3o 1 do Di\u00e1rio Oficial da Uni\u00e3o de segunda-feira (15\/8).  &nbsp;  Os gestores v\u00e3o representar um refor\u00e7o t\u00e9cnico nos quadros de diversos \u00f3rg\u00e3os da Administra\u00e7\u00e3o P\u00fablica Federal. Mas, para isso, precisar\u00e3o passar por curso de forma\u00e7\u00e3o na Escola Nacional de Administra\u00e7\u00e3o P\u00fablica (Enap). O curso \u00e9 obrigat\u00f3rio, considerado a segunda etapa do concurso.  &nbsp;  Os primeiros gestores aprovados no concurso p\u00fablico de 2009, nomeados em fevereiro deste ano, j\u00e1 est\u00e3o trabalhando na Casa Civil da Presid\u00eancia da Rep\u00fablica, Secretaria-Geral da Presid\u00eancia, Subchefia de Assuntos Federativos da Secretaria de Rela\u00e7\u00f5es Institucionais da Presid\u00eancia, Secretaria de Pol\u00edticas para as Mulheres, Secretaria de Promo\u00e7\u00e3o da Igualdade Racial, e nos minist\u00e9rios da Ci\u00eancia e Tecnologia, Educa\u00e7\u00e3o, Integra\u00e7\u00e3o Nacional, Justi\u00e7a, Sa\u00fade, Cidades, Comunica\u00e7\u00f5es, Desenvolvimento Agr\u00e1rio, Desenvolvimento Social e Combate \u00e0 Fome, Desenvolvimento, Ind\u00fastria e Com\u00e9rcio Exterior, Esportes, Trabalho e Emprego, e Planejamento.  &nbsp;  A Carreira de Especialista em Pol\u00edticas P\u00fablicas e Gestor Governamental completou 20 anos em 2009. Foi idealizada para profissionalizar a gest\u00e3o do Estado por meio da atua\u00e7\u00e3o de um corpo de servidores permanentes, com inser\u00e7\u00e3o em toda a administra\u00e7\u00e3o, com a finalidade de constituir um elo entre os governantes e a m\u00e1quina p\u00fablica. A Secretaria de Gest\u00e3o (Seges) do Minist\u00e9rio do Planejamento \u00e9 respons\u00e1vel por coordenar a defini\u00e7\u00e3o da unidade de exerc\u00edcio dos gestores e autorizar suas movimenta\u00e7\u00f5es. A triagem das vagas leva em conta as condi\u00e7\u00f5es da for\u00e7a de trabalho dos \u00f3rg\u00e3os e minist\u00e9rios e os programas priorit\u00e1rios em curso no Governo Federal.  &nbsp;  <b>Autoriza\u00e7\u00e3o especial<\/b>  Como se trata de quantitativo superior a 50% do n\u00famero original de vagas, a autoriza\u00e7\u00e3o da Presid\u00eancia da Rep\u00fablica \u00e9 necess\u00e1ria. O mesmo procedimento ocorreu em abril, quando o governo autorizou, por meio de Exposi\u00e7\u00e3o de Motivos, 60 vagas extras para o cargo de analista ambiental do Ibama. Em junho, outra Exposi\u00e7\u00e3o de Motivos, permitiu o ingresso de mais 200 policiais rodovi\u00e1rios federais.  &nbsp;  Desde o an\u00fancio das medidas restritivas para concursos e nomea\u00e7\u00f5es anunciadas no come\u00e7o do ano, o MP segue o crit\u00e9rio de convocar aprovados, preferencialmente dos certames com prazos em fase de encerramento. Dessa forma, o minist\u00e9rio se organiza para conciliar as autoriza\u00e7\u00f5es com a meta de redu\u00e7\u00e3o de despesas e as prioridades de governo, respeitando direitos adquiridos.    <\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Do CorreioWeb &nbsp; A presidenta Dilma Roussef autorizou nesta semana o ingresso de mais 92 especialistas em Pol\u00edticas P\u00fablicas e Gest\u00e3o Governamental. As vagas s\u00e3o relativas ao concurso p\u00fablico realizado em 2009, com prazo de vencimento a expirar em dezembro de 2011. A autoriza\u00e7\u00e3o foi publicada na p\u00e1gina 68 da Se\u00e7\u00e3o 1 do Di\u00e1rio Oficial da Uni\u00e3o de segunda-feira [&hellip;]<\/p>\n","protected":false},"author":33,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1734","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/1734","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/comments?post=1734"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/1734\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/media?parent=1734"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/categories?post=1734"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/tags?post=1734"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}