{"id":1693,"date":"2011-07-18T08:54:00","date_gmt":"2011-07-18T11:54:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/tjes_forma_comissao_de_concurso_para_cartorios_de_todo_estado\/"},"modified":"2011-07-18T08:54:00","modified_gmt":"2011-07-18T11:54:00","slug":"tjes_forma_comissao_de_concurso_para_cartorios_de_todo_estado","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/tjes_forma_comissao_de_concurso_para_cartorios_de_todo_estado\/","title":{"rendered":"TJES forma comiss\u00e3o de concurso para cart\u00f3rios de todo estado"},"content":{"rendered":"<p>  <b><i> <\/p>\n<p><\/i><\/b><b><i>Do CorreioWeb<\/i><\/b>  &nbsp;  <b>O Tribunal de Justi\u00e7a do Esp\u00edrito Santo (TJES) se tornou mais uma das cortes que se apressam para cumprir a determina\u00e7\u00e3o do Conselho Nacional de Justi\u00e7a (CNJ) \u2013 a de substituir o quadro de profissionais irregulares de cart\u00f3rios por servidores devidamente concursados.<\/b> Os tribunais dos estados do Maranh\u00e3o, Cear\u00e1, Minas Gerais e S\u00e3o Paulo j\u00e1 deram o pontap\u00e9 inicial e lan\u00e7aram editais de concursos, que juntos somam 1.433 vagas imediatas.  <b>&nbsp;<\/b>  Os desembargadores do TJES aprovaram a comiss\u00e3o examinadora do pr\u00f3ximo certame que vai preencher vagas em serventias extrajudiciais. De acordo com dados do pr\u00f3prio TJ, atualmente 106 cart\u00f3rios t\u00eam o cargo de tabeli\u00e3o vago.  &nbsp;  A comiss\u00e3o elegeu como presidente o corregedor geral da Justi\u00e7a, desembargador S\u00e9rgio Luiz Teixeira Gama, e como membros os magistrados Aldary Nunes J\u00fanior, Ezequiel Tur\u00edbio e Maria Cristina de Souza Ferreira, al\u00e9m do registrador Helv\u00e9cio Duia Castello, a tabeli\u00e3 Gerusa Corteletti Ronconi, a procuradora de Justi\u00e7a Ivanilce da Cruz Rom\u00e3o e o advogado Francisco Carlos Pio de Oliveira.  &nbsp;  O concurso p\u00fablico ainda n\u00e3o tem data prevista para sua realiza\u00e7\u00e3o. As informa\u00e7\u00f5es tamb\u00e9m foram publicadas na p\u00e1gina oficial do TJES. Veja a <a href=\"http:\/\/www.tj.es.gov.br\/%25C3%259Altimas-Not%25C3%25ADcias\/tjes-aprova-comissao-examinadora-para-concurso-de-serventias-extrajudiciais.html\">nota<\/a>.  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Do CorreioWeb &nbsp; O Tribunal de Justi\u00e7a do Esp\u00edrito Santo (TJES) se tornou mais uma das cortes que se apressam para cumprir a determina\u00e7\u00e3o do Conselho Nacional de Justi\u00e7a (CNJ) \u2013 a de substituir o quadro de profissionais irregulares de cart\u00f3rios por servidores devidamente concursados. Os tribunais dos estados do Maranh\u00e3o, Cear\u00e1, Minas Gerais e S\u00e3o Paulo j\u00e1 deram o [&hellip;]<\/p>\n","protected":false},"author":33,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1693","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/1693","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/comments?post=1693"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/1693\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/media?parent=1693"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/categories?post=1693"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/tags?post=1693"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}