{"id":1643,"date":"2011-06-10T14:55:00","date_gmt":"2011-06-10T17:55:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/tjam_deve_lancar_concurso_para_servidores_e_juizes\/"},"modified":"2011-06-10T14:55:00","modified_gmt":"2011-06-10T17:55:00","slug":"tjam_deve_lancar_concurso_para_servidores_e_juizes","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/tjam_deve_lancar_concurso_para_servidores_e_juizes\/","title":{"rendered":"TJAM deve lan\u00e7ar concurso para servidores e ju\u00edzes"},"content":{"rendered":"<p>  <b><i> <\/p>\n<p><\/i><\/b><b><i>Do CorreioWeb<\/i><\/b><b> <i>\u2013 com informa\u00e7\u00f5es do TJAM<\/i><\/b>  &nbsp;  <b>A assessoria de comunica\u00e7\u00e3o do Tribunal de Justi\u00e7a do Amazonas (TJAM) confirmou \u00e0 equipe do <i>CorreioWeb<\/i> que at\u00e9 o final deste ano realizar\u00e1 concurso p\u00fablico para preencher um total de 800 vagas para servidores e 60 para ju\u00edzes substitutos.<\/b> De acordo com informa\u00e7\u00f5es do tribunal, os novos servidores v\u00e3o custar mais de R$ 4,5 milh\u00f5es por m\u00eas aos cofres do Tribunal.  &nbsp;  Primeiramente o TJAM vai lan\u00e7ar o concurso para servidores, cuja comiss\u00e3o organizadora foi at\u00e9 formada e ser\u00e1 encabe\u00e7ada pela desembargadora Carla Reis. A banca que vai organizar a sele\u00e7\u00e3o ainda n\u00e3o foi definida. Segundo informa\u00e7\u00f5es do Tribunal, um processo de licita\u00e7\u00e3o ser\u00e1 aberto para contratar a empresa, mas ainda n\u00e3o h\u00e1 data definida para iniciar o processo.  &nbsp;  J\u00e1 o concurso de magistrados ser\u00e1 realizado at\u00e9 o final do ano. Os novos ju\u00edzes devem atuar em varas da capital Manaus e do interior do Amazonas. Segundo informa\u00e7\u00f5es do presidente do tribunal, desembargador Jo\u00e3o Sim\u00f5es, enquanto o TJAM n\u00e3o conta com os novos contratados, as comarcas do interior, que seriam desativadas por falta de dinheiro, ser\u00e3o mantidas. A decis\u00e3o de manter as comarcas j\u00e1 foi aprovada pelo pleno do TJAM.  &nbsp;  No dia 21 de mar\u00e7o, o TJAM anunciou o fechamento de 36 comarcas no interior do Estado, que atendem a 652 mil pessoas. Ap\u00f3s dois meses de negocia\u00e7\u00f5es, que contaram com a presen\u00e7a de membros do Conselho Nacional de Justi\u00e7a (CNJ) para auxiliar o TJAM nas negocia\u00e7\u00f5es, o governo decidiu aumentar para R$ 419 milh\u00f5es o or\u00e7amento do tribunal em 2012, retirando 0,2% dos repasses da Assembleia Legislativa do Estado.    <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Do CorreioWeb \u2013 com informa\u00e7\u00f5es do TJAM &nbsp; A assessoria de comunica\u00e7\u00e3o do Tribunal de Justi\u00e7a do Amazonas (TJAM) confirmou \u00e0 equipe do CorreioWeb que at\u00e9 o final deste ano realizar\u00e1 concurso p\u00fablico para preencher um total de 800 vagas para servidores e 60 para ju\u00edzes substitutos. De acordo com informa\u00e7\u00f5es do tribunal, os novos servidores v\u00e3o custar mais de [&hellip;]<\/p>\n","protected":false},"author":33,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1643","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/1643","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/comments?post=1643"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/1643\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/media?parent=1643"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/categories?post=1643"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/tags?post=1643"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}