{"id":13812,"date":"2020-10-02T09:06:05","date_gmt":"2020-10-02T12:06:05","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/?p=13812"},"modified":"2020-10-02T09:06:05","modified_gmt":"2020-10-02T12:06:05","slug":"ccj-aprova-projeto-com-alteracoes-na-lei-geral-dos-concursos-veja-o-que-muda","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/ccj-aprova-projeto-com-alteracoes-na-lei-geral-dos-concursos-veja-o-que-muda\/","title":{"rendered":"CCJ aprova projeto com altera\u00e7\u00f5es na Lei Geral dos Concursos; veja o que muda"},"content":{"rendered":"<div class=\"normal\">\n<div class=\"ultimas_foto_link\">\n<h3 class=\"ultimas_legenda\">Uma das altera\u00e7\u00f5es amplia a validade da Lei Geral dos Concursos para os processos seletivos tempor\u00e1rios de estatais que recebam recursos do Tesouro e \u00f3rg\u00e3os de seguran\u00e7a p\u00fablica subordinados ao GDF<\/h3>\n<\/div>\n<\/div>\n<div id=\"aui_3_2_0_1144\" class=\"ultimas_texto\">\n<p>A Comiss\u00e3o de Constitui\u00e7\u00e3o e Justi\u00e7a (CCJ) da C\u00e2mara Legislativa do Distrito Federal (CLDF) aprovou o<a href=\"http:\/\/legislacao.cl.df.gov.br\/Legislacao\/consultaProposicao-1!957!2020!visualizar.action\"> projeto de lei 957\/2020<\/a> que altera a Lei n\u00ba 4.949\/2012 , a chamada Lei Geral dos Concursos.\u00a0\u00a0Uma das mudan\u00e7as amplia a validade das regras dos processos seletivos tempor\u00e1rios de estatais que recebam recursos do Tesouro, assim como aos \u00f3rg\u00e3os de seguran\u00e7a p\u00fablica subordinados ao Governador do Distrito Federal.<\/p>\n<p>De acordo com o autor do projeto, Jos\u00e9 Gomes as modifica\u00e7\u00f5es visam aperfei\u00e7oar a legisla\u00e7\u00e3o, para obter maior seguran\u00e7a jur\u00eddica, transpar\u00eancia e isonomia e diminuir a judicializa\u00e7\u00e3o excessiva em raz\u00e3o de alguns dispositivos legais.<\/p>\n<\/div>\n<div id=\"aui_3_2_0_1144\" class=\"ultimas_texto\">\n<p id=\"aui_3_2_0_1142\">A proposta tamb\u00e9m estabelece que o deficiente auditivo e o de vis\u00e3o monocular t\u00eam direito de concorrer, em concurso p\u00fablico, na administra\u00e7\u00e3o direta, aut\u00e1rquica e fundacional, \u00e0s vagas reservadas aos deficientes. O texto considera defici\u00eancia auditiva como a perda permanente de audi\u00e7\u00e3o, unilateral ou bilateral, no montante de quarenta e um decib\u00e9is (dB) ou mais.<\/p>\n<p id=\"aui_3_2_0_1155\">Tamb\u00e9m s\u00e3o feitas altera\u00e7\u00f5es nos processos de corre\u00e7\u00e3o de provas e apresenta\u00e7\u00e3o de recursos. Segundo o autor do projeto, a inten\u00e7\u00e3o \u00e9 diminuir a litigiosidade nos procedimentos de sele\u00e7\u00e3o de pessoal, bem como a de garantir maior transpar\u00eancia e seguran\u00e7a jur\u00eddica para a Administra\u00e7\u00e3o e para os candidatos.<\/p>\n<p>O projeto ainda est\u00e1 em tramita\u00e7\u00e3o. <a href=\"http:\/\/legislacao.cl.df.gov.br\/Legislacao\/consultaProposicao-1!957!2020!visualizar.action\">Acompanhe aqui.<\/a><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Uma das altera\u00e7\u00f5es amplia a validade da Lei Geral dos Concursos para os processos seletivos tempor\u00e1rios de estatais que recebam recursos do Tesouro e \u00f3rg\u00e3os de seguran\u00e7a p\u00fablica subordinados ao GDF A Comiss\u00e3o de Constitui\u00e7\u00e3o e Justi\u00e7a (CCJ) da C\u00e2mara Legislativa do Distrito Federal (CLDF) aprovou o projeto de lei 957\/2020 que altera a Lei n\u00ba 4.949\/2012 , a chamada [&hellip;]<\/p>\n","protected":false},"author":41,"featured_media":10820,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[282],"tags":[],"class_list":["post-13812","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-concursos"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/13812","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/users\/41"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/comments?post=13812"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/13812\/revisions"}],"predecessor-version":[{"id":13813,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/13812\/revisions\/13813"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/media\/10820"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/media?parent=13812"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/categories?post=13812"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/tags?post=13812"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}