{"id":13581,"date":"2020-09-11T10:31:49","date_gmt":"2020-09-11T13:31:49","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/?p=13581"},"modified":"2020-09-11T10:32:46","modified_gmt":"2020-09-11T13:32:46","slug":"autorizado-concurso-do-ibge-para-6-500-vagas-tera-edital-ate-marco","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/autorizado-concurso-do-ibge-para-6-500-vagas-tera-edital-ate-marco\/","title":{"rendered":"Autorizado! Concurso do IBGE para 6.500 vagas ter\u00e1 edital at\u00e9 mar\u00e7o"},"content":{"rendered":"<p>O <strong><a href=\"https:\/\/www.ibge.gov.br\/\">Instituto Brasileiro de Geografia e Estat\u00edstica (IBGE)<\/a><\/strong> foi oficialmente autorizado, nesta sexta-feira (11\/9) a contratar por termpo determinado, 6.500 profissionais. A informa\u00e7\u00e3o foi publicada no Di\u00e1rio Oficial da Uni\u00e3o.<\/p>\n<p>As chances s\u00e3o para agente de pesquisa e mapeamento, supervisor de coleta e qualidade, agente de pesquisa por telefone e supervisor de pesquisas.<\/p>\n<p>O an\u00fancio afirma que o prazo para publica\u00e7\u00e3o do edital de abertura de inscri\u00e7\u00f5es para o processo seletivo simplificado ser\u00e1 de at\u00e9 seis meses, contado a partir da publica\u00e7\u00e3o da Portaria, ou seja, at\u00e9 mar\u00e7o de 2021.<\/p>\n<p>Os profissionais poder\u00e3o ser contratados a partir de janeiro de 2021 para operacionaliza\u00e7\u00e3o das pesquisas permanentes de natureza estat\u00edstica e geocient\u00edfica do IBGE.<\/p>\n<p>De acordo com a publica\u00e7\u00e3o, as contrata\u00e7\u00f5es ser\u00e3o formalizadas mediante disponibilidade or\u00e7ament\u00e1rias e o recrutamento dos profissionais depender\u00e1 de pr\u00e9via aprova\u00e7\u00e3o dos candidatos em processo seletivo simplificado.<\/p>\n<p>O prazo de dura\u00e7\u00e3o dos contratos dever\u00e1 ser de at\u00e9 um ano. Mas, os contratos poder\u00e3o ser prorrogados, desde que devidamente justificados.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-13582\" src=\"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-content\/uploads\/sites\/14\/2020\/09\/coisa-2.jpg\" alt=\"\" width=\"519\" height=\"205\" srcset=\"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-content\/uploads\/sites\/14\/2020\/09\/coisa-2.jpg 519w, https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-content\/uploads\/sites\/14\/2020\/09\/coisa-2-300x118.jpg 300w, https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-content\/uploads\/sites\/14\/2020\/09\/coisa-2-230x91.jpg 230w\" sizes=\"auto, (max-width: 519px) 100vw, 519px\" \/><\/p>\n<p><strong><a href=\"https:\/\/www.in.gov.br\/en\/web\/dou\/-\/portaria-n-20.388-de-3-de-setembro-de-2020-276906108\">Confira a portaria completa aqui!<\/a><\/strong><\/p>\n<p><strong>Leia tamb\u00e9m: <a href=\"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/ibge-confirmada-abertura-de-concurso-com-208-mil-vagas-em-2021\/\">IBGE: confirmada abertura de concurso com 208 mil vagas em 2021<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Instituto Brasileiro de Geografia e Estat\u00edstica (IBGE) foi oficialmente autorizado, nesta sexta-feira (11\/9) a contratar por termpo determinado, 6.500 profissionais. A informa\u00e7\u00e3o foi publicada no Di\u00e1rio Oficial da Uni\u00e3o. As chances s\u00e3o para agente de pesquisa e mapeamento, supervisor de coleta e qualidade, agente de pesquisa por telefone e supervisor de pesquisas. O an\u00fancio afirma que o prazo para [&hellip;]<\/p>\n","protected":false},"author":41,"featured_media":9141,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[282],"tags":[],"class_list":["post-13581","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-concursos"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/13581","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/users\/41"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/comments?post=13581"}],"version-history":[{"count":2,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/13581\/revisions"}],"predecessor-version":[{"id":13584,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/13581\/revisions\/13584"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/media\/9141"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/media?parent=13581"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/categories?post=13581"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/tags?post=13581"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}