{"id":12849,"date":"2020-07-03T06:00:03","date_gmt":"2020-07-03T09:00:03","guid":{"rendered":"http:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/?p=12849"},"modified":"2020-07-28T14:39:44","modified_gmt":"2020-07-28T17:39:44","slug":"fique-por-dentro-do-pl-dos-30-dias-proposto-por-ibaneis-para-agilizar-concursos-da-pcdf","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/fique-por-dentro-do-pl-dos-30-dias-proposto-por-ibaneis-para-agilizar-concursos-da-pcdf\/","title":{"rendered":"Fique por dentro do &#8221;PL dos 30 dias&#8221;, proposto por Ibaneis para agilizar concursos da PCDF"},"content":{"rendered":"<h2>PL apresentado por Ibaneis quer alterar a Lei Geral dos Concursos do DF e diminuir o prazo para aplica\u00e7\u00e3o das provas apenas para a PCDF<\/h2>\n<p>&nbsp;<\/p>\n<p>Seria bom que os concurseiros de olho numa vaga na Pol\u00edcia Civil do Distrito Federal (PCDF) apressassem os estudos. Isso porque, o governador do Distrito Federal, Ibaneis Rocha, enviou uma mensagem ao deputado Rafael Prudente, presidente da C\u00e2mara Legislativa (CLDF), na semana passada, para submeter \u00e0 aprecia\u00e7\u00e3o da Casa um novo projeto de Lei espec\u00edfico para a sele\u00e7\u00e3o da corpora\u00e7\u00e3o, alterando a <strong><a href=\"http:\/\/www.fazenda.df.gov.br\/aplicacoes\/legislacao\/legislacao\/TelaSaidaDocumento.cfm?txtNumero=4949&amp;txtAno=2012&amp;txtTipo=5&amp;txtParte=.\">Lei n\u00ba 4.949<\/a><\/strong>, de 15 de outubro de 2012, conhecida como Lei Geral dos Concursos do DF. Ibaneis afirma que a mat\u00e9ria necessita de aprecia\u00e7\u00e3o com relativa brevidade, solicitando que seja em regime de urg\u00eancia.<\/p>\n<p>&nbsp;<\/p>\n<p>Segundo o PL, o par\u00e1grafo \u00fanico do artigo 11, que hoje est\u00e1 assim:<\/p>\n<pre class=\"legislao-4corpo\">O edital normativo do concurso p\u00fablico deve ser:\r\n\r\nI \u2013 publicado integralmente no Di\u00e1rio Oficial do Distrito Federal, \r\ncom anteced\u00eancia m\u00ednima de noventa dias da realiza\u00e7\u00e3o da primeira prova<\/pre>\n<p>deve ser alterado para:<\/p>\n<pre><em>\"Nos concursos p\u00fablicos para provimento de cargos das carreiras da Pol\u00edcia Civil do Distrito Federal, \r\no prazo de que trata o inciso I, deste artigo, ser\u00e1 de trinta dias da realiza\u00e7\u00e3o da primeira prova\u201d.<\/em><\/pre>\n<p>Ou seja, o objetivo \u00e9 a diminui\u00e7\u00e3o do prazo legal de 90 dias para um m\u00eas, mas apenas para sele\u00e7\u00f5es da PCDF.<\/p>\n<p>&nbsp;<\/p>\n<p>A proposta tamb\u00e9m inclui um quinto par\u00e1grafo no artigo 55, que versa sobre os recursos das provas, para conter outra exce\u00e7\u00e3o destinada apenas \u00e0 corpora\u00e7\u00e3o: <em>&#8220;Nos concursos p\u00fablicos para provimento de cargos das carreiras da Pol\u00edcia Civil do Distrito Federal, o prazo, de que trata \u00a7 1\u00ba deste artigo, ser\u00e1 de, no m\u00ednimo, cinco dias \u00fateis, contados da publica\u00e7\u00e3o oficial do gabarito ou do resultado das provas.\u201d<\/em> O prazo antes era de, no m\u00ednimo, 10 dias \u00fateis para interposi\u00e7\u00e3o de recurso, contado da publica\u00e7\u00e3o oficial do gabarito ou do resultado das provas.<\/p>\n<p>E, para garantir que o proposto no PL ainda valha para os concursos em aberto no momento pela PCDF, escriv\u00e3o e agente, a mat\u00e9ria ainda pretende modificar o artigo segundo e terceiro, inserindo os textos:<\/p>\n<p><em>&#8221;Art. 2\u00ba Aplica-se o disposto nesta Lei a concursos p\u00fablicos em andamento, desde que ainda n\u00e3o realizada a primeira prova, caso em que o edital normativo dever\u00e1 ser republicado com as devidas altera\u00e7\u00f5es. <\/em><\/p>\n<p><em>Art. 3\u00ba Esta Lei entra em vigor na data de sua publica\u00e7\u00e3o&#8221;\u00a0<\/em><\/p>\n<p>&nbsp;<\/p>\n<h3>Justificativa do diretor-geral da PCDF<\/h3>\n<p>A justificativa da mat\u00e9ria foi feita pelo pr\u00f3prio diretor-Geral da Pol\u00edcia Civil do Distrito Federal (PCDF), Robson C\u00e2ndido. Segundo o delegado, o objetivo de incluir disposivo prevendo prazos diferenciados para a PCDF \u00e9 que &#8220;a observ\u00e2ncia da legisla\u00e7\u00e3o distrital em comento no que tange a concursos p\u00fablicos para provimento de cargos de \u00f3rg\u00e3os de natureza policial que, por for\u00e7a do art. 21, Inc. XIV, da Constitui\u00e7\u00e3o\u00a0Federal, s\u00e3o organizados e mantidos pela Uni\u00e3o, tem potencial de gerar inseguran\u00e7a jur\u00eddica e, pela elasticidade de certos prazos, grave preju\u00edzo \u00e0 administra\u00e7\u00e3o p\u00fablica e aos pr\u00f3prios candidatos.&#8221;<\/p>\n<p>&#8220;Isso porque os concursos para provimento de cargos de natureza policial, em especial da Pol\u00edcia Civil do Distrito Federal, demandam a realiza\u00e7\u00e3o de diversas fases, incluindo avalia\u00e7\u00e3o psicol\u00f3gica e de aptid\u00e3o f\u00edsica, somado ao fato de que o curso de forma\u00e7\u00e3o integra o certame, o que torna todo o processo bastante longo e, portanto, penoso.&#8221;<\/p>\n<p>Assim, o diretor considera que os prazos da lei distrital s\u00e3o dilatados &#8220;quando se observa a complexidade dos atos relacionados ao certame para provimento de cargos de natureza policial&#8221;. Segundo C\u00e2ndido, devido a esses prazos, os concursos p\u00fablicos da PCDF podem levar at\u00e9 dois anos para sua conclus\u00e3o, &#8220;em evidente e grave preju\u00edzo aos candidatos e, em especial, para a administra\u00e7\u00e3o p\u00fablica e ao destinat\u00e1rio dos seus servi\u00e7os p\u00fablicos.&#8221;<\/p>\n<p>O delegado enfatizou que os concursos para escriv\u00e3o e agente foram autorizados porque o quadro de pessoal hoje representa pouco mais de 40% do previsto em lei, sem falar que a a institui\u00e7\u00e3o conta com mais de 260 servidores em abono de perman\u00eancia, ou seja, aptos \u00e0 imediata aposentadoria, &#8220;o que torna urgente e imperiosa, a bem do interesse p\u00fablico, a c\u00e9lere sele\u00e7\u00e3o e contrata\u00e7\u00e3o de novos servidores&#8221;.<\/p>\n<p>O PL j\u00e1 foi protocolado na CLDF, sob o n\u00famero <a href=\"http:\/\/legislacao.cl.df.gov.br\/Legislacao\/consultaProposicao-1!1272!2020!visualizar.action\"><strong>1272<\/strong><\/a>, e aguarda aprecia\u00e7\u00e3o.<\/p>\n<p>&nbsp;<\/p>\n<h3>Fim do concurso PCDF apenas em 2022<\/h3>\n<p>De fato, o cronograma oficial do recente concurso p\u00fablico para agente da PCDF pode assustar. Est\u00e1 prevista somente para 22 de fevereiro de 2022, ou seja, mais de um ano e meio ap\u00f3s o lan\u00e7amento do edital de abertura, a divulga\u00e7\u00e3o do resultado final na primeira\u00a0etapa do concurso e convoca\u00e7\u00e3o em 1\u00aa chamada para matr\u00edcula do 1\u00ba grupo do curso de forma\u00e7\u00e3o profissional. Ser\u00e3o, ao todo, tr\u00eas grupos, o \u00faltimo est\u00e1 previsto para ter o curso de forma\u00e7\u00e3o finalizado apenas em setembro de 2022.<\/p>\n<p>Por outro lado, o prazo para os estudos do conte\u00fado complexo do edital, que surpreendeu os candidatos com a cobran\u00e7a de mat\u00e9rias n\u00e3o comuns em concursos policiais, at\u00e9 a prova marcada para 18 de outubro, encurtaria em dois ter\u00e7os, e os concurseiros teriam que apertar, e muito, o passo para conseguir vencer todo o edital. <em>Prepara-se melhor ap\u00f3s ler isso:\u00a0<\/em><a href=\"http:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/estatistica-contabilidade-especialistas-analisam-edital-para-agente-da-pcdf-2020\/\"><strong>Estat\u00edstica, contabilidade? Especialistas analisam edital para agente da PCDF 2020\u00a0<\/strong><\/a><\/p>\n<p>No dia da publica\u00e7\u00e3o do edital para agentes, nesta quarta-feira (1\u00ba\/7) no DODF, o diretor-geral da PCDF se pronunciou em seu perfil pessoal no Instagram falando que estava trabalhando para agilizar os tr\u00e2mites do concurso, quando foi perguntado por um seguidor sobre o andamento extenso do certame.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-content\/uploads\/sites\/14\/2020\/07\/WhatsApp-Image-2020-07-01-at-11.31.37.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-12808\" src=\"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-content\/uploads\/sites\/14\/2020\/07\/WhatsApp-Image-2020-07-01-at-11.31.37.jpeg\" alt=\"\" width=\"445\" height=\"87\" srcset=\"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-content\/uploads\/sites\/14\/2020\/07\/WhatsApp-Image-2020-07-01-at-11.31.37.jpeg 640w, https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-content\/uploads\/sites\/14\/2020\/07\/WhatsApp-Image-2020-07-01-at-11.31.37-300x59.jpeg 300w, https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-content\/uploads\/sites\/14\/2020\/07\/WhatsApp-Image-2020-07-01-at-11.31.37-550x107.jpeg 550w, https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-content\/uploads\/sites\/14\/2020\/07\/WhatsApp-Image-2020-07-01-at-11.31.37-230x45.jpeg 230w\" sizes=\"auto, (max-width: 445px) 100vw, 445px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-content\/uploads\/sites\/14\/2020\/07\/WhatsApp-Image-2020-07-01-at-11.20.26.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-12806\" src=\"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-content\/uploads\/sites\/14\/2020\/07\/WhatsApp-Image-2020-07-01-at-11.20.26.jpeg\" alt=\"\" width=\"447\" height=\"437\" srcset=\"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-content\/uploads\/sites\/14\/2020\/07\/WhatsApp-Image-2020-07-01-at-11.20.26.jpeg 640w, https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-content\/uploads\/sites\/14\/2020\/07\/WhatsApp-Image-2020-07-01-at-11.20.26-300x293.jpeg 300w, https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-content\/uploads\/sites\/14\/2020\/07\/WhatsApp-Image-2020-07-01-at-11.20.26-550x538.jpeg 550w, https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-content\/uploads\/sites\/14\/2020\/07\/WhatsApp-Image-2020-07-01-at-11.20.26-230x225.jpeg 230w\" sizes=\"auto, (max-width: 447px) 100vw, 447px\" \/><\/a><\/p>\n<p>O edital de abertura para agente da PCDF foi lan\u00e7ado com oferta de 1.800 vagas para candidatos com qualquer n\u00edvel superior e sal\u00e1rio inicial de R$ 8,6 mil. O concurso promete ser o maior do ano em termos de concorr\u00eancia. Confira aqui o edital, an\u00e1lise, dicas e <a href=\"http:\/\/concursos.correioweb.com.br\/app\/noticias\/2020\/07\/01\/noticiasinterna,40878\/concurso-agente-pcdf-edital-com-1-800-vagas-e-finalmente-lancado-no-d.shtml\"><strong>tudo sobre o novo concurso aqui!\u00a0<\/strong><\/a> J\u00e1 o concurso para escriv\u00e3o ainda est\u00e1 suspenso devido ao coronav\u00edrus; as provas estavam marcadas para mar\u00e7o deste ano.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center\"><em>E compartilhe a mat\u00e9ria no<\/em> <a href=\"http:\/\/forum.concursos.correioweb.com.br\/\"><strong>F\u00f3rum CW!\u00a0<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>PL apresentado por Ibaneis quer alterar a Lei Geral dos Concursos do DF e diminuir o prazo para aplica\u00e7\u00e3o das provas apenas para a PCDF &nbsp; Seria bom que os concurseiros de olho numa vaga na Pol\u00edcia Civil do Distrito Federal (PCDF) apressassem os estudos. Isso porque, o governador do Distrito Federal, Ibaneis Rocha, enviou uma mensagem ao deputado Rafael [&hellip;]<\/p>\n","protected":false},"author":33,"featured_media":12851,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[282],"tags":[1460,1463,705,1565,106,1566,1567],"class_list":["post-12849","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-concursos","tag-agente-pcdf","tag-escrivao-pcdf","tag-ibaneis-rocha","tag-lei-geral-dos-concursos-df","tag-pcdf","tag-pl-dos-30-dias","tag-robson-candido"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/12849","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/comments?post=12849"}],"version-history":[{"count":3,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/12849\/revisions"}],"predecessor-version":[{"id":13108,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/12849\/revisions\/13108"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/media\/12851"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/media?parent=12849"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/categories?post=12849"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/tags?post=12849"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}