{"id":11002,"date":"2020-01-28T13:30:32","date_gmt":"2020-01-28T16:30:32","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/?p=11002"},"modified":"2020-01-28T13:30:32","modified_gmt":"2020-01-28T16:30:32","slug":"menos-de-um-segundo-justica-anula-reprovacao-de-candidato-que-excedeu-tempo-de-prova-da-pf","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/menos-de-um-segundo-justica-anula-reprovacao-de-candidato-que-excedeu-tempo-de-prova-da-pf\/","title":{"rendered":"Menos de um segundo: Justi\u00e7a anula reprova\u00e7\u00e3o de candidato que excedeu tempo de prova da PF"},"content":{"rendered":"<h2>O candidato tamb\u00e9m requereu\u00a0invalida\u00e7\u00e3o do teste psicot\u00e9cnico, ap\u00f3s ser reprovado<\/h2>\n<p><em>Vict\u00f3ria Ol\u00edmpio*<\/em> &#8211; Foi anulada, pela Sexta Turma do Tribunal Regional da 1\u00aa Regi\u00e3o (TRF-1), a reprova\u00e7\u00e3o no exame f\u00edsico de nata\u00e7\u00e3o e no teste psicot\u00e9cnico de um candidato que concorria ao cargo de agente da Pol\u00edcia Federal. Na apela\u00e7\u00e3o, o candidato argumento que nadou os 50 metros alcan\u00e7ando a marca de 41\u201d88, enquanto a exig\u00eancia era de que nadasse a mesma dist\u00e2ncia em at\u00e9 41\u201d00, sob pena de reprova\u00e7\u00e3o no concurso.<\/p>\n<p>O relator do caso, juiz federal convocado C\u00e9sar Cintra Jatahy Fonseca apontou que \u201co conceito de &#8216;capacidade f\u00edsica&#8217; \u00e9 um conceito de experi\u00eancia. \u00c9 com base na experi\u00eancia que se vai responder se um candidato que nade 50 metros em uma piscina, em 41 segundos e 56 mil\u00e9simos \u2013 quando o m\u00e1ximo permitido era 41 segundos -, tem, sob esse aspecto, capacidade f\u00edsica para exercer o cargo de agente de Pol\u00edcia Federal\u201d.<\/p>\n<p>Ainda de acordo com o relator, \u201co policial federal s\u00f3 excepcionalmente lida com a viol\u00eancia\u201d, logo \u201cem termos de complei\u00e7\u00e3o f\u00edsica, para o exerc\u00edcio do cargo de policial federal \u00e9, sen\u00e3o efeito do paradigma masculino e patriarcal de nossa sociedade, reminisc\u00eancia das administra\u00e7\u00f5es militares a que o Departamento de Pol\u00edcia Federal esteve por muitos anos submetido, sem contar que nas pr\u00f3prias For\u00e7as Armadas tais requisitos merecem ser adaptados \u00e0 evolu\u00e7\u00e3o tecnol\u00f3gica\u201d.<\/p>\n<p>O magistrado tamb\u00e9m afirmou que \u201cn\u00e3o consta que algu\u00e9m aprovado de acordo com essa marca tenha-se revelado fisicamente incapaz para o exerc\u00edcio do cargo, de modo a justificar reajuste da exig\u00eancia\u201d. O juiz explicou que a prova pode estar sujeita a diversos fatores externos que podem variar no dia do teste.<\/p>\n<p>&nbsp;<\/p>\n<h3>Teste psicot\u00e9cnico da PF<\/h3>\n<p>Tamb\u00e9m foi requerido pelo candidato a invalida\u00e7\u00e3o do teste psicot\u00e9cnico, que alegou erro t\u00e9cnico grosseiro na avalia\u00e7\u00e3o da banca examinadora, que o reprovou em fun\u00e7\u00e3o de quatro caracter\u00edsticas avaliadas no teste PMK: dimens\u00e3o tensional, ang\u00fastia, inseguran\u00e7a e instabilidade.<\/p>\n<p>Sobre a elimina\u00e7\u00e3o do candidato no exame psicot\u00e9cnico, consta de jurisprud\u00eancia do Supremo Tribunal Federal (STF), que h\u00e1 a necessidade de previs\u00e3o em lei e \u201c\u00e9 necess\u00e1rio um grau m\u00ednimo de objetividade e de publicidade dos crit\u00e9rios que nortear\u00e3o a avalia\u00e7\u00e3o psicot\u00e9cnica. A aus\u00eancia desses requisitos torna o ato ileg\u00edtimo, por n\u00e3o possibilitar o acesso \u00e0 tutela jurisdicional para a verifica\u00e7\u00e3o de les\u00e3o de direito individual pelo uso desses crit\u00e9rios\u201d.<\/p>\n<p>Com repercuss\u00e3o geral, o STF firmou ainda a tese de que \u201cno caso de declara\u00e7\u00e3o de nulidade de exame psicot\u00e9cnico previsto em lei e em edital, \u00e9 indispens\u00e1vel \u00e0 realiza\u00e7\u00e3o de nova avalia\u00e7\u00e3o, com crit\u00e9rios objetivos, para prosseguimento no certame\u201d.<\/p>\n<p style=\"text-align: center\"><em>O que voc\u00ea achou da not\u00edcia? Comente no<\/em> <strong><a href=\"http:\/\/forum.concursos.correioweb.com.br\/\">F\u00f3rum CW!\u00a0<\/a><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><em>* Estagi\u00e1ria sob supervis\u00e3o de Lorena Pacheco<\/em><\/p>\n<p><em>* Com informa\u00e7\u00f5es de TRF1<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O candidato tamb\u00e9m requereu\u00a0invalida\u00e7\u00e3o do teste psicot\u00e9cnico, ap\u00f3s ser reprovado Vict\u00f3ria Ol\u00edmpio* &#8211; Foi anulada, pela Sexta Turma do Tribunal Regional da 1\u00aa Regi\u00e3o (TRF-1), a reprova\u00e7\u00e3o no exame f\u00edsico de nata\u00e7\u00e3o e no teste psicot\u00e9cnico de um candidato que concorria ao cargo de agente da Pol\u00edcia Federal. Na apela\u00e7\u00e3o, o candidato argumento que nadou os 50 metros alcan\u00e7ando a [&hellip;]<\/p>\n","protected":false},"author":32,"featured_media":11003,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[282,1253,1185],"tags":[24,1250,1255,564,348,805,1254,872],"class_list":["post-11002","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-concursos","category-policia-federal","category-taf","tag-concurso","tag-decisao","tag-exma-psicologico","tag-pf","tag-policia-federal","tag-taf","tag-teste-fisico","tag-trf1"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/11002","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/comments?post=11002"}],"version-history":[{"count":4,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/11002\/revisions"}],"predecessor-version":[{"id":11027,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/11002\/revisions\/11027"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/media\/11003"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/media?parent=11002"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/categories?post=11002"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/tags?post=11002"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}