{"id":10455,"date":"2019-12-16T13:51:40","date_gmt":"2019-12-16T16:51:40","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/?p=10455"},"modified":"2019-12-16T13:51:40","modified_gmt":"2019-12-16T16:51:40","slug":"cro-de-sao-paulo-contrata-banca-organizadora-do-novo-concurso","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/cro-de-sao-paulo-contrata-banca-organizadora-do-novo-concurso\/","title":{"rendered":"CRO de S\u00e3o Paulo contrata banca organizadora do novo concurso"},"content":{"rendered":"<p>Vict\u00f3ria Ol\u00edmpio * &#8211; O Conselho Regional de Odontologia de S\u00e3o Paulo (<strong><a href=\"http:\/\/www.crosp.org.br\/\">CRO\/SP<\/a><\/strong>) vai realizar um novo concurso p\u00fablico e j\u00e1 definiu a banca organizadora! A <strong><a href=\"http:\/\/www.rboconcursos.com.br\/convocacao.php?c=87\">RBO Servi\u00e7os P\u00fablicos e Projetos Eireli EPP<\/a><\/strong> foi a contratada para planejamento, organiza\u00e7\u00e3o\u00a0e execu\u00e7\u00e3o de concurso p\u00fablico e\/ou processo seletivo de provas objetivas, pr\u00e1ticas e provas de t\u00edtulos.<\/p>\n<p>Est\u00e1 previsto que as taxas de inscri\u00e7\u00e3o sejam de R$ 41,70 para cargos de n\u00edvel m\u00e9dio e R$ 51,70 para os cargos de n\u00edvel superior.<\/p>\n<p>O Conselho n\u00e3o informou uma previs\u00e3o de quando o edital ser\u00e1 publicado ou o quantitativo de vagas que ser\u00e3o ofertados. O contrato com a banca organizadora pode ser conferido atrav\u00e9s do Di\u00e1rio Oficial da Uni\u00e3o (<strong><a href=\"http:\/\/pesquisa.in.gov.br\/imprensa\/jsp\/visualiza\/index.jsp?data=12\/12\/2019&amp;jornal=530&amp;pagina=194&amp;totalArquivos=286\">DOU<\/a><\/strong>).<\/p>\n<h3>\u00daltimo concurso<\/h3>\n<p>Em 2015 o Conselho <strong><a href=\"http:\/\/www.crosp.org.br\/uploads\/selecao_publica\/8934734f0af80bb3212fbeaa0808bd42.pdf\">realizou o \u00faltimo certame<\/a><\/strong>, que ofertou 39 vagas e forma\u00e7\u00e3o de cadastro reserva. A Funda\u00e7\u00e3o para o Vestibular da Universidade Estadual Paulista \u201cJ\u00falio de Mesquita Filho\u201d (Funda\u00e7\u00e3o Vunesp) foi a banca respons\u00e1vel pelo certame. Os aprovados receberam remunera\u00e7\u00f5es variando de R$ 1.378,74 a R$ 4.488,99 , al\u00e9m dos acr\u00e9scimos de vale refei\u00e7\u00e3o e alimenta\u00e7\u00e3o, assist\u00eancia m\u00e9dica e odontol\u00f3gico, aux\u00edlio educa\u00e7\u00e3o e creche, seguro de vida, vale transporte e uniforme.<\/p>\n<p>As chances foram para auxiliar administrativo, auxiliar de servi\u00e7os gerais, motorista, telefonista, advogado junior, analista de suporte, assistente administrativo, assistente cont\u00e1bil, bibliotec\u00e1rio, fiscal e programador. A sele\u00e7\u00e3o foi realizada por prova objetiva e discursiva, para o cargo de fiscal.<\/p>\n<p style=\"text-align: center\"><em>O que voc\u00ea achou da not\u00edcia? Comente no<\/em> <strong><a href=\"http:\/\/forum.concursos.correioweb.com.br\/viewforum.php?f=57&amp;sid=3c37580a4390df9703ebdcc6c03d5437\">F\u00f3rum CW. <\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vict\u00f3ria Ol\u00edmpio * &#8211; O Conselho Regional de Odontologia de S\u00e3o Paulo (CRO\/SP) vai realizar um novo concurso p\u00fablico e j\u00e1 definiu a banca organizadora! A RBO Servi\u00e7os P\u00fablicos e Projetos Eireli EPP foi a contratada para planejamento, organiza\u00e7\u00e3o\u00a0e execu\u00e7\u00e3o de concurso p\u00fablico e\/ou processo seletivo de provas objetivas, pr\u00e1ticas e provas de t\u00edtulos. Est\u00e1 previsto que as taxas de [&hellip;]<\/p>\n","protected":false},"author":32,"featured_media":10456,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[153,282,4],"tags":[187,1131,763],"class_list":["post-10455","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-autorizacao","category-concursos","category-concursos-publicos","tag-concursos","tag-cro-sp","tag-dou"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/10455","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/comments?post=10455"}],"version-history":[{"count":3,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/10455\/revisions"}],"predecessor-version":[{"id":10459,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/10455\/revisions\/10459"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/media\/10456"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/media?parent=10455"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/categories?post=10455"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/tags?post=10455"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}