{"id":10227,"date":"2019-12-02T16:11:59","date_gmt":"2019-12-02T19:11:59","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/?p=10227"},"modified":"2019-12-02T16:56:19","modified_gmt":"2019-12-02T19:56:19","slug":"tecnicas-de-memorizacao-cursinho-promove-evento-gratuito-com-o-leitor-mais-rapido-do-mundo","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/tecnicas-de-memorizacao-cursinho-promove-evento-gratuito-com-o-leitor-mais-rapido-do-mundo\/","title":{"rendered":"T\u00e9cnicas de memoriza\u00e7\u00e3o: cursinho promove evento gratuito com &#8220;o leitor mais r\u00e1pido do mundo&#8221;!"},"content":{"rendered":"<p><em>Vict\u00f3ria Ol\u00edmpio<\/em>* &#8211; Estudar para concursos p\u00fablicos requer dedica\u00e7\u00e3o, determina\u00e7\u00e3o e estrat\u00e9gia. A trajet\u00f3ria pode levar meses e at\u00e9 anos, mas os concurseiros n\u00e3o podem perder tempo e precisam adotar t\u00e9cnicas eficientes nos estudos para alcan\u00e7ar a t\u00e3o sonhada aprova\u00e7\u00e3o.<\/p>\n<p>Para ajudar os estudantes, um evento online e gratuito est\u00e1 sendo promovido pelo Gran Cursos Online, nesta segunda-feira (2\/12). A coach Erika Radespiel vai entrevistar James Bauer, considerado pelo Livro dos Recordes &#8220;o leitor mais r\u00e1pido do mundo&#8221;, segundo o Gran Cursos Online. Bauer vai apresentar seu m\u00e9todo exclusivo de super aprendizagem com t\u00e9cnicas de memoriza\u00e7\u00e3o que v\u00e3o ajudar os candidatos na trajet\u00f3ria dos estudos.<\/p>\n<p>O evento\u00a0come\u00e7ar\u00e1, a partir das 19h, no canal do Gran Cursos Online. As inscri\u00e7\u00f5es podem ser realizadas <a href=\"https:\/\/www.grancursosonline.com.br\/lp\/entrevista-com-james-saigg-bauer\" target=\"_blank\" rel=\"noopener\">aqui<\/a>.<\/p>\n<p>Tamb\u00e9m ser\u00e3o sorteados cinco exemplares da sua obra \u201cManual Pr\u00e1tico Passo a Passo \u2013 Leitura Din\u00e2mica\u201d. Os candidatos ainda ter\u00e3o acesso \u00e0s t\u00e9cnicas de leitura din\u00e2mica e memoriza\u00e7\u00e3o de informa\u00e7\u00f5es para provas e concursos.<\/p>\n<p>\u201cS\u00e3o exerc\u00edcios simples e acess\u00edveis que s\u00e3o capazes de, em poucos minutos, dobrar a velocidade de leitura do estudante, sem comprometer a compreens\u00e3o do conte\u00fado: exerc\u00edcios com os olhos, com as m\u00e3os e pr\u00e1ticas de ritmiza\u00e7\u00e3o. Al\u00e9m disso, o espectador saber\u00e1 como pode monitorar a sua evolu\u00e7\u00e3o enquanto leitor por meio de testes objetivos,\u201d destaca a coach.<\/p>\n<p>&nbsp;<\/p>\n<h3>Sobre o leitor mais r\u00e1pido do mundo, James Bauer<\/h3>\n<p>Bauer \u00e9 pesquisador das ci\u00eancias cognitivas, professor de leitura din\u00e2mica, compreens\u00e3o autom\u00e1tica, interpreta\u00e7\u00e3o de textos, mnem\u00f4nica, programa\u00e7\u00e3o neurolingu\u00edstica, aprendizagem acelerada, intelig\u00eancia aplicada, neuroci\u00eancia, orat\u00f3ria, metodologia de estudos e desenvolvimento pessoal.<\/p>\n<p>Ao longo de seus 25 anos de atua\u00e7\u00e3o, o profissional j\u00e1 atendeu a mais de um milh\u00e3o de alunos realizando mentorias e ministrando cursos e palestras em todo o Brasil e exterior. Suas palestras e treinamentos s\u00e3o acess\u00edveis mediante a doa\u00e7\u00e3o de leite e alimentos.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center\"><em>O que voc\u00ea achou da not\u00edcia? Comente no<\/em> <strong><a href=\"http:\/\/forum.concursos.correioweb.com.br\/\">F\u00f3rum CW. <\/a><\/strong><\/p>\n<p><em>* Estagi\u00e1ria sob supervis\u00e3o de Lorena Pacheco<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vict\u00f3ria Ol\u00edmpio* &#8211; Estudar para concursos p\u00fablicos requer dedica\u00e7\u00e3o, determina\u00e7\u00e3o e estrat\u00e9gia. A trajet\u00f3ria pode levar meses e at\u00e9 anos, mas os concurseiros n\u00e3o podem perder tempo e precisam adotar t\u00e9cnicas eficientes nos estudos para alcan\u00e7ar a t\u00e3o sonhada aprova\u00e7\u00e3o. Para ajudar os estudantes, um evento online e gratuito est\u00e1 sendo promovido pelo Gran Cursos Online, nesta segunda-feira (2\/12). A [&hellip;]<\/p>\n","protected":false},"author":32,"featured_media":10234,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[282],"tags":[867,1154,1155],"class_list":["post-10227","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-concursos","tag-cursinho","tag-evento-gratuito","tag-james-bauer"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/10227","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/comments?post=10227"}],"version-history":[{"count":6,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/10227\/revisions"}],"predecessor-version":[{"id":10235,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/10227\/revisions\/10235"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/media\/10234"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/media?parent=10227"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/categories?post=10227"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/tags?post=10227"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}