{"id":894,"count":1,"description":"","link":"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/tag\/jakeline-daia\/","name":"Jakeline Daia","slug":"jakeline-daia","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-json\/wp\/v2\/tags\/894","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-json\/wp\/v2\/posts?tags=894"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}