{"id":9789,"date":"2025-08-08T10:54:08","date_gmt":"2025-08-08T13:54:08","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/?p=9789"},"modified":"2025-08-08T11:01:57","modified_gmt":"2025-08-08T14:01:57","slug":"embaixada-do-peru-abre-as-portas-sabado-para-festival-de-comida-musica-danca-e-artesanato","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/embaixada-do-peru-abre-as-portas-sabado-para-festival-de-comida-musica-danca-e-artesanato\/","title":{"rendered":"Embaixada do Peru abre as portas s\u00e1bado para festival de comida, m\u00fasica, dan\u00e7a e artesanato"},"content":{"rendered":"<p><!--StartFragment --><\/p>\n<p><span class=\"cf0\"> <!--StartFragment --><\/span><\/p>\n<p><em>A tradi\u00e7\u00e3o completa 10 anos em Bras\u00edlia sob o comando do chef peruano Mar<\/em>co Espinoza<\/p>\n<figure id=\"attachment_9792\" aria-describedby=\"caption-attachment-9792\" style=\"width: 225px\" class=\"wp-caption alignright\"><a href=\"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2025\/08\/WhatsApp-Image-2025-08-08-at-07.59.27.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-9792 size-medium\" src=\"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2025\/08\/WhatsApp-Image-2025-08-08-at-07.59.27-225x300.jpeg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2025\/08\/WhatsApp-Image-2025-08-08-at-07.59.27-225x300.jpeg 225w, https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2025\/08\/WhatsApp-Image-2025-08-08-at-07.59.27.jpeg 768w, https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2025\/08\/WhatsApp-Image-2025-08-08-at-07.59.27-800x1067.jpeg 800w, https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2025\/08\/WhatsApp-Image-2025-08-08-at-07.59.27-550x734.jpeg 550w, https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2025\/08\/WhatsApp-Image-2025-08-08-at-07.59.27-230x307.jpeg 230w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a><figcaption id=\"caption-attachment-9792\" class=\"wp-caption-text\">Embaixador do Peru, R\u00f3mulo Acurio, e o chef peruano Marco Espinoza na apresenta\u00e7\u00e3o do Festival Peruano 2025. Cr\u00e9dito: Festival Peruano\/Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n<p>Com ingredientes vindos do mar do Pac\u00edfico, das montanhas andinas e da selva amaz\u00f4nica, o Peru apresenta uma das culin\u00e1rias mais fant\u00e1sticas do mundo, que se desenvolve com forte apelo cultural dado pela m\u00fasica e dan\u00e7a t\u00edpicas do pa\u00eds vizinho. Tudo isso ser\u00e1 oferecido ao brasiliense neste s\u00e1bado, 10 de agosto, na Embaixada do Peru, situada na Avenida das Na\u00e7\u00f5es, Quadra 811.<\/p>\n<p><span class=\"cf0\"> Durante todo o dia, das 10h \u00e0s 18h, gastronomia e apresenta\u00e7\u00f5es culturais, al\u00e9m de workshops ensinando o preparo do ceviche e do pisco <\/span><span class=\"cf0\">sour<\/span><span class=\"cf0\"> est\u00e3o programados. Os visitantes tamb\u00e9m poder\u00e3o adquirir artesanato e roupas t\u00edpicas, al\u00e9m de produtos como <\/span><span class=\"cf0\">Inka<\/span><span class=\"cf0\"> Cola e doces no bazar, que \u00e9 outra atra\u00e7\u00e3o do festival peruano.<\/span><\/p>\n<p><strong><span class=\"cf0\">Ceviche, pisco e tempero<\/span><\/strong><\/p>\n<p><span class=\"cf0\"> \u00c0 frente dos sabores estar\u00e1 o renomado chef peruano Marco Espinoza, respons\u00e1vel pela curadoria do evento, desde a primeira edi\u00e7\u00e3o, dez anos atr\u00e1s. Ele, que tem restaurantes no Rio de Janeiro e S\u00e3o Paulo, em Bras\u00edlia responde pelo <\/span><span class=\"cf0\">Tayp\u00e1<\/span><span class=\"cf0\">, <\/span><span class=\"cf0\">Cant\u00f3n<\/span><span class=\"cf0\">, Chaco e <\/span><span class=\"cf0\">Kinjo<\/span><span class=\"cf0\"> Nikkei. <\/span><\/p>\n<p><span class=\"cf0\"> Na \u00e1rea de <\/span><span class=\"cf0\">cevicheria<\/span><span class=\"cf0\">, voc\u00ea poder\u00e1 degustar o prato \u00edcone da gastronomia peruana feito de salm\u00e3o com guacamole (R$ 35), arroz de frutos do mar, polvo, lula e camar\u00e3o (R$ 45), vegano s\u00f3 com vegetais (R$ 35) e at\u00e9 de frango com abacate (R$ 30).<\/span><\/p>\n<p><span class=\"cf0\"> Outra atra\u00e7\u00e3o s\u00e3o os pratos na brasa, como <\/span><span class=\"cf0\">anticucho<\/span><span class=\"cf0\">, espeto de <\/span><span class=\"cf0\">fil\u00e9-mignon<\/span><span class=\"cf0\"> com batata e molho de <\/span><span class=\"cf0\">guacatay<\/span><span class=\"cf0\"> (R$ 25), costela com arroz a jardineira de vegetais (R$ 35) e galeto com batata frita e salada (R$ 35). J\u00e1 a cozinha <\/span><span class=\"cf0\">criolla<\/span><span class=\"cf0\"> peruana se apresenta com o cl\u00e1ssico <\/span><span class=\"cf0\">aji<\/span><span class=\"cf0\"> de galinha com arroz e batata cozida (R$ 40), <\/span><span class=\"cf0\">lomo<\/span><span class=\"cf0\"> saltado de <\/span><span class=\"cf0\">fil\u00e9-mignon<\/span><span class=\"cf0\"> com batata frita e arroz branco (R$ 45) e papa <\/span><span class=\"cf0\">rellena<\/span><span class=\"cf0\">, que s\u00e3o as batatas recheadas de carne e salada de cebola com molho <\/span><span class=\"cf0\">rocoto<\/span><span class=\"cf0\"> (R$ 30).<\/span><\/p>\n<figure id=\"attachment_9793\" aria-describedby=\"caption-attachment-9793\" style=\"width: 240px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2025\/08\/WhatsApp-Image-2025-08-08-at-08.19.02.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-9793 size-medium\" src=\"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2025\/08\/WhatsApp-Image-2025-08-08-at-08.19.02-240x300.jpeg\" alt=\"\" width=\"240\" height=\"300\" srcset=\"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2025\/08\/WhatsApp-Image-2025-08-08-at-08.19.02-240x300.jpeg 240w, https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2025\/08\/WhatsApp-Image-2025-08-08-at-08.19.02-768x960.jpeg 768w, https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2025\/08\/WhatsApp-Image-2025-08-08-at-08.19.02.jpeg 800w, https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2025\/08\/WhatsApp-Image-2025-08-08-at-08.19.02-550x688.jpeg 550w, https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2025\/08\/WhatsApp-Image-2025-08-08-at-08.19.02-230x288.jpeg 230w\" sizes=\"auto, (max-width: 240px) 100vw, 240px\" \/><\/a><figcaption id=\"caption-attachment-9793\" class=\"wp-caption-text\">Cr\u00e9dito: Festival Peruano\/Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n<p><span class=\"cf0\"> A influ\u00eancia japonesa no Peru que rendeu com a culin\u00e1ria local um mix chamado Nikkei se evidencia no preparo de yakisoba de carne, macarr\u00e3o japon\u00eas, vegetais e molho (R$ 40), <\/span><span class=\"cf0\">yakimeshi<\/span><span class=\"cf0\"> com cogumelos (R$ 40), al\u00e9m de hamburguer com <\/span><span class=\"cf0\">blend<\/span><span class=\"cf0\"> de carnes, cheddar com pimenta <\/span><span class=\"cf0\">sriracha<\/span><span class=\"cf0\">, alface, maionese de gengibre e batata frita (R$ 35).<\/span><\/p>\n<p><span class=\"cf0\"> Na mesa de doces n\u00e3o faltar\u00e3o o ic\u00f4nico suspiro limenho, nem churros com molho de chocolate branco e pistache por R$ 20, cada. Al\u00e9m da cerveja peruana, <\/span><span class=\"cf0\">Cusque\u00f1a<\/span><span class=\"cf0\">, haver\u00e1 drinques feitos de pisco, o destilado peruano por excel\u00eancia com mais de 400 anos de hist\u00f3ria. O bartender e sommelier Paul <\/span><span class=\"cf0\">Berrospi<\/span><span class=\"cf0\"> ensinar\u00e1 o preparo das receitas durante workshop.<\/span><\/p>\n<p><strong><span class=\"cf0\">Aula de <\/span><span class=\"cf0\">caj\u00f3n<\/span><\/strong><\/p>\n<p><span class=\"cf0\"> A programa\u00e7\u00e3o cultural conta com as apresenta\u00e7\u00f5es da Banda T\u00edpica Peruana, um sexteto instrumental dirigido pelo m\u00fasico Alex Carrasco, que apresentar\u00e1 os ritmos folcl\u00f3ricos das diversas regi\u00f5es do Peru, com destaque para o <\/span><span class=\"cf0\">caj\u00f3n<\/span><span class=\"cf0\">, instrumento secular de percuss\u00e3o que teve origem na \u00e9poca colonial e era tocado pelos escravos. Desde 2001, <\/span><span class=\"cf0\">caj\u00f3n<\/span><span class=\"cf0\"> se tornou patrim\u00f4nio cultural da m\u00fasica peruana. Est\u00e1 previsto workshop de <\/span><span class=\"cf0\">caj\u00f3n<\/span><span class=\"cf0\">, a cargo do m\u00fasico peruano Carrasco.<\/span><\/p>\n<p><span class=\"cf0\"> Diretamente de S\u00e3o Paulo, o grupo de dan\u00e7a folcl\u00f3rica <\/span><span class=\"cf0\">Ra\u00edces<\/span> <span class=\"cf0\">Norte\u00f1as<\/span><span class=\"cf0\"> apresentar\u00e1 dan\u00e7as tradicionais como a <\/span><span class=\"cf0\">Marinera<\/span> <span class=\"cf0\">Norte\u00f1a<\/span><span class=\"cf0\"> y <\/span><span class=\"cf0\">Huayno<\/span><span class=\"cf0\">.<\/span><\/p>\n<p><span class=\"cf0\"> O acesso ao festival se dar\u00e1 pela entrada social da embaixada, mediante a entrega de 1 quilo de alimento n\u00e3o perec\u00edvel que ser\u00e1 doado aos projetos sociais apoiados pelo Governo do Distrito Federal. Instagram: <a href=\"https:\/\/www.instagram.com\/festivalperuanobsb\">@festivalperuanobsb<\/a>.<\/span><\/p>\n<p><!--EndFragment --><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A tradi\u00e7\u00e3o completa 10 anos em Bras\u00edlia sob o comando do chef peruano Marco Espinoza<\/p>\n","protected":false},"author":54,"featured_media":9791,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[201],"tags":[565,1338,169],"class_list":["post-9789","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-festival","tag-embaixada-do-peru","tag-festival-peruano","tag-marco-espinoza"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-json\/wp\/v2\/posts\/9789","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-json\/wp\/v2\/users\/54"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-json\/wp\/v2\/comments?post=9789"}],"version-history":[{"count":4,"href":"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-json\/wp\/v2\/posts\/9789\/revisions"}],"predecessor-version":[{"id":9796,"href":"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-json\/wp\/v2\/posts\/9789\/revisions\/9796"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-json\/wp\/v2\/media\/9791"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-json\/wp\/v2\/media?parent=9789"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-json\/wp\/v2\/categories?post=9789"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-json\/wp\/v2\/tags?post=9789"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}