{"id":9435,"date":"2025-05-01T10:17:41","date_gmt":"2025-05-01T13:17:41","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/?p=9435"},"modified":"2025-05-01T10:21:13","modified_gmt":"2025-05-01T13:21:13","slug":"chef-francisco-ansiliero-e-homenageado-em-jantar-memoravel-no-quintal-do-fogo-na-chapada","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/chef-francisco-ansiliero-e-homenageado-em-jantar-memoravel-no-quintal-do-fogo-na-chapada\/","title":{"rendered":"Chef Francisco Ansiliero \u00e9 homenageado em jantar memor\u00e1vel no Quintal do Fogo na Chapada"},"content":{"rendered":"<figure id=\"attachment_9444\" aria-describedby=\"caption-attachment-9444\" style=\"width: 225px\" class=\"wp-caption alignright\"><a href=\"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2025\/05\/1000649767.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-9444 size-medium\" src=\"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2025\/05\/1000649767-225x300.jpg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2025\/05\/1000649767-225x300.jpg 225w, https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2025\/05\/1000649767.jpg 768w, https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2025\/05\/1000649767-800x1067.jpg 800w, https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2025\/05\/1000649767-550x733.jpg 550w, https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2025\/05\/1000649767-230x307.jpg 230w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a><figcaption id=\"caption-attachment-9444\" class=\"wp-caption-text\">Cr\u00e9dito: Arquivo pessoal<\/figcaption><\/figure>\n<p>O fogo, a mata, o sabor \u2013 tudo isso reunido ao cair da noite constituiu o cen\u00e1rio ideal para homenagear o principal nome da gastronomia de Bras\u00edlia, Francisco Ansiliero, durante memor\u00e1vel jantar com ingredientes t\u00edpicos do cerrado, servido em cinco etapas desenvolvidas por meia d\u00fazia de renomados chefs, que praticam a culin\u00e1ria regional, entre eles, o pr\u00f3prio homenageado.<\/p>\n<p>A ideia partiu da chef Mara Alcamim, que trocou a vida urbana da capital pelo ro\u00e7ado na Chapada dos Veadeiros, onde recebeu em seu restaurante Na Mata, dois quil\u00f4metros do centro da Vila de S\u00e3o Jorge, uma centena de pessoas para degustar card\u00e1pio de alta gastronomia executado no ch\u00e3o de terra.<\/p>\n<p><strong>Pratos ex\u00f3ticos<\/strong><\/p>\n<p>Coube ao chef Gil Guimar\u00e3es, parceiro de Mara e Francisco nas apresenta\u00e7\u00f5es da comida do cerrado inclusive em S\u00e3o Paulo, interpretar a primeira entrada fria e saborosa feita com tartar de pirarucu acompanhada de cajuzinho do cerrado. O segundo prato trouxe \u00e0 mesa l\u00edngua bovina defumada com tostas de ciabatta e molho reduzido nos temperos de n\u00e3o se perder uma gota sequer. Foi obra do chef Mois\u00e9s Costa, que toca o Primitivo Churrasco, especializado em cortes especiais e gastronomia na brasa, instalado na 303 Sul.<\/p>\n<div id='gallery-1' class='gallery galleryid-9435 gallery-columns-3 gallery-size-full'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/chef-francisco-ansiliero-e-homenageado-em-jantar-memoravel-no-quintal-do-fogo-na-chapada\/attachment\/1000649787\/'><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2025\/05\/1000649787.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2025\/05\/1000649787.jpg 800w, https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2025\/05\/1000649787-300x225.jpg 300w, https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2025\/05\/1000649787-768x576.jpg 768w, https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2025\/05\/1000649787-550x413.jpg 550w, https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2025\/05\/1000649787-230x173.jpg 230w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/chef-francisco-ansiliero-e-homenageado-em-jantar-memoravel-no-quintal-do-fogo-na-chapada\/attachment\/1000649793\/'><img loading=\"lazy\" decoding=\"async\" width=\"1067\" height=\"800\" src=\"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2025\/05\/1000649793.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2025\/05\/1000649793.jpg 1067w, https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2025\/05\/1000649793-300x225.jpg 300w, https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2025\/05\/1000649793-768x576.jpg 768w, https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2025\/05\/1000649793-1024x768.jpg 1024w, https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2025\/05\/1000649793-800x600.jpg 800w, https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2025\/05\/1000649793-550x412.jpg 550w, https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2025\/05\/1000649793-230x172.jpg 230w\" sizes=\"auto, (max-width: 1067px) 100vw, 1067px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/chef-francisco-ansiliero-e-homenageado-em-jantar-memoravel-no-quintal-do-fogo-na-chapada\/attachment\/1000649796\/'><img loading=\"lazy\" decoding=\"async\" width=\"1067\" height=\"800\" src=\"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2025\/05\/1000649796.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2025\/05\/1000649796.jpg 1067w, https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2025\/05\/1000649796-300x225.jpg 300w, https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2025\/05\/1000649796-768x576.jpg 768w, https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2025\/05\/1000649796-1024x768.jpg 1024w, https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2025\/05\/1000649796-800x600.jpg 800w, https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2025\/05\/1000649796-550x412.jpg 550w, https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2025\/05\/1000649796-230x172.jpg 230w\" sizes=\"auto, (max-width: 1067px) 100vw, 1067px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/chef-francisco-ansiliero-e-homenageado-em-jantar-memoravel-no-quintal-do-fogo-na-chapada\/attachment\/1000649802\/'><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"508\" src=\"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2025\/05\/1000649802.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2025\/05\/1000649802.jpg 600w, https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2025\/05\/1000649802-300x254.jpg 300w, https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2025\/05\/1000649802-550x466.jpg 550w, https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2025\/05\/1000649802-230x195.jpg 230w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p>Um disc\u00edpulo da chef Mara Alcamim, Black D\u00eanis, comanda a cozinha do Na Mata. \u201cEla me pegou aos 18 anos e me ensinou tudo\u201d, revelou o autor do terceiro prato, um cupim assado na brasa com xib\u00e9u de baba\u00e7u e maxixe. Tamb\u00e9m na cozinha, outro pupilo de Mara estava presente: Rog\u00e9rio Evangelista, chef do Universal, que leva adiante a proposta gastron\u00f4mica aprovada pelos brasilienses.<\/p>\n<figure id=\"attachment_9437\" aria-describedby=\"caption-attachment-9437\" style=\"width: 800px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2025\/05\/1000649770-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-9437\" src=\"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2025\/05\/1000649770-1.jpg\" alt=\"\" width=\"800\" height=\"600\" srcset=\"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2025\/05\/1000649770-1.jpg 800w, https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2025\/05\/1000649770-1-300x225.jpg 300w, https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2025\/05\/1000649770-1-768x576.jpg 768w, https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2025\/05\/1000649770-1-550x413.jpg 550w, https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2025\/05\/1000649770-1-230x173.jpg 230w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><figcaption id=\"caption-attachment-9437\" class=\"wp-caption-text\">Cr\u00e9dito: Arquivo pessoal<\/figcaption><\/figure>\n<p>Pausa para assistir ao vivo no meio do gramado bem iluminado a atua\u00e7\u00e3o das estrelas da noite: a dona da casa explicando a ancestral t\u00e9cnica de cozimento que consiste em colocar os alimentos sobre brasas obtidas depois de duas horas de lenha queimando no fogo em buraco aberto na terra. Chama-se curanto. Com esse procedimento Mara Alcamim preparou legumes envoltos em tecido que cozinharam como se estivessem dentro de uma panela de press\u00e3o, at\u00e9 o vapor sai do buraco coberto de terra e tapado com pedras.<\/p>\n<figure id=\"attachment_9442\" aria-describedby=\"caption-attachment-9442\" style=\"width: 225px\" class=\"wp-caption alignright\"><a href=\"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2025\/05\/1000649761.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-9442 size-medium\" src=\"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2025\/05\/1000649761-225x300.jpg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2025\/05\/1000649761-225x300.jpg 225w, https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2025\/05\/1000649761.jpg 768w, https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2025\/05\/1000649761-800x1067.jpg 800w, https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2025\/05\/1000649761-550x733.jpg 550w, https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2025\/05\/1000649761-230x307.jpg 230w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a><figcaption id=\"caption-attachment-9442\" class=\"wp-caption-text\">Cr\u00e9dito: Arquivo pessoal<\/figcaption><\/figure>\n<p>Enquanto isso, Francisco acompanhava o ponto de cozimento das tr\u00eas leitoas preparadas por ele, sob os cuidados e supervis\u00e3o do bi\u00f3logo Marco Ant\u00f4nio Veronese, \u201cmeu escudeiro\u201d, como a ele se refere Francisco. Os dois s\u00e3o amigos de longa data e sempre cozinham juntos nos eventos realizados at\u00e9 no exterior. Na d\u00e9cada de 1990, Ansiliero e Veronese assumiram o restaurante brasileiro que funcionou no Salon del Gusto, do evento Terra Madre, durante conven\u00e7\u00e3o anual do Slow Food, realizada em Turim, nas instala\u00e7\u00f5es antigas da f\u00e1brica Fiat.<\/p>\n<p>O \u201cescudeiro\u201d mostrou destreza no trato da carne su\u00edna assada ao cortar as leitoas com um prato. Para acompanhar a iguaria, o arroz do cerrado, produzido pelos Kalunga, de Cavalcante (GO). Acrescentei polpa de buriti, \u00f3leo de buriti, cajuzinho do cerrado, cagaita e nosso aben\u00e7oado pequi\u201d, informou o chef do Dom Francisco.<\/p>\n<figure id=\"attachment_9443\" aria-describedby=\"caption-attachment-9443\" style=\"width: 225px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2025\/05\/1000649755.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-9443 size-medium\" src=\"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2025\/05\/1000649755-225x300.jpg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2025\/05\/1000649755-225x300.jpg 225w, https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2025\/05\/1000649755.jpg 768w, https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2025\/05\/1000649755-800x1067.jpg 800w, https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2025\/05\/1000649755-550x733.jpg 550w, https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2025\/05\/1000649755-230x307.jpg 230w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a><figcaption id=\"caption-attachment-9443\" class=\"wp-caption-text\">Cr\u00e9dito: Arquivo pessoal<\/figcaption><\/figure>\n<p>Para coroar o surpreendente menu, a chef Mara Alcamim preparou de sobremesa, Rolo da terra, na plancha, com doce de leite caseiro e pa\u00e7oca de baru. Como trilha sonora da experi\u00eancia, o DJ Thiago Roots, residente da Chapada, apresentou uma sele\u00e7\u00e3o musical que inundou o ambiente com aut\u00eantica brasilidade.<\/p>\n<p><strong>Ao mestre com carinho<\/strong><\/p>\n<p>O evento na Chapada dos Veadeiros simbolizou o reconhecimento da categoria pelo muito que aprendeu com Francisco, um descendente de Italianos, nascido em Santa Catarina, com passagem pela Amaz\u00f4nia e radicado no Planalto Central, desde 1980. Com essas influ\u00eancias o chef, que \u00e9 um estudioso da gastronomia, conseguiu resgatar joias do bioma do cerrado, como pequi, cagaita, buriti para dar-lhes lugar de direito na cozinha de seus restaurantes, da\u00ed ser tratado como mestre. Franco e direto no trato, mas carinhoso, ele costuma lembrar uma frase que ouviu do amigo e colega franc\u00eas Laurent Suaudeau: \u201cQuem n\u00e3o ensina o que aprendeu e descobriu na vida \u00e9 um covarde, n\u00e3o merece viver\u201d.<\/p>\n<p>O evento contou com o apoio das marcas Del Maipo Wines, Corona, 3 Cora\u00e7\u00f5es e YVY Destilaria, que tornaram a experi\u00eancia mais completa e memor\u00e1vel para todos os presentes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O fogo, a mata, o sabor \u2013 tudo isso reunido ao cair da noite constituiu o cen\u00e1rio ideal para homenagear o principal nome da gastronomia de Bras\u00edlia, Francisco Ansiliero, durante memor\u00e1vel jantar com ingredientes t\u00edpicos do cerrado, servido em cinco etapas desenvolvidas por meia d\u00fazia de renomados chefs, que praticam a culin\u00e1ria regional, entre eles, o pr\u00f3prio homenageado. A ideia [&hellip;]<\/p>\n","protected":false},"author":54,"featured_media":9436,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[73],"tags":[1189,1285],"class_list":["post-9435","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-materia","tag-na-mata","tag-quintal-do-fogo"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-json\/wp\/v2\/posts\/9435","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-json\/wp\/v2\/users\/54"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-json\/wp\/v2\/comments?post=9435"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-json\/wp\/v2\/posts\/9435\/revisions"}],"predecessor-version":[{"id":9445,"href":"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-json\/wp\/v2\/posts\/9435\/revisions\/9445"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-json\/wp\/v2\/media\/9436"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-json\/wp\/v2\/media?parent=9435"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-json\/wp\/v2\/categories?post=9435"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-json\/wp\/v2\/tags?post=9435"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}