{"id":8739,"date":"2024-09-06T06:03:18","date_gmt":"2024-09-06T09:03:18","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/?p=8739"},"modified":"2024-09-06T00:17:57","modified_gmt":"2024-09-06T03:17:57","slug":"influencias-da-cozinha-oriental-se-juntam-no-nk-sushi-no-lago-sul","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/influencias-da-cozinha-oriental-se-juntam-no-nk-sushi-no-lago-sul\/","title":{"rendered":"Influ\u00eancias da cozinha oriental se juntam no NK Sushi, no Lago Sul"},"content":{"rendered":"<p>Quando desembarcou em Bras\u00edlia na d\u00e9cada de 1970 para assumir as ca\u00e7arolas da embaixada do Jap\u00e3o, o chef Ryozo Komiya, nascido em T\u00f3quio que, depois teve seu pr\u00f3prio restaurante, n\u00e3o encontrou concorr\u00eancia. Pelo contr\u00e1rio, estava praticamente sozinho porque comida japonesa n\u00e3o fazia sucesso. Ainda assim, Komiya San, como era conhecido o chef desbravador, vaticinou: \u201cesta ser\u00e1 a culin\u00e1ria do futuro\u201d, lembra o filho Cristiano, chef do New Koto, herdeiro da mais pura linhagem nip\u00f4nica.<\/p>\n<p>Quatro d\u00e9cadas mais tarde, a previs\u00e3o se confirma: n\u00e3o se passa um m\u00eas sem que a cidade receba uma opera\u00e7\u00e3o da gastronomia japonesa. Al\u00e9m da tradi\u00e7\u00e3o da cozinha nip\u00f4nica outras influ\u00eancias orientais est\u00e3o presentes \u2013 chinesa, tailandesa e coreana &#8211; , como no mais recente lan\u00e7amento, que atende pela sigla NK Sushi, de Nanko como era o nome do japinha que existia no Gilberto Salom\u00e3o.<\/p>\n<figure id=\"attachment_8741\" aria-describedby=\"caption-attachment-8741\" style=\"width: 800px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2024\/09\/WhatsApp-Image-2024-09-05-at-13.28.01.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-8741\" src=\"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2024\/09\/WhatsApp-Image-2024-09-05-at-13.28.01.jpeg\" alt=\"\" width=\"800\" height=\"578\" srcset=\"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2024\/09\/WhatsApp-Image-2024-09-05-at-13.28.01.jpeg 800w, https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2024\/09\/WhatsApp-Image-2024-09-05-at-13.28.01-300x217.jpeg 300w, https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2024\/09\/WhatsApp-Image-2024-09-05-at-13.28.01-768x555.jpeg 768w, https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2024\/09\/WhatsApp-Image-2024-09-05-at-13.28.01-550x397.jpeg 550w, https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2024\/09\/WhatsApp-Image-2024-09-05-at-13.28.01-230x166.jpeg 230w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><figcaption id=\"caption-attachment-8741\" class=\"wp-caption-text\">Sandra Yu, o marido chef Paulo Yu, o chef William Chen e o empres\u00e1rio Kiko Pimenta. Cr\u00e9dito: Liana Sabo\/CB\/D.A Press<\/figcaption><\/figure>\n<p>Ao reestruturar a casa com mais vigor, no andar de baixo do bloco C da QI 7, Lago Sul, o empres\u00e1rio Kiko Pimenta entregou a confec\u00e7\u00e3o dos sabores a dois craques de origem chinesa: William Chen, chef executivo, respons\u00e1vel pelos pratos quentes e Paulo Yu, que prepara o card\u00e1pio frio, e cuja mulher Sandra Tanabe \u00e9 s\u00f3cia da casa. Antes de al\u00e7ar voos at\u00e9 no exterior, Chen foi fundador do Babel ainda enquanto a m\u00e3e, Dona Fen, tocava o Taiwan, na 413 Sul, que virou o emp\u00f3rio La Palma. Paulo formado na Unieuro trabalhou no Naoum, Ichiban, Grande Muralha e abriu o Ayumi na 103 Sul. Os dois t\u00eam hist\u00f3ria comum: s\u00e3o filhos de emigrantes vindos de Taiwan, a China insular.<\/p>\n<p><strong>Receita do av\u00f4<\/strong><\/p>\n<div id='gallery-1' class='gallery galleryid-8739 gallery-columns-3 gallery-size-full'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/influencias-da-cozinha-oriental-se-juntam-no-nk-sushi-no-lago-sul\/whatsapp-image-2024-09-05-at-13-29-08-2\/'><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"1067\" src=\"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2024\/09\/WhatsApp-Image-2024-09-05-at-13.29.08-2.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2024\/09\/WhatsApp-Image-2024-09-05-at-13.29.08-2.jpeg 800w, https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2024\/09\/WhatsApp-Image-2024-09-05-at-13.29.08-2-225x300.jpeg 225w, https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2024\/09\/WhatsApp-Image-2024-09-05-at-13.29.08-2-768x1024.jpeg 768w, https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2024\/09\/WhatsApp-Image-2024-09-05-at-13.29.08-2-550x734.jpeg 550w, https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2024\/09\/WhatsApp-Image-2024-09-05-at-13.29.08-2-230x307.jpeg 230w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/influencias-da-cozinha-oriental-se-juntam-no-nk-sushi-no-lago-sul\/whatsapp-image-2024-09-05-at-13-29-07-1\/'><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"1067\" src=\"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2024\/09\/WhatsApp-Image-2024-09-05-at-13.29.07-1.jpeg\" class=\"attachment-full size-full\" alt=\"\" aria-describedby=\"gallery-1-8744\" srcset=\"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2024\/09\/WhatsApp-Image-2024-09-05-at-13.29.07-1.jpeg 800w, https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2024\/09\/WhatsApp-Image-2024-09-05-at-13.29.07-1-225x300.jpeg 225w, https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2024\/09\/WhatsApp-Image-2024-09-05-at-13.29.07-1-768x1024.jpeg 768w, https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2024\/09\/WhatsApp-Image-2024-09-05-at-13.29.07-1-550x734.jpeg 550w, https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2024\/09\/WhatsApp-Image-2024-09-05-at-13.29.07-1-230x307.jpeg 230w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-8744'>\n\t\t\t\tCr\u00e9dito: Liana Sabo\/CB\/D.A Press\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/influencias-da-cozinha-oriental-se-juntam-no-nk-sushi-no-lago-sul\/whatsapp-image-2024-09-05-at-13-29-06\/'><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"1067\" src=\"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2024\/09\/WhatsApp-Image-2024-09-05-at-13.29.06.jpeg\" class=\"attachment-full size-full\" alt=\"\" aria-describedby=\"gallery-1-8743\" srcset=\"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2024\/09\/WhatsApp-Image-2024-09-05-at-13.29.06.jpeg 800w, https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2024\/09\/WhatsApp-Image-2024-09-05-at-13.29.06-225x300.jpeg 225w, https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2024\/09\/WhatsApp-Image-2024-09-05-at-13.29.06-768x1024.jpeg 768w, https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2024\/09\/WhatsApp-Image-2024-09-05-at-13.29.06-550x734.jpeg 550w, https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2024\/09\/WhatsApp-Image-2024-09-05-at-13.29.06-230x307.jpeg 230w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-8743'>\n\t\t\t\tCr\u00e9dito: Liana Sabo\/CB\/D.A Press\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/influencias-da-cozinha-oriental-se-juntam-no-nk-sushi-no-lago-sul\/whatsapp-image-2024-09-05-at-13-29-07-2\/'><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"1067\" src=\"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2024\/09\/WhatsApp-Image-2024-09-05-at-13.29.07-2.jpeg\" class=\"attachment-full size-full\" alt=\"\" aria-describedby=\"gallery-1-8745\" srcset=\"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2024\/09\/WhatsApp-Image-2024-09-05-at-13.29.07-2.jpeg 800w, https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2024\/09\/WhatsApp-Image-2024-09-05-at-13.29.07-2-225x300.jpeg 225w, https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2024\/09\/WhatsApp-Image-2024-09-05-at-13.29.07-2-768x1024.jpeg 768w, https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2024\/09\/WhatsApp-Image-2024-09-05-at-13.29.07-2-550x734.jpeg 550w, https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2024\/09\/WhatsApp-Image-2024-09-05-at-13.29.07-2-230x307.jpeg 230w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-8745'>\n\t\t\t\tCr\u00e9dito: Liana Sabo\/CB\/D.A Press\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/influencias-da-cozinha-oriental-se-juntam-no-nk-sushi-no-lago-sul\/whatsapp-image-2024-09-05-at-13-29-07\/'><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"1067\" src=\"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2024\/09\/WhatsApp-Image-2024-09-05-at-13.29.07.jpeg\" class=\"attachment-full size-full\" alt=\"\" aria-describedby=\"gallery-1-8747\" srcset=\"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2024\/09\/WhatsApp-Image-2024-09-05-at-13.29.07.jpeg 800w, https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2024\/09\/WhatsApp-Image-2024-09-05-at-13.29.07-225x300.jpeg 225w, https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2024\/09\/WhatsApp-Image-2024-09-05-at-13.29.07-768x1024.jpeg 768w, https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2024\/09\/WhatsApp-Image-2024-09-05-at-13.29.07-550x734.jpeg 550w, https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2024\/09\/WhatsApp-Image-2024-09-05-at-13.29.07-230x307.jpeg 230w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-8747'>\n\t\t\t\tCr\u00e9dito: Liana Sabo\/CB\/D.A Press\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/influencias-da-cozinha-oriental-se-juntam-no-nk-sushi-no-lago-sul\/whatsapp-image-2024-09-05-at-13-29-07-3\/'><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2024\/09\/WhatsApp-Image-2024-09-05-at-13.29.07-3.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2024\/09\/WhatsApp-Image-2024-09-05-at-13.29.07-3.jpeg 800w, https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2024\/09\/WhatsApp-Image-2024-09-05-at-13.29.07-3-300x225.jpeg 300w, https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2024\/09\/WhatsApp-Image-2024-09-05-at-13.29.07-3-768x576.jpeg 768w, https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2024\/09\/WhatsApp-Image-2024-09-05-at-13.29.07-3-550x413.jpeg 550w, https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2024\/09\/WhatsApp-Image-2024-09-05-at-13.29.07-3-230x173.jpeg 230w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/influencias-da-cozinha-oriental-se-juntam-no-nk-sushi-no-lago-sul\/whatsapp-image-2024-09-05-at-13-29-06-1\/'><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"1280\" src=\"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2024\/09\/WhatsApp-Image-2024-09-05-at-13.29.06-1.jpeg\" class=\"attachment-full size-full\" alt=\"\" aria-describedby=\"gallery-1-8742\" srcset=\"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2024\/09\/WhatsApp-Image-2024-09-05-at-13.29.06-1.jpeg 960w, https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2024\/09\/WhatsApp-Image-2024-09-05-at-13.29.06-1-225x300.jpeg 225w, https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2024\/09\/WhatsApp-Image-2024-09-05-at-13.29.06-1-768x1024.jpeg 768w, https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2024\/09\/WhatsApp-Image-2024-09-05-at-13.29.06-1-800x1067.jpeg 800w, https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2024\/09\/WhatsApp-Image-2024-09-05-at-13.29.06-1-550x733.jpeg 550w, https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-content\/uploads\/sites\/25\/2024\/09\/WhatsApp-Image-2024-09-05-at-13.29.06-1-230x307.jpeg 230w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-8742'>\n\t\t\t\tCr\u00e9dito: Liana Sabo\/CB\/D.A Press\n\t\t\t\t<\/figcaption><\/figure>\n\t\t<\/div>\n\n<p>Voc\u00ea pode come\u00e7ar a degusta\u00e7\u00e3o com um incr\u00edvel tempur\u00e1 de manjeric\u00e3o crocante que William aprendeu com o av\u00f4 materno. \u201cN\u00e3o conhe\u00e7o nenhuma gastronomia que tenha o manjeric\u00e3o como \u00fanico ingrediente do prato\u201d, observou o chef que serve a raridade com molho ponzu. Outra entrada se chama General Tso que \u00e9 frango empanado com um molho agridoce escuro. Ainda da cozinha quente vem o arroz de sushi prensado e frito, coberto com tartar de salm\u00e3o, cebola roxa, ovas massago e teriyaki, enquanto as estrelas do menu japon\u00eas que vem da \u00e1gua \u2013 peixe branco, atum e salm\u00e3o \u2013 em forma de l\u00e2minas formam o Usuzukuri misto, carpaccio no molho ponzu.<\/p>\n<p>O ceviche ganhou uma vers\u00e3o com til\u00e1pia e molho menos \u00e1cido com laranja e lim\u00e3o siciliano e o tataki de salm\u00e3o trufado recendendo o perfume de trufas vem coberto com palha de batata doce. \u00c9 da bancada do chef Paulo Yu que chega \u00e0 mesa sashimi com 20 fatias dos melhores peixes do dia; ovas de peixe voador, salm\u00e3o, bagre e ouri\u00e7o-do-mar e o grand finale que pode ser delicioso combinado de sushi e sashimi s\u00f3 de salm\u00e3o. A harmoniza\u00e7\u00e3o fica perfeita com os brancos da Mistral, que assina a carta de vinhos.<\/p>\n<p>Com capacidade para 110 lugares, NK Sushi exibe belo projeto de Andr\u00e9 Alf. Funciona de segunda a s\u00e1bado, das 18h30 \u00e0s 23h. Almo\u00e7o apenas sexta e s\u00e1bado. Reservas: 99276-5849.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quando desembarcou em Bras\u00edlia na d\u00e9cada de 1970 para assumir as ca\u00e7arolas da embaixada do Jap\u00e3o, o chef Ryozo Komiya, nascido em T\u00f3quio que, depois teve seu pr\u00f3prio restaurante, n\u00e3o encontrou concorr\u00eancia. Pelo contr\u00e1rio, estava praticamente sozinho porque comida japonesa n\u00e3o fazia sucesso. Ainda assim, Komiya San, como era conhecido o chef desbravador, vaticinou: \u201cesta ser\u00e1 a culin\u00e1ria do futuro\u201d, [&hellip;]<\/p>\n","protected":false},"author":54,"featured_media":8740,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[136],"tags":[139,1162,1163,561,1161],"class_list":["post-8739","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-restaurantes-japoneses","tag-comida-japonesa","tag-culinaria-asiatica","tag-gastronomia-oriental","tag-lago-sul","tag-nk-sushi"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-json\/wp\/v2\/posts\/8739","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-json\/wp\/v2\/users\/54"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-json\/wp\/v2\/comments?post=8739"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-json\/wp\/v2\/posts\/8739\/revisions"}],"predecessor-version":[{"id":8749,"href":"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-json\/wp\/v2\/posts\/8739\/revisions\/8749"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-json\/wp\/v2\/media\/8740"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-json\/wp\/v2\/media?parent=8739"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-json\/wp\/v2\/categories?post=8739"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-json\/wp\/v2\/tags?post=8739"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}