{"id":8017,"date":"2024-02-16T06:19:07","date_gmt":"2024-02-16T09:19:07","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/?p=8017"},"modified":"2024-02-15T18:34:15","modified_gmt":"2024-02-15T21:34:15","slug":"restaurante-noru-aposta-em-festivais-e-jantares-especiais","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/restaurante-noru-aposta-em-festivais-e-jantares-especiais\/","title":{"rendered":"Restaurante Noru aposta em festivais e jantares especiais"},"content":{"rendered":"<p><em>O estabelecimento vai incorporar uma nova programa\u00e7\u00e3o no primeiro semestre<br \/>\n<\/em><\/p>\n<p>O ano de 2024 promete na cozinha japonesa do Noru Sushi Lounge. Filipe Pataro, Marcos Souza e Bruna Moth\u00e9, s\u00f3cios do restaurante localizado no Noroeste, anunciaram que o primeiro semestre ser\u00e1 marcado por algumas novidades.<\/p>\n<p>Entre elas est\u00e1 o Festival de Sushis e Sashimis com peixes amaz\u00f4nicos. A ideia \u00e9 apresentar sabores diferentes para o p\u00fablico ao apostar em iguarias de \u00e1gua doce. A outra novidade \u00e9 o jantar a quatro m\u00e3os, uma iniciativa que reunir\u00e1 chefs renomados. Entre os nomes confirmados est\u00e1 Di Oliveira, do Brasis Ateli\u00ea Gastron\u00f4mico.<\/p>\n<p><a href=\"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/a-nova-cozinha-japonesa-de-brasilia\/\">Lan\u00e7ado em 2022, o Noru nasceu para suprir uma demanda dos moradores do bairro<\/a>. A principal caracter\u00edstica do estabelecimento \u00e9 praticar a nova cozinha japonesa, incorporando sabores originais \u00e0 tradi\u00e7\u00e3o da culin\u00e1ria. No ano passado, o restaurante foi premiado como Melhor Japon\u00eas da cidade pela <em>Revista Encontro<\/em>.<\/p>\n<p>Instalado no Condom\u00ednio Stylo, Quadras 10\/11 Bloco B, lojas 2 e 3, o restaurante funciona de segunda a domingo, das 18h \u00e0s 0h, sendo que sexta, s\u00e1bado e domingo tamb\u00e9m para o almo\u00e7o das 12h \u00e0s 16h. Telefone: 99554-0336. Instagram: <a href=\"https:\/\/www.instagram.com\/norusushi\/\">@norusushi<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O estabelecimento vai incorporar uma nova programa\u00e7\u00e3o no primeiro semestre O ano de 2024 promete na cozinha japonesa do Noru Sushi Lounge. Filipe Pataro, Marcos Souza e Bruna Moth\u00e9, s\u00f3cios do restaurante localizado no Noroeste, anunciaram que o primeiro semestre ser\u00e1 marcado por algumas novidades. Entre elas est\u00e1 o Festival de Sushis e Sashimis com peixes amaz\u00f4nicos. A ideia \u00e9 [&hellip;]<\/p>\n","protected":false},"author":54,"featured_media":6793,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[136],"tags":[1000,994,338],"class_list":["post-8017","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-restaurantes-japoneses","tag-noru-sushi-lounge","tag-novidade","tag-restaurante"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-json\/wp\/v2\/posts\/8017","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-json\/wp\/v2\/users\/54"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-json\/wp\/v2\/comments?post=8017"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-json\/wp\/v2\/posts\/8017\/revisions"}],"predecessor-version":[{"id":8020,"href":"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-json\/wp\/v2\/posts\/8017\/revisions\/8020"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-json\/wp\/v2\/media\/6793"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-json\/wp\/v2\/media?parent=8017"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-json\/wp\/v2\/categories?post=8017"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-json\/wp\/v2\/tags?post=8017"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}