{"id":1285,"date":"2017-05-19T10:30:36","date_gmt":"2017-05-19T13:30:36","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/?p=1285"},"modified":"2017-05-18T16:13:23","modified_gmt":"2017-05-18T19:13:23","slug":"nespresso-tem-novos-sabores-inspirados-em-paises-africanos","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/nespresso-tem-novos-sabores-inspirados-em-paises-africanos\/","title":{"rendered":"Nespresso tem novos sabores inspirados em pa\u00edses africanos"},"content":{"rendered":"<p>A onda de caf\u00e9 em c\u00e1psulas chegou para ficar. A Nespresso, a mais famosa delas, deve abrir m\u00eas que vem a segunda boutique na capital, no ParkShoppping &#8211; a primeira fica no Iguatemi.<\/p>\n<p>O novo espa\u00e7o, de 113m\u00b2, promete uma experi\u00eancia 360\u00ba que permitir\u00e1 a degusta\u00e7\u00e3o de 25 blends fixos e a observa\u00e7\u00e3o dos muitos acess\u00f3rios da marca.<\/p>\n<p>A nova boutique vem com lan\u00e7amentos de linhas exclusivas e limitadas. A Explorations apresenta sabores do Laos e do Qu\u00eania. Laos Bolaven Plateau vem com notas de trigo dourado e fundo herbal fresco com um toque \u00e1cido. J\u00e1 no Kenya Peaberry, o destaque fica por conta da acidez delicada e notas frutadas.<\/p>\n<p>As novidades s\u00e3o vendidas em um duo pack, com 20 c\u00e1psulas, por R$ 120.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A onda de caf\u00e9 em c\u00e1psulas chegou para ficar. A Nespresso, a mais famosa delas, deve abrir m\u00eas que vem a segunda boutique na capital, no ParkShoppping &#8211; a primeira fica no Iguatemi. O novo espa\u00e7o, de 113m\u00b2, promete uma experi\u00eancia 360\u00ba que permitir\u00e1 a degusta\u00e7\u00e3o de 25 blends fixos e a observa\u00e7\u00e3o dos muitos acess\u00f3rios da marca. A nova [&hellip;]<\/p>\n","protected":false},"author":54,"featured_media":1286,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1285","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-json\/wp\/v2\/posts\/1285","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-json\/wp\/v2\/users\/54"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-json\/wp\/v2\/comments?post=1285"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-json\/wp\/v2\/posts\/1285\/revisions"}],"predecessor-version":[{"id":1287,"href":"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-json\/wp\/v2\/posts\/1285\/revisions\/1287"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-json\/wp\/v2\/media\/1286"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-json\/wp\/v2\/media?parent=1285"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-json\/wp\/v2\/categories?post=1285"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/lianasabo\/wp-json\/wp\/v2\/tags?post=1285"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}