{"id":70,"count":1,"description":"","link":"https:\/\/blogs.correiobraziliense.com.br\/jusbraziliense\/tag\/presuncao-de-inocencia\/","name":"presun\u00e7\u00e3o de inoc\u00eancia","slug":"presuncao-de-inocencia","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/jusbraziliense\/wp-json\/wp\/v2\/tags\/70","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/jusbraziliense\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/jusbraziliense\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/jusbraziliense\/wp-json\/wp\/v2\/posts?tags=70"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}