{"id":77,"count":2,"description":"","link":"https:\/\/blogs.correiobraziliense.com.br\/igualdade\/tag\/redes-sociais\/","name":"Redes Sociais","slug":"redes-sociais","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/igualdade\/wp-json\/wp\/v2\/tags\/77","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/igualdade\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/igualdade\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/igualdade\/wp-json\/wp\/v2\/posts?tags=77"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}