{"id":41,"count":6,"description":"","link":"https:\/\/blogs.correiobraziliense.com.br\/igualdade\/tag\/ditadura-militar\/","name":"Ditadura militar","slug":"ditadura-militar","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/igualdade\/wp-json\/wp\/v2\/tags\/41","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/igualdade\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/igualdade\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/igualdade\/wp-json\/wp\/v2\/posts?tags=41"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}