{"id":80,"count":3,"description":"","link":"https:\/\/blogs.correiobraziliense.com.br\/igualdade\/category\/intervencao-militar\/","name":"Interven\u00e7\u00e3o Militar","slug":"intervencao-militar","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/igualdade\/wp-json\/wp\/v2\/categories\/80","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/igualdade\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/igualdade\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/igualdade\/wp-json\/wp\/v2\/posts?categories=80"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}