{"id":72,"count":5,"description":"","link":"https:\/\/blogs.correiobraziliense.com.br\/igualdade\/category\/genero-nas-artes\/","name":"G\u00eanero nas Artes","slug":"genero-nas-artes","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/igualdade\/wp-json\/wp\/v2\/categories\/72","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/igualdade\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/igualdade\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/igualdade\/wp-json\/wp\/v2\/posts?categories=72"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}