{"id":122,"count":1,"description":"","link":"https:\/\/blogs.correiobraziliense.com.br\/igualdade\/category\/feminicidio\/","name":"Feminic\u00eddio","slug":"feminicidio","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/igualdade\/wp-json\/wp\/v2\/categories\/122","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/igualdade\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/igualdade\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/igualdade\/wp-json\/wp\/v2\/posts?categories=122"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}