{"id":3998,"date":"2019-07-07T14:05:09","date_gmt":"2019-07-07T17:05:09","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/elasnoataque\/?p=3998"},"modified":"2019-07-10T17:38:14","modified_gmt":"2019-07-10T20:38:14","slug":"estados-unidos-tetracampeao-final-copa-do-mundo-feminina-franca","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/elasnoataque\/estados-unidos-tetracampeao-final-copa-do-mundo-feminina-franca\/","title":{"rendered":"Com gol de Rapinoe, EUA vencem Holanda e conquistam o tetra na Copa da Fran\u00e7a"},"content":{"rendered":"<p><strong>Lyon (Fran\u00e7a) \u2014\u00a0<\/strong>A final da Copa do Mundo colocou frente a frente os Estados Unidos, atuais campe\u00e3s mundiais, e a Holanda, atual campe\u00e3 europeia. As favoritas americanas n\u00e3o conseguiram furar o bloqueio montado pela equipe comandada por Sarina Wiegman no primeiro tempo, mas desencantaram com o gol marcado dos p\u00e9s do nome deste Mundial: Megan Rapinoe. Engajada, sem medo de confrontar nem mesmo o presidente do pa\u00eds que defende, a capit\u00e3 abriu o placar de p\u00eanalti e viu Rose Lavelle decretar o quarto t\u00edtulo dos EUA, ap\u00f3s vit\u00f3ria por 2 x 0 sobre a Holanda, neste domingo (7\/7), no Parc de Olympique Lyonnais, em Lyon, na Fran\u00e7a.<\/p>\n<p>\u201c\u00c9 dif\u00edcil descrever o meu sentimento, \u00e9 incr\u00edvel. Todas as pessoas que trabalharam tanto para chegarmos at\u00e9 aqui. Temos um grupo muito unido, estamos sempre muito motivadas para vencer\u201d, disse Rapinoe, ap\u00f3s a partida. Rapinoe foi substitu\u00edda aos 33 minutos do segundo tempo e saiu de campo muito aplaudida pelo est\u00e1dio lotado. Depois, ela seria novamente ovacionada, por receber o pr\u00eamio de melhor jogadora da Copa, aos 34 anos. A veterana chegou aos seis gols e assumiu a artilharia do torneio, ao lado da companheira de equipe Alex Morgan e da inglesa Ellen White.<\/p>\n<p>Pela primeira vez na Copa da Fran\u00e7a, as americanas n\u00e3o marcaram nos primeiros 12 minutos de jogo. No entanto, a superioridade do time comandado por Jill Ellis foi provada durante o jogo. No segundo tempo, sa\u00edram os dois gols que ampliaram a soberania dos Estados Unidos no futebol feminino. N\u00e3o foi na primeira parcial, mas, aos 12 minutos do segunda, Alex Morgan recebeu a bola na grande \u00e1rea e foi acertada pela defensora Van der Gragt, que levantou demais o p\u00e9 na tentativa de afastar o lance. A \u00e1rbitra francesa Stephanie Frappart consultou o VAR para confirmar o p\u00eanalti.<\/p>\n<p>Com seguran\u00e7a, a veterana Megan Rapinoe cobrou para o fundo das redes. Uma dos destaques da partida, a goleira Van Veenendaal nem se mexeu. Rapinoe se igualou na artilharia da Copa do Mundo com seis gols, ao lado da companheira de equipe Alex Morgan e da inglesa Ellen White. Depois do p\u00eanalti, a sele\u00e7\u00e3o holandesa sentiu e deixou as americanas se aproximarem com liberdade do gol. Com o jogo controlado, Rose Lavelle invadiu a \u00e1rea e conduziu a bola sem marca\u00e7\u00e3o. A decis\u00e3o tomada pela americana foi chutar forte no cantinho do gol de Veenendaal, que n\u00e3o conseguiu defender a bola.<\/p>\n<figure id=\"attachment_3999\" aria-describedby=\"caption-attachment-3999\" style=\"width: 750px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-3999\" src=\"https:\/\/blogs.correiobraziliense.com.br\/elasnoataque\/wp-content\/uploads\/sites\/36\/2019\/07\/rap.jpg\" alt=\"Estados Unidos-Megan Rapinoe-Copa do Mundo feminina\" width=\"750\" height=\"500\" srcset=\"https:\/\/blogs.correiobraziliense.com.br\/elasnoataque\/wp-content\/uploads\/sites\/36\/2019\/07\/rap.jpg 750w, https:\/\/blogs.correiobraziliense.com.br\/elasnoataque\/wp-content\/uploads\/sites\/36\/2019\/07\/rap-300x200.jpg 300w, https:\/\/blogs.correiobraziliense.com.br\/elasnoataque\/wp-content\/uploads\/sites\/36\/2019\/07\/rap-550x367.jpg 550w, https:\/\/blogs.correiobraziliense.com.br\/elasnoataque\/wp-content\/uploads\/sites\/36\/2019\/07\/rap-230x153.jpg 230w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><figcaption id=\"caption-attachment-3999\" class=\"wp-caption-text\">Megan Rapinoe fechou a Copa do Mundo com o sexto gol dela \u00e9 o pr\u00eamio de melhor do torneio | Richard Heathcote\/Getty Images<\/figcaption><\/figure>\n<p>A goleira holandesa foi a grande respons\u00e1vel por segurar o empate at\u00e9 o segundo tempo. A primeira grande chance das americanas foi aos 27 minutos do primeiro tempo. Ap\u00f3s escanteio, Ertz chutou forte no meio do gol e, apesar da confus\u00e3o na \u00e1rea, Van Veenendaal foi r\u00e1pida e fez uma bela defesa. Dez minutos depois, as americanas montaram um bombardeio ofensivo. Primeiro, com a cabe\u00e7ada de Mewis no meio da defesa e, depois, com Alex Morgan, que desviou o cruzamento rasteiro de Rapinoe, obrigando Van Veenendaal a fazer dois milagres. No segundo lance, a bola chegou a parar na trave.<\/p>\n<p>A vit\u00f3ria por 2 x 0 deu aos Estados Unidos o quarto t\u00edtulo Mundial. Com o tetracampeonato conquistado, as americanas bateram outro recorde. Jill Ellis, t\u00e9cnica da sele\u00e7\u00e3o norte-americana, se tornou a primeira treinadora a conquistar o bicampeonato em uma Copa do Mundo feminina.<\/p>\n<p><strong>Por Maria Eduarda Cardim e Ma\u00edra Nunes \u2014 Enviadas especiais<\/strong><\/p>\n<p><strong>Patroc\u00ednio:\u00a0<\/strong>Col\u00e9gio Moraes R\u00eago<strong><br \/>\nApoio:\u00a0<\/strong>Casa de Viagens e Bancorbr\u00e1s \u2013 Ag\u00eancia de Viagens<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lyon (Fran\u00e7a) \u2014\u00a0A final da Copa do Mundo colocou frente a frente os Estados Unidos, atuais campe\u00e3s mundiais, e a Holanda, atual campe\u00e3 europeia. As favoritas americanas n\u00e3o conseguiram furar o bloqueio montado pela equipe comandada por Sarina Wiegman no primeiro tempo, mas desencantaram com o gol marcado dos p\u00e9s do nome deste Mundial: Megan Rapinoe. Engajada, sem medo de [&hellip;]<\/p>\n","protected":false},"author":80,"featured_media":4070,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25],"tags":[714,524,20,116,166,675,698],"class_list":["post-3998","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-futebol","tag-campea","tag-copa-da-franca","tag-copa-do-mundo","tag-estados-unidos","tag-final","tag-holanda","tag-megan-rapinoe"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/elasnoataque\/wp-json\/wp\/v2\/posts\/3998","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/elasnoataque\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/elasnoataque\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/elasnoataque\/wp-json\/wp\/v2\/users\/80"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/elasnoataque\/wp-json\/wp\/v2\/comments?post=3998"}],"version-history":[{"count":11,"href":"https:\/\/blogs.correiobraziliense.com.br\/elasnoataque\/wp-json\/wp\/v2\/posts\/3998\/revisions"}],"predecessor-version":[{"id":4071,"href":"https:\/\/blogs.correiobraziliense.com.br\/elasnoataque\/wp-json\/wp\/v2\/posts\/3998\/revisions\/4071"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/elasnoataque\/wp-json\/wp\/v2\/media\/4070"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/elasnoataque\/wp-json\/wp\/v2\/media?parent=3998"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/elasnoataque\/wp-json\/wp\/v2\/categories?post=3998"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/elasnoataque\/wp-json\/wp\/v2\/tags?post=3998"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}