{"id":5021,"date":"2017-04-04T00:00:17","date_gmt":"2017-04-04T03:00:17","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/?p=5021"},"modified":"2017-04-04T15:57:44","modified_gmt":"2017-04-04T18:57:44","slug":"5021-2","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/5021-2\/","title":{"rendered":"OAB envia of\u00edcio aos 20 clubes da S\u00e9rie A exigindo fim da proibi\u00e7\u00e3o da venda do mando de campo"},"content":{"rendered":"<p>A Ordem dos Advogados do Brasil \u2014 Subse\u00e7\u00e3o do Distrito Federal (OAB-DF) \u2014 conseguiu a ades\u00e3o das seccionais do Rio Grande do Norte, Mato Grosso e Amazonas e enviar\u00e1 nesta semana of\u00edcio para os 20 clubes da primeira divis\u00e3o do Campeonato Brasileiro, em mais uma tentativa de derrubar o veto a jogos fora dos estados de origem dos times da S\u00e9rie A. O primeiro documento, ao qual o <strong>blog<\/strong> teve acesso, foi encaminhado ao presidente do Atl\u00e9tico-MG, Daniel Nepomuceno. Em fevereiro, um conselho t\u00e9cnico da S\u00e9rie A aprovou a medida na sede da Confedera\u00e7\u00e3o Brasileira de Futebol (CBF), no Rio, por 14 votos a 6. Flamengo, Fluminense, Corinthians, Ponte Preta, Atl\u00e9tico-PR e Atl\u00e9tico-GO foram contra. &#8220;Pelo menos seis times est\u00e3o do nosso lado. A ideia \u00e9 mobilizar os outros. \u00c9 em prol de toda a sociedade, n\u00e3o s\u00f3 de Bras\u00edlia. Estamos abertos ao di\u00e1logo. N\u00e3o queremos politizar nada. \u00c9 um movimento que partiu de dentro da OAB&#8221;, disse ao <strong>blog<\/strong> Maur\u00edcio Corr\u00eaa da Veiga, presidente da Comiss\u00e3o de Direito Desportivo e Conselheiro da OAB\/DF.<\/p>\n<p>O texto assinado por Maur\u00edcio Corr\u00eaa da Veiga e pelo presidente da OAB\/DF, Juliano Costa Couto, recomenda\u00a0duas alternativas: \u201cA imediata reconsidera\u00e7\u00e3o da proibi\u00e7\u00e3o da venda de mando de campo ou que se cogite permitir a \u201cvenda\u201d do mando de campo durante a primeira metade do Campeonato Brasileiro\u201d. O documento encaminhado aos presidentes dos 20 clubes da S\u00e9rie A alega, ainda, que a decis\u00e3o do conselho t\u00e9cnico \u201cse traduz em um manifesto desrespeito ao torcedor de todas as entidades de pr\u00e1tica desportiva do pa\u00eds, que s\u00e3o privados da oportunidade de assistir aos seus clubes em outras pra\u00e7as desportivas deste pa\u00eds continental&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center\"><a href=\"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/wp-content\/uploads\/sites\/15\/2017\/04\/image.png\" rel=\"attachment wp-att-5022\"><br \/>\n<\/a><a href=\"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/wp-content\/uploads\/sites\/15\/2017\/04\/image.png\" rel=\"attachment wp-att-5022\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-5022\" src=\"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/wp-content\/uploads\/sites\/15\/2017\/04\/image-225x300.png\" alt=\"image\" width=\"225\" height=\"300\" \/><\/a><a href=\"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/wp-content\/uploads\/sites\/15\/2017\/04\/image-1.jpeg\" rel=\"attachment wp-att-5024\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-5024\" src=\"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/wp-content\/uploads\/sites\/15\/2017\/04\/image-1-256x300.jpeg\" alt=\"image\" width=\"256\" height=\"300\" \/><\/a><\/p>\n<p style=\"text-align: center\"><em>Of\u00edcio enviado ao presidente do Atl\u00e9tico-MG<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Distrito Federal (Man\u00e9 Garrincha), Rio Grande do Norte (Natal), Mato Grosso (Arena Pantanal) e Amazonas (Arena da Amaz\u00f4nia) s\u00e3o os quatro estados que se sentiram prejudicados pela decis\u00e3o dos clubes que pro\u00edbe a chamada venda de mando de campo no Brasileir\u00e3o. <a href=\"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/oab-entra-na-briga-para-derrubar-veto-venda-de-mando-de-campo-no-brasileirao-arenas-ameacam-ir-justica\/\">Como o blog antecipou em 23 de mar\u00e7o<\/a>, o presidente da CBF, Marco Polo Del Nero, foi o primeiro a receber o of\u00edcio enviado pela OAB-DF. O cartola respondeu que cumpre a decis\u00e3o dos clubes.<\/p>\n<p>O principal alvo do documento da OAB \u00e9 o presidente do Atl\u00e9tico-MG, Daniel Nepomuceno, mentor da proposta aprovada pela maioria. \u201cEu levei a minha posi\u00e7\u00e3o ao Conselho T\u00e9cnico porque achei um absurdo o que aconteceu no ano passado. Voc\u00ea deve se lembrar. O America-MG vendeu um mando de campo e levou o jogo l\u00e1 pro Paran\u00e1. O Palmeiras jogou em casa. Depois que foi rebaixado, o Santa Cruz recebeu v\u00e1rias propostas indecentes para jogar fora do Recife tamb\u00e9m. Resumindo: n\u00e3o sou contra a venda do mando de campo, eu n\u00e3o admito \u00e9 invers\u00e3o de mando. Era isso que estava acontecendo, ou seja, time visitante que era beneficiado e jogava como se estivesse em casa\u201d, reclamou o mandat\u00e1rio do Galo ao blog.<\/p>\n<p>Por sinal, Daniel Nepomuceno recebe nesta semana os gestores do Man\u00e9 Garrincha e das arenas das Dunas, Pantanal e da Amaz\u00f4nia. Segundo o secret\u00e1rio de Turismo do DF, Jaime Recena, o di\u00e1logo prop\u00f5e duas sa\u00eddas. \u201cAs nossas sugest\u00f5es s\u00e3o duas: impedir invers\u00e3o de mando nas \u00faltimas 10 partidas e a indica\u00e7\u00e3o dos jogos que os times pretendem disputar fora dos seus estados antes do in\u00edcio da competi\u00e7\u00e3o\u201d. O secret\u00e1rio de Esportes da Amaz\u00f4nia \u00e9 mias incisivo. \u201cEstamos tentando uma solu\u00e7\u00e3o amig\u00e1vel, mas se n\u00e3o for poss\u00edvel, vamos entrar com a\u00e7\u00e3o na Justi\u00e7a\u201d, amea\u00e7a Fabr\u00edcio Lima.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Ordem dos Advogados do Brasil \u2014 Subse\u00e7\u00e3o do Distrito Federal (OAB-DF) \u2014 conseguiu a ades\u00e3o das seccionais do Rio Grande do Norte, Mato Grosso e Amazonas e enviar\u00e1 nesta semana of\u00edcio para os 20 clubes da primeira divis\u00e3o do Campeonato Brasileiro, em mais uma tentativa de derrubar o veto a jogos fora dos estados [&hellip;]<\/p>\n","protected":false},"author":31,"featured_media":3254,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"wpb_read_more":[],"footnotes":""},"categories":[9],"tags":[145,169,167,168],"class_list":["post-5021","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esporte","tag-brasileirao","tag-campeonato-brasileiro","tag-mando-de-jogo","tag-serie-a"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/wp-json\/wp\/v2\/posts\/5021","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/wp-json\/wp\/v2\/users\/31"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/wp-json\/wp\/v2\/comments?post=5021"}],"version-history":[{"count":5,"href":"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/wp-json\/wp\/v2\/posts\/5021\/revisions"}],"predecessor-version":[{"id":5030,"href":"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/wp-json\/wp\/v2\/posts\/5021\/revisions\/5030"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/wp-json\/wp\/v2\/media\/3254"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/wp-json\/wp\/v2\/media?parent=5021"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/wp-json\/wp\/v2\/categories?post=5021"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/wp-json\/wp\/v2\/tags?post=5021"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}