{"id":4954,"date":"2017-03-31T01:00:50","date_gmt":"2017-03-31T04:00:50","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/?p=4954"},"modified":"2017-03-31T01:28:47","modified_gmt":"2017-03-31T04:28:47","slug":"liga-das-nacoes-pode-vetar-europeus-na-copa-america-de-2019","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/liga-das-nacoes-pode-vetar-europeus-na-copa-america-de-2019\/","title":{"rendered":"Liga das Na\u00e7\u00f5es pode inviabilizar convite a sele\u00e7\u00f5es europeias para Copa Am\u00e9rica de 2019 no Brasil"},"content":{"rendered":"<p>A ideia da Confedera\u00e7\u00e3o Sul-Americana de Futebol (Conmebol) de convidar sele\u00e7\u00f5es europeias para a Copa Am\u00e9rica de 2019, no Brasil, antecipada nesta quinta-feira pelo colega Mart\u00edn Fernandez, do portal GloboEsporte.com, pode esbarrar no calend\u00e1rio de uma nova competi\u00e7\u00e3o do Velho Mundo.<\/p>\n<p>Depois da Copa de 2018, na R\u00fassia, a Uefa colocar\u00e1 em pr\u00e1tica a primeira edi\u00e7\u00e3o da Liga das Na\u00e7\u00f5es Europeias.\u00a0 O Final Four, como a entidade batizou a disputa pelo t\u00edtulo, ser\u00e1 disputado de 5 a 9 de junho, em um pa\u00eds sede ainda indefinido. Logo, o choque ou a proximidade de datas entre as duas competi\u00e7\u00f5es oficiais dos respectivos continentes pode inviabilizar a presen\u00e7a das na\u00e7\u00f5es de origem latina Fran\u00e7a, Portugal, It\u00e1lia e Espanha na Copa Am\u00e9rica, como sugerem alguns pa\u00edses filiados \u00e0 Conmebol.<\/p>\n<p>Aprovada por unanimidade em 2014, no Cazaquist\u00e3o, como um ant\u00eddoto contra amistosos ca\u00e7a-n\u00edqueis, a Liga das Na\u00e7\u00f5es Europeias dividir\u00e1 seus filiados em quatro divis\u00f5es, com direito a promo\u00e7\u00e3o e rebaixamento. As ligas A e B ter\u00e3o 12 sele\u00e7\u00f5es cada divididas em quatro chaves com tr\u00eas pa\u00edses. Eles jogam entre si em ida e volta. Os quatro melhores avan\u00e7am ao chamado Final Four. As ligas C e D ser\u00e3o disputadas, respectivamente, por 15 e 16 sele\u00e7\u00f5es. Os primeiros colocados de cada grupo sobem de divis\u00e3o e os quatro piores descem.<\/p>\n<p>O Final Four, que pode impedir esquadras europeias na Copa Am\u00e9rica, vale t\u00edtulo. As semifinais e a final ser\u00e3o em um pa\u00eds determinado pelo Comit\u00ea Executivo da Uefa.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_4955\" aria-describedby=\"caption-attachment-4955\" style=\"width: 300px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/wp-content\/uploads\/sites\/15\/2017\/03\/Liga-1.jpg\" rel=\"attachment wp-att-4955\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-4955\" src=\"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/wp-content\/uploads\/sites\/15\/2017\/03\/Liga-1-300x169.jpg\" alt=\"O formato da Liga das Na\u00e7\u00f5es definido pela Uefa\" width=\"300\" height=\"169\" \/><\/a><figcaption id=\"caption-attachment-4955\" class=\"wp-caption-text\">O formato da Liga das Na\u00e7\u00f5es definido pela Uefa<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>Paralelamente \u00e0 Liga das Na\u00e7\u00f5es, ocorrer\u00e3o as Eliminat\u00f3rias para a Eurocopa de 2020, com cinco grupos com cinco sele\u00e7\u00f5es e outros cinco de seis. O campe\u00e3o e o vice de cada chave se classificam direto para a Eurocopa, totalizando 20 sele\u00e7\u00f5es. As outras quatro vagas ser\u00e3o definidas em uma repescagem com base justamente no ranking da Liga das Na\u00e7\u00f5es Europeias. Neste caso, a Uefa vai formar quatro grupos com quatro equipes em semifinais e uma decis\u00e3o em campo neutro. O vencedor de cada uma das chaves da repescagem avan\u00e7a \u00e0 Eurocopa de 2020.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_4956\" aria-describedby=\"caption-attachment-4956\" style=\"width: 300px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/wp-content\/uploads\/sites\/15\/2017\/03\/Liga-2.jpg\" rel=\"attachment wp-att-4956\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-4956\" src=\"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/wp-content\/uploads\/sites\/15\/2017\/03\/Liga-2-300x169.jpg\" alt=\"A Liga das Na\u00e7\u00f5es tamb\u00e9m definir\u00e1 quatro vagas para a Euro-2020\" width=\"300\" height=\"169\" \/><\/a><figcaption id=\"caption-attachment-4956\" class=\"wp-caption-text\">A Liga das Na\u00e7\u00f5es tamb\u00e9m definir\u00e1 quatro vagas para a Euro-2020<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>O poss\u00edvel choque de datas do Final Four da Liga das Na\u00e7\u00f5es Europeias pode inviabilizar a presen\u00e7a europeia na Copa Am\u00e9rica, mas n\u00e3o impediria a poss\u00edvel presen\u00e7a do Jap\u00e3o na competi\u00e7\u00e3o. A sele\u00e7\u00e3o asi\u00e1tica inclusive participou da Copa Am\u00e9rica em 1999. Os samurais ficaram em \u00faltimo lugar no Grupo A, atr\u00e1s do Paraguai, do Peru e da Bol\u00edvia.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A ideia da Confedera\u00e7\u00e3o Sul-Americana de Futebol (Conmebol) de convidar sele\u00e7\u00f5es europeias para a Copa Am\u00e9rica de 2019, no Brasil, antecipada nesta quinta-feira pelo colega Mart\u00edn Fernandez, do portal GloboEsporte.com, pode esbarrar no calend\u00e1rio de uma nova competi\u00e7\u00e3o do Velho Mundo. Depois da Copa de 2018, na R\u00fassia, a Uefa colocar\u00e1 em pr\u00e1tica a primeira [&hellip;]<\/p>\n","protected":false},"author":31,"featured_media":2871,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"wpb_read_more":[],"footnotes":""},"categories":[9],"tags":[],"class_list":["post-4954","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esporte"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/wp-json\/wp\/v2\/posts\/4954","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/wp-json\/wp\/v2\/users\/31"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/wp-json\/wp\/v2\/comments?post=4954"}],"version-history":[{"count":3,"href":"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/wp-json\/wp\/v2\/posts\/4954\/revisions"}],"predecessor-version":[{"id":4959,"href":"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/wp-json\/wp\/v2\/posts\/4954\/revisions\/4959"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/wp-json\/wp\/v2\/media\/2871"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/wp-json\/wp\/v2\/media?parent=4954"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/wp-json\/wp\/v2\/categories?post=4954"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/wp-json\/wp\/v2\/tags?post=4954"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}