{"id":4734,"date":"2017-03-17T00:00:22","date_gmt":"2017-03-17T03:00:22","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/?p=4734"},"modified":"2017-03-16T21:25:15","modified_gmt":"2017-03-17T00:25:15","slug":"4734-2","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/4734-2\/","title":{"rendered":"Campe\u00e3o da Eurocopa, Portugal v\u00ea fracasso em massa dos seus clubes nas competi\u00e7\u00f5es continentais"},"content":{"rendered":"<p>Oito meses depois de conquistar o \u00fanico t\u00edtulo de sua hist\u00f3ria, Portugal fracassa nas competi\u00e7\u00f5es europeias. Campe\u00e3o da Eurocopa em julho do ano passado ao vencer a Fran\u00e7a em Saint-Denis, por 1 x 0, o pa\u00eds n\u00e3o tem nenhum time classificado para as quartas de final da Liga dos Campe\u00f5es da Europa nem para a mesma fase da Liga Europa, o segundo torneio mais importante do continente. Para voc\u00ea ter uma ideia, a B\u00e9lgica tem dois times nas quartas da Europa League (Anderlecht e Genk) e a Turquia classificou um (Besiktas). <\/p>\n<p>O fracasso foi maior na Liga Europa. Representante da terra de Cam\u00f5es na fase de grupos, o Sporting Braga n\u00e3o passou da fase de grupos. Antes, Rio Ave e Arouca nem sequer passaram da etapa eliminat\u00f3ria. Portugal simplesmente n\u00e3o teve representantes na fase de 16 avos da competi\u00e7\u00e3o. A na\u00e7\u00e3o lusitana tem tradi\u00e7\u00e3o na competi\u00e7\u00e3o. Conquistou o t\u00edtulo duas vezes, ambas com o Porto, nas temporadas de 2002\/2003 e de 2010\/2011. E foi cinco vezes vice.<\/p>\n<p>Na Liga dos Campe\u00f5es da Europa, mais decep\u00e7\u00f5es. O Sporting deu adeus ao torneio na fase de grupos. Porto e Benfica se despediram nas oitavas. Campe\u00e3o em 1988 e em 2004, o Porto n\u00e3o aguentou a Juventus e perdeu por 3 x 0 no placar agregado.  Bi em 1962 e 1963, o Benfica n\u00e3o foi p\u00e1reo para o Borussia Dortmund. Apanhou por 4 x 1 no placar agregado. <\/p>\n<p>Resta a Portugal o orgulho de torcer pelo n\u00famero 1 do mundo Cristiano Ronaldo nas quartas de final da Champions League. Ou pelo fant\u00e1stico Monaco de Leonardo Jardim, um dos treinadores mais promissores da Europa. Na Liga Europa, o consolo \u00e9 Jos\u00e9 Mourinho. \u00c0 frente do Manchester United, The Special One tentar\u00e1 repetir a conquista de 2002\/2003, quando levou o Porto ao t\u00edtulo da Copa da Uefa, antecessora da Liga Europa. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Oito meses depois de conquistar o \u00fanico t\u00edtulo de sua hist\u00f3ria, Portugal fracassa nas competi\u00e7\u00f5es europeias. Campe\u00e3o da Eurocopa em julho do ano passado ao vencer a Fran\u00e7a em Saint-Denis, por 1 x 0, o pa\u00eds n\u00e3o tem nenhum time classificado para as quartas de final da Liga dos Campe\u00f5es da Europa nem para a [&hellip;]<\/p>\n","protected":false},"author":31,"featured_media":2871,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"wpb_read_more":[],"footnotes":""},"categories":[9],"tags":[],"class_list":["post-4734","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esporte"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/wp-json\/wp\/v2\/posts\/4734","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/wp-json\/wp\/v2\/users\/31"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/wp-json\/wp\/v2\/comments?post=4734"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/wp-json\/wp\/v2\/posts\/4734\/revisions"}],"predecessor-version":[{"id":4735,"href":"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/wp-json\/wp\/v2\/posts\/4734\/revisions\/4735"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/wp-json\/wp\/v2\/media\/2871"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/wp-json\/wp\/v2\/media?parent=4734"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/wp-json\/wp\/v2\/categories?post=4734"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/wp-json\/wp\/v2\/tags?post=4734"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}