{"id":34790,"date":"2026-02-19T10:10:37","date_gmt":"2026-02-19T13:10:37","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/?p=34790"},"modified":"2026-02-19T10:10:37","modified_gmt":"2026-02-19T13:10:37","slug":"botafogo-sofre-com-a-falta-de-variacao-tatica-sob-o-comando-de-anselmi","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/botafogo-sofre-com-a-falta-de-variacao-tatica-sob-o-comando-de-anselmi\/","title":{"rendered":"Botafogo sofre com a falta de varia\u00e7\u00e3o t\u00e1tica sob o comando de Anselmi"},"content":{"rendered":"<p>O Botafogo acumula seis derrotas consecutivas na temporada. Perdeu duas vezes para o Fluminense e uma para Vasco, Gr\u00eamio, Flamengo e Nacional nesta quarta-feira na altitude de 4.000m de Potos\u00ed, na Bol\u00edvia, em partidas de tr\u00eas competi\u00e7\u00f5es diferentes: Carioca, Brasileir\u00e3o e Pr\u00e9-Libertadores. N\u00e3o, isso n\u00e3o pode ser considerado normal.<\/p>\n<p>&nbsp;<\/p>\n<p>A sequ\u00eancia \u00e9 causada por um motivo: a falta de flexibilidade do t\u00e9cnico Martin Anselmi. O argentino \u00e9 bom t\u00e9cnico. Se n\u00e3o fosse, n\u00e3o teria no curr\u00edculo os t\u00edtulos da Copa Sul-Americana, Recopa Sul-Americana, Copa Equador e Supercopa do Equador. A quest\u00e3o \u00e9 o apego ao mesmo sistema de jogo no Uni\u00f3n La Calera, Independiente del Valle, Cruz Azul, Porto e agora no Botafogo. \u00a0Ele tem uma fidelidade canina a defesas com linha de tr\u00eas.<\/p>\n<p>&nbsp;<\/p>\n<p>Ironicamente, Martin Anselmi iniciou a passagem pelo Botafogo escalando o time com uma linha de quatro: Vitinho, Mateo Ponte improvisado na zaga ao lado de Barboza e Alex Telles na lateral esquerda na vit\u00f3ria por 1 x 0 contra o Volta Redonda na estreia no Carioca. Foi s\u00f3.<\/p>\n<p>&nbsp;<\/p>\n<p>Depois disso, abra\u00e7ou a linha de tr\u00eas, n\u00e3o largou e nem indica mudan\u00e7a. A altitude levou Martin Anselmi a fortalecer a linha defensiva e transform\u00e1-la praticamente em cinco defensores na tentativa de controlar o Nacional de Potos\u00ed. O time boliviano balan\u00e7ou a rede.<\/p>\n<p>&nbsp;<\/p>\n<p>A falta de varia\u00e7\u00e3o t\u00e1tica e os recorrentes improvisos na defesa ao utilizar zagueiros que nem sempre s\u00e3o especialistas \u00e9 uma demanda para Martin Anselmi resolver. A falta de pontaria nas finaliza\u00e7\u00f5es, n\u00e3o! O Botafogo poderia ter voltado da Bol\u00edvia no m\u00ednimo com empate.<\/p>\n<p>&nbsp;<\/p>\n<p>Matheus Martins desperdi\u00e7ou a melhor oportunidade do Botafogo no primeiro tempo. Na etapa final, foi a vez de \u00c1lvaro Montoro falhar praticamente embaixo da trave. Alex Telles tentou resolver em uma cobran\u00e7a de falta e quase conseguiu igualar o placar.<\/p>\n<p>&nbsp;<\/p>\n<p>O resultado contra o Nacional de Potos\u00ed estava dentro do previsto. A sequ\u00eancia de seis derrotas consecutivas, n\u00e3o. Bruno Lage, por exemplo, caiu em 2023 depois de uma s\u00e9rie de cinco partidas sem vencer. Renato Paiva e Tiago Nunes ca\u00edram por muito menos porque o trabalho simplesmente n\u00e3o mostrava evolu\u00e7\u00e3o.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/the-botafogo-way-martin-anselmi-pode-entregar-o-que-deseja-john-textor\/\">Como o dono da SAF John Textor est\u00e1 focado em outros assuntos<\/a>, Martin Anselmi ganha tempo para colocar a casa em ordem. As respostas precisam ser imediatas contra o Boavista na Ta\u00e7a Rio e na volta contra o Nacional de Potos\u00ed no Est\u00e1dio Nilton Santos.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Leia tamb\u00e9m:<\/strong><\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"fxj94RODaC\"><p><a href=\"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/saida-de-coutinho-do-vasco-expoe-relacao-toxica-entre-idolos-e-torcidas\/\">Sa\u00edda de Coutinho do Vasco exp\u00f5e rela\u00e7\u00e3o t\u00f3xica entre \u00eddolos e torcidas<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u201cSa\u00edda de Coutinho do Vasco exp\u00f5e rela\u00e7\u00e3o t\u00f3xica entre \u00eddolos e torcidas\u201d \u2014 Blog Drible de Corpo\" src=\"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/saida-de-coutinho-do-vasco-expoe-relacao-toxica-entre-idolos-e-torcidas\/embed\/#?secret=xqE8sQUFiO#?secret=fxj94RODaC\" data-secret=\"fxj94RODaC\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<div>\n<p><strong>X: @marcospaulolima<\/strong><\/p>\n<\/div>\n<div>\n<p><strong>Instagram: @marcospaulolima.jor<\/strong><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>O Botafogo acumula seis derrotas consecutivas na temporada. Perdeu duas vezes para o Fluminense e uma para Vasco, Gr\u00eamio, Flamengo e Nacional nesta quarta-feira na altitude de 4.000m de Potos\u00ed, na Bol\u00edvia, em partidas de tr\u00eas competi\u00e7\u00f5es diferentes: Carioca, Brasileir\u00e3o e Pr\u00e9-Libertadores. N\u00e3o, isso n\u00e3o pode ser considerado normal. &nbsp; A sequ\u00eancia \u00e9 causada por [&hellip;]<\/p>\n","protected":false},"author":31,"featured_media":34792,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"wpb_read_more":[],"footnotes":""},"categories":[9],"tags":[1471,3,1417,202,1530,738,1529,1429,1528,1527],"class_list":["post-34790","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esporte","tag-analise-tatica","tag-botafogo","tag-brasileirao-2026","tag-carioca","tag-crise-no-botafogo","tag-john-textor","tag-linha-de-tres","tag-martin-anselmi","tag-nacional-de-potosi","tag-pre-libertadores"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/wp-json\/wp\/v2\/posts\/34790","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/wp-json\/wp\/v2\/users\/31"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/wp-json\/wp\/v2\/comments?post=34790"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/wp-json\/wp\/v2\/posts\/34790\/revisions"}],"predecessor-version":[{"id":34793,"href":"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/wp-json\/wp\/v2\/posts\/34790\/revisions\/34793"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/wp-json\/wp\/v2\/media\/34792"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/wp-json\/wp\/v2\/media?parent=34790"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/wp-json\/wp\/v2\/categories?post=34790"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/wp-json\/wp\/v2\/tags?post=34790"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}