{"id":215,"date":"2015-07-20T08:00:00","date_gmt":"2015-07-20T11:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/no_whatsapp_com_pere_o_irmao_de_guardiola\/"},"modified":"2015-11-18T13:24:45","modified_gmt":"2015-11-18T15:24:45","slug":"no_whatsapp_com_pere_o_irmao_de_guardiola","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/no_whatsapp_com_pere_o_irmao_de_guardiola\/","title":{"rendered":"No WhatsApp com Pere, o irm\u00e3o de Guardiola"},"content":{"rendered":"<p>Um dia desses, conheci pessoalmente um cara mais brother do t\u00e9cnico do  Bayern de Munique, Pep Guardiola, do que eu imaginava \u2014 o irm\u00e3o dele,  Pere Guardiola. Foi um cumprimento r\u00e1pido, daqueles que s\u00f3 d\u00e1 tempo de  trocar cart\u00f5es de contato. Gra\u00e7as ao ucraniano Jan Koum, inventor do  WhatsApp, tive mais acesso a um dos 10 agentes de jogadores mais  influentes do mundo, que tem Luis Su\u00e1rez como principal cliente, via  aplicativo.  <\/p>\n<p>A primeira troca de textos foi r\u00e1pida e t\u00edmida.  Entretanto, desde a excelente entrevista de Daniel Alves ao programa  Bola da Vez, da ESPN Brasil, o bate-papo com Pere Guardiola se  intensificou. Dani contou que Pep Guardiola toparia assumir a Sele\u00e7\u00e3o  Brasileira quando Mano Menezes foi demitido. Estava livre, curtia ano  sab\u00e1tico em Nova York. O lateral-direito disse, ainda, que o treinador  tinha um time montadinho na cabe\u00e7a.  <\/p>\n<p>L\u00e1 fui eu perturbar o irm\u00e3o  do Guardiola. A informa\u00e7\u00e3o de que o treinador toparia assumir a Sele\u00e7\u00e3o  era apenas uma confirma\u00e7\u00e3o do que o Lance! publicara em 2012, no dia da  demiss\u00e3o de Mano. A novidade \u00e9 desvendar quais seriam os 11 titulares de  Guardiola se a CBF n\u00e3o tivesse preferido Felip\u00e3o. Perguntei ao Pere se  imaginava \u201cel once ideal\u201d do Brasil, mas ele blindou o maninho. \u201cOl\u00e1,  Marcos, perd\u00e3o, mas n\u00e3o posso dar opini\u00e3o ou informa\u00e7\u00e3o a esse respeito.  O melhor seria falar com Guardiola, mas ele n\u00e3o d\u00e1 entrevistas  exclusivas.\u201d  <\/p>\n<p>T\u00e1 bom, Pere, nem ia pedir, mesmo&#8230; Decidi me  debru\u00e7ar sobre os campinhos t\u00e1ticos que coleciono em casa das eras  Guardiola no Bar\u00e7a e no Bayern. Entrei na m\u00e1quina do tempo e projetei  uma Sele\u00e7\u00e3o Brasileira de fic\u00e7\u00e3o, com a cabe\u00e7a dele, com o sistema  t\u00e1tico mais usado por ele na temporada passada (4-1-4-1). Ah, e tentando  achar jogadores conhecidos, com o perfil dele.  <\/p>\n<p>Pep Guardiola e o  ex-auxiliar, Tito Vilanova, gostavam do goleiro Diego Alves. Tentaram  at\u00e9 contrat\u00e1-lo. O \u201cdelator\u201d Daniel Alves certamente seria o  lateral-direito e Marcelo, o esquerdo. A dupla de zaga contaria com  Thiago Silva, outro sonho frustrado de Guardiola nos tempos de Bar\u00e7a, e  David Luiz, que lembra um dos queridinhos dele \u2014 Puyol \u2014 ao menos na  cabeleira.  <\/p>\n<p>Tive uma dificuldade imensa para achar um \u201cs\u00f3sia\u201d do  Busquets ou do Schweinsteiger no futebol brasileiro. Vencido pelo  cansa\u00e7o, eu me rendi ao Luiz Gustavo. Sem convic\u00e7\u00e3o, \u00e9 claro. Pep  Guardiola dispensou o volante quando chegou ao Bayern de Munique. Talvez  a escassez o faria mudar de ideia ao assumir a Sele\u00e7\u00e3o. Os mais  apressadinhos dir\u00e3o que o time est\u00e1 igualzinho ao do Felip\u00e3o na Copa.  Calma, calma, calma, a revolu\u00e7\u00e3o come\u00e7a agora&#8230;  <\/p>\n<p>\u00c0 frente de Luiz  Gustavo, uma linha de quatro jogadores de muita t\u00e9cnica para dar a Pep  Guardiola posse de bola, movimenta\u00e7\u00e3o, falta de refer\u00eancias no ataque.  Aberto na direita, Lucas. Ao lado dele, Oscar,&nbsp; o cara da condu\u00e7\u00e3o da  bola. Ganso, o cara da cad\u00eancia, chamado por Guardiola de \u201cmaravilhoso\u201d  na v\u00e9spera da final do Mundial de Clubes de 2011. E Philippe Coutinho ou  Willian na ponta canhota. Na frente, o fora de s\u00e9rie Neymar, no papel  de falso 9.  <\/p>\n<p>Enviei meu \u201cPep Team\u201d ao irm\u00e3o de Guardiola. A  reposta de Pere foi um joinha, que n\u00e3o quer dizer nada, \u00f3bvio. Valeu o  desafio. Arrisco dizer que esse time encantaria e n\u00e3o ganharia o hexa.  Mas, pelo menos, Guardiola ressuscitaria uma escola. Lembram o que ele  disse ap\u00f3s Barcelona 4 x 0 Santos na final do Mundial de Clubes 2011? \u201cO  que tentamos fazer \u00e9 passar a bola o mais r\u00e1pido poss\u00edvel. \u00c9 o que o  Brasil fez em toda a sua vida, segundo contavam meus pais e av\u00f3s\u201d. Ao  menos, a CBF n\u00e3o foi p\u00e3o-dura: comprou Guardiola Confidencial, o livro  em portugu\u00eas lan\u00e7ado no Brasil na semana passada. Que n\u00e3o seja s\u00f3  enfeite na estante, Dunga.  <\/p>\n<p>Coluna publicada nesta segunda (20\/7) no <b>Correio Braziliense<\/b>  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um dia desses, conheci pessoalmente um cara mais brother do t\u00e9cnico do Bayern de Munique, Pep Guardiola, do que eu imaginava \u2014 o irm\u00e3o dele, Pere Guardiola. Foi um cumprimento r\u00e1pido, daqueles que s\u00f3 d\u00e1 tempo de trocar cart\u00f5es de contato. Gra\u00e7as ao ucraniano Jan Koum, inventor do WhatsApp, tive mais acesso a um dos [&hellip;]<\/p>\n","protected":false},"author":31,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"wpb_read_more":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-215","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/wp-json\/wp\/v2\/posts\/215","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/wp-json\/wp\/v2\/users\/31"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/wp-json\/wp\/v2\/comments?post=215"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/wp-json\/wp\/v2\/posts\/215\/revisions"}],"predecessor-version":[{"id":304,"href":"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/wp-json\/wp\/v2\/posts\/215\/revisions\/304"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/wp-json\/wp\/v2\/media?parent=215"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/wp-json\/wp\/v2\/categories?post=215"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/wp-json\/wp\/v2\/tags?post=215"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}