{"id":13163,"date":"2019-09-16T20:00:03","date_gmt":"2019-09-16T23:00:03","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/?p=13163"},"modified":"2019-09-16T22:26:42","modified_gmt":"2019-09-17T01:26:42","slug":"titulo-7-x-1-e-virada-nas-quartas-da-liga-dos-campeoes-da-asia-o-impressionante-inicio-do-treinador-xavi-hernandez","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/titulo-7-x-1-e-virada-nas-quartas-da-liga-dos-campeoes-da-asia-o-impressionante-inicio-do-treinador-xavi-hernandez\/","title":{"rendered":"T\u00edtulo, 7 x 1, e virada heroica nas quartas de final da Liga dos Campe\u00f5es da \u00c1sia: o impressionante in\u00edcio do agora treinador Xavi Hernandez"},"content":{"rendered":"<p>O in\u00edcio da carreira de Xavi Hern\u00e1ndez como treinador tem sa\u00eddo melhor do que a encomenda. Aos 39 anos, o \u00eddolo do Barcelona e da sele\u00e7\u00e3o da Espanha acumula \u00f3timos resultados \u00e0 frente do Al-Sadd do Qatar. O \u00faltimo deles foi nesta segunda-feira. Pressionado a vencer o Al-Nassr da Ar\u00e1bia Saudita por dois gols de diferen\u00e7a para avan\u00e7ar \u00e0s semifinais da Liga dos Campe\u00f5es da \u00c1sia, o treinador conseguiu: venceu por 3 x 1 no est\u00e1dio Jassim Bin Hamad, em Doha.<\/p>\n<p>O Al-Nassr, do meia Giuliano e do volante Petros, havia vencido o jogo de ida por 2 x 1. Em casa, Akram Afif, Al Heidos e o argelino Bounedjah decretaram a virada para 4 x 3 no placar agregado. Hamed-Allah descontou para o time saudita diante de 13.262 torcedores.<\/p>\n<p>Classificado para o Mundial de Clubes da Fifa como atual campe\u00e3o nacional do pa\u00eds sede do torneio marcado para dezembro, o Al-Sadd aguarda o vencedor entre Al-Ittihad e Al-Hilal nas semifinais. Do outro lado da chave est\u00e3o Shangai SIGP, Urawa Red Diamonds, Guangzhou Evergrande e o Kashima Antlers \u2014 atual campe\u00e3o continental. O Al-Sadd busca o tri. Faturou o t\u00edtulo nas edi\u00e7\u00f5es de 1989 e de 2011.<\/p>\n<p>&nbsp;<\/p>\n<blockquote><p><strong>Xavi desbancou o Al-Nassr no sistema 4-2-3-1<\/strong><\/p>\n<p>Al-Sheeb<\/p>\n<p>Pedro Miguel, Khoukhi, Salman e Abdelkarim Hassan<\/p>\n<p>Gabi e Jung<\/p>\n<p>Al-Haydos, Nam e Akram Afif<\/p>\n<p>Bounedjah<\/p>\n<p>&nbsp;<\/p><\/blockquote>\n<p>Xavi tem um in\u00edcio dos sonhos. S\u00e3o cinco vit\u00f3rias, um empate e uma derrota em sete jogos oficiais. S\u00f3 perdeu para o Al-Nassr. Em 31 de agosto, o Al-Sadd humilhou o Al-Shahaniya por uma placar bem familiar a n\u00f3s brasileiros: 7 x 1.<\/p>\n<p>Em dois meses de trabalho, Xavi tem at\u00e9 trof\u00e9u. Em 17 de agosto, conquistou o t\u00edtulo da Supercopa do Qatar, chamada de Sheikh Jassim Cup. Ao Al-Sadd derrotou o Al-Duhail por 1 x 0. Xavi tamb\u00e9m desbancou o advers\u00e1rio nas oitavas de final da Liga dos Campe\u00f5es da \u00c1sia.<\/p>\n<p>Por sinal, Xavi tem sido uma esp\u00e9cie de exterminador de treinadores portugueses. O Al-Duhail \u00e9 comandado pelo lusitano Rui Faria. Desbancado nesta segunda-feira da Liga dos Campe\u00f5es da \u00c1sia, o Al-Nasrr \u00e9 liderado por Rui Vit\u00f3ria.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Siga o blogueiro no Twitter:<\/strong>\u00a0<a href=\"https:\/\/twitter.com\/mplimaDF\">@mplimaDF<\/a><\/p>\n<p><strong>Siga o blogueiro no Instagram:<\/strong>\u00a0@marcospaul0lima<\/p>\n<p><strong>Siga o blog no Facebook:<\/strong>\u00a0https:<a href=\"https:\/\/www.facebook.com\/dribledecorpo\/\">\/\/www.facebook.com\/dribledecorpo\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O in\u00edcio da carreira de Xavi Hern\u00e1ndez como treinador tem sa\u00eddo melhor do que a encomenda. Aos 39 anos, o \u00eddolo do Barcelona e da sele\u00e7\u00e3o da Espanha acumula \u00f3timos resultados \u00e0 frente do Al-Sadd do Qatar. O \u00faltimo deles foi nesta segunda-feira. Pressionado a vencer o Al-Nassr da Ar\u00e1bia Saudita por dois gols de [&hellip;]<\/p>\n","protected":false},"author":31,"featured_media":13164,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"wpb_read_more":[],"footnotes":""},"categories":[9],"tags":[],"class_list":["post-13163","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esporte"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/wp-json\/wp\/v2\/posts\/13163","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/wp-json\/wp\/v2\/users\/31"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/wp-json\/wp\/v2\/comments?post=13163"}],"version-history":[{"count":6,"href":"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/wp-json\/wp\/v2\/posts\/13163\/revisions"}],"predecessor-version":[{"id":13167,"href":"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/wp-json\/wp\/v2\/posts\/13163\/revisions\/13167"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/wp-json\/wp\/v2\/media\/13164"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/wp-json\/wp\/v2\/media?parent=13163"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/wp-json\/wp\/v2\/categories?post=13163"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dribledecorpo\/wp-json\/wp\/v2\/tags?post=13163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}