{"id":334,"count":1,"description":"","link":"https:\/\/blogs.correiobraziliense.com.br\/denise\/tag\/pr\/","name":"pr","slug":"pr","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/denise\/wp-json\/wp\/v2\/tags\/334","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/denise\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/denise\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/denise\/wp-json\/wp\/v2\/posts?tags=334"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}