{"id":6949,"date":"2021-04-19T12:27:05","date_gmt":"2021-04-19T15:27:05","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/denise\/?p=6949"},"modified":"2021-04-19T12:30:21","modified_gmt":"2021-04-19T15:30:21","slug":"convocacao-de-paulo-guedes-sera-o-teste-dos-independentes-da-cpi","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/denise\/convocacao-de-paulo-guedes-sera-o-teste-dos-independentes-da-cpi\/","title":{"rendered":"Convoca\u00e7\u00e3o de Paulo Guedes ser\u00e1 o teste dos &#8220;independentes&#8221; da CPI"},"content":{"rendered":"<p>    A oposi\u00e7\u00e3o promete pedir a convoca\u00e7\u00e3o do ministro da Economia, Paulo Guedes, no rol das autoridades do governo a serem ouvidas na primeira leva de depoimentos da CPI da Covid. A ideia de ouvir o ministro, por\u00e9m, est\u00e1 muito longe de ser um consenso e at\u00e9 alguns independentes consideram que levar o ministro da Economia n\u00e3o \u00e9 algo para um primeiro momento. O bom sendo, avisam alguns senadores que acompanham a CPI, indica que Guedes s\u00f3 deve ser convocado depois de ouvidas todas as autoridades de sa\u00fade e se ficar comprovado que o problema foi na abertura do cofre por parte da equipe econ\u00f4mica. <\/p>\n<p>    As primeiras semanas de trabalho dir\u00e3o se os independentes adotar\u00e3o tudo o que a oposi\u00e7\u00e3o quiser, ou v\u00e3o impor limites a esse alinhamento de uma lado e de outro. E a convoca\u00e7\u00e3o Guedes \u00e9 vista como um bom momento para testar esse limite.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A oposi\u00e7\u00e3o promete pedir a convoca\u00e7\u00e3o do ministro da Economia, Paulo Guedes, no rol das autoridades do governo a serem ouvidas na primeira leva de depoimentos da CPI da Covid. A ideia de ouvir o ministro, por\u00e9m, est\u00e1 muito longe de ser um consenso e at\u00e9 alguns independentes consideram que levar o ministro da Economia n\u00e3o \u00e9 algo para um [&hellip;]<\/p>\n","protected":false},"author":29,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-6949","post","type-post","status-publish","format-standard","hentry","category-politica"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/denise\/wp-json\/wp\/v2\/posts\/6949","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/denise\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/denise\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/denise\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/denise\/wp-json\/wp\/v2\/comments?post=6949"}],"version-history":[{"count":4,"href":"https:\/\/blogs.correiobraziliense.com.br\/denise\/wp-json\/wp\/v2\/posts\/6949\/revisions"}],"predecessor-version":[{"id":6953,"href":"https:\/\/blogs.correiobraziliense.com.br\/denise\/wp-json\/wp\/v2\/posts\/6949\/revisions\/6953"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/denise\/wp-json\/wp\/v2\/media?parent=6949"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/denise\/wp-json\/wp\/v2\/categories?post=6949"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/denise\/wp-json\/wp\/v2\/tags?post=6949"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}