{"id":13016,"date":"2026-01-15T10:47:38","date_gmt":"2026-01-15T13:47:38","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/denise\/?p=13016"},"modified":"2026-01-15T10:47:38","modified_gmt":"2026-01-15T13:47:38","slug":"a-preocupacao-dos-politicos","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/denise\/a-preocupacao-dos-politicos\/","title":{"rendered":"A preocupa\u00e7\u00e3o dos pol\u00edticos"},"content":{"rendered":"<p><em><strong>Coluna Bras\u00edlia-DF publicada na quinta-feira, 15 de janeiro de 2026, por Denise Rothenburg com Eduarda Esposito<\/strong><\/em><\/p>\n<figure id=\"attachment_13015\" aria-describedby=\"caption-attachment-13015\" style=\"width: 460px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/blogs.correiobraziliense.com.br\/denise\/wp-content\/uploads\/sites\/12\/2026\/01\/coluna-15-de-janeiro.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-13015\" src=\"https:\/\/blogs.correiobraziliense.com.br\/denise\/wp-content\/uploads\/sites\/12\/2026\/01\/coluna-15-de-janeiro-300x290.jpg\" alt=\"\" width=\"460\" height=\"445\" srcset=\"https:\/\/blogs.correiobraziliense.com.br\/denise\/wp-content\/uploads\/sites\/12\/2026\/01\/coluna-15-de-janeiro-300x290.jpg 300w, https:\/\/blogs.correiobraziliense.com.br\/denise\/wp-content\/uploads\/sites\/12\/2026\/01\/coluna-15-de-janeiro-768x743.jpg 768w, https:\/\/blogs.correiobraziliense.com.br\/denise\/wp-content\/uploads\/sites\/12\/2026\/01\/coluna-15-de-janeiro-1024x991.jpg 1024w, https:\/\/blogs.correiobraziliense.com.br\/denise\/wp-content\/uploads\/sites\/12\/2026\/01\/coluna-15-de-janeiro-1440x1394.jpg 1440w, https:\/\/blogs.correiobraziliense.com.br\/denise\/wp-content\/uploads\/sites\/12\/2026\/01\/coluna-15-de-janeiro-800x774.jpg 800w, https:\/\/blogs.correiobraziliense.com.br\/denise\/wp-content\/uploads\/sites\/12\/2026\/01\/coluna-15-de-janeiro-550x532.jpg 550w, https:\/\/blogs.correiobraziliense.com.br\/denise\/wp-content\/uploads\/sites\/12\/2026\/01\/coluna-15-de-janeiro-230x223.jpg 230w, https:\/\/blogs.correiobraziliense.com.br\/denise\/wp-content\/uploads\/sites\/12\/2026\/01\/coluna-15-de-janeiro.jpg 1996w\" sizes=\"auto, (max-width: 460px) 100vw, 460px\" \/><\/a><figcaption id=\"caption-attachment-13015\" class=\"wp-caption-text\">Cr\u00e9dito: Kleber Sales<\/figcaption><\/figure>\n<p>Primeiramente, a Pol\u00edcia Federal (PF) prendeu o pr\u00f3prio Daniel Vorcaro, dono do Banco Master, e seus s\u00f3cios. Agora, foi a vez de parentes e empres\u00e1rios, com destaque para o cunhado de Vorcaro, Fabiano Zettel, e para o investidor Nelson Tanure. Muitos est\u00e3o apreensivos com a perspectiva de uma nova fase da investiga\u00e7\u00e3o ter como alvo o bra\u00e7o pol\u00edtico do banqueiro. Por isso, ningu\u00e9m estranhe se, abertos os trabalhos do Congresso, os discursos das excel\u00eancias\u00a0que conviviam com Vorcaro forem na linha de \u201creceber uma pessoa n\u00e3o \u00e9 crime\u201d, \u201ccircular com uma pessoa n\u00e3o \u00e9 crime\u201d. Em conversas reservadas, muitos dizem que \u00e9 preciso averiguar muito a fim de evitar injusti\u00e7as, porque, antes de o esc\u00e2ndalo explodir,\u00a0o dono do Master\u00a0era tido como um empres\u00e1rio sempre se cercando de figuras poderosas como forma de se blindar. E nem todo envolvimento resultaria em cumplicidade com os crimes cometidos.<\/p>\n<p style=\"text-align: center\"><strong>\u00bb \u00bb \u00bb <\/strong><\/p>\n<p><strong>Joio\u00a0e trigo\/<\/strong> Os parlamentares de centro consideram que \u00e9 preciso identificar quem, no meio da pol\u00edtica, ajudou na constru\u00e7\u00e3o das fraudes ou se omitiu na hora de denunciar o esquema. Se\u00a0os malfeitos\u00a0tivessem sido revelados antes, muita gente n\u00e3o teria se reunido com Vorcaro.<\/p>\n<h3>A vis\u00e3o do governo sobre o Master<\/h3>\n<p>Se o caso Master virar tema da campanha presidencial deste ano, o governo j\u00e1 tem o discurso na ponta da l\u00edngua. Foi o presidente Luiz In\u00e1cio Lula da Silva quem aprovou a indica\u00e7\u00e3o de Gabriel Gal\u00edpolo, presidente do Banco Central (BC), que, acertadamente e tecnicamente, liquidou o banco de Daniel Vorcaro.<\/p>\n<h3>Arrefeceu, mas&#8230;<\/h3>\n<p>Tanto no Uni\u00e3o Brasil quanto no Progressistas tem muita gente dizendo que a candidatura do senador Fl\u00e1vio Bolsonaro (PL-RJ) ao Pal\u00e1cio do Planalto foi um balde de \u00e1gua fria na federa\u00e7\u00e3o entre os dois partidos. Mas os presidentes das respectivas agremia\u00e7\u00f5es continuam apostando na jun\u00e7\u00e3o das duas legendas para gastar menos na elei\u00e7\u00e3o de deputados federais.<\/p>\n<h3>Noves fora&#8230;<\/h3>\n<p>O c\u00e1lculo das dire\u00e7\u00f5es \u00e9 de que a federa\u00e7\u00e3o interessa porque ser\u00e3o dois partidos lan\u00e7ando candidatos como se fosse um s\u00f3. Isso significa que d\u00e1 para dividir os custos das campanhas.<\/p>\n<h3>O que vem por a\u00ed<\/h3>\n<p>Os mesmos deputados que prometem trabalhar para derrubar os vetos da Lei de Diretrizes Or\u00e7ament\u00e1rias (LDO) a respeito dos valores inscritos na conta \u201crestos a pagar\u201d v\u00e3o lutar para que seja derrubado tamb\u00e9m o veto \u00e0s emendas.<\/p>\n<h3>Mais uma tens\u00e3o<\/h3>\n<p>No governo, por\u00e9m, o que se diz \u00e9 que o dinheiro \u00e9 um s\u00f3 e os pol\u00edticos ter\u00e3o que escolher: ou os \u201crestos a pagar\u201d ou as emendas deste ano. N\u00e3o tem\u00a0recursos para executar tudo.<\/p>\n<h3>CURTIDAS<\/h3>\n<figure id=\"attachment_13014\" aria-describedby=\"caption-attachment-13014\" style=\"width: 300px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/blogs.correiobraziliense.com.br\/denise\/wp-content\/uploads\/sites\/12\/2026\/01\/paulo-teixeira.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-13014\" src=\"https:\/\/blogs.correiobraziliense.com.br\/denise\/wp-content\/uploads\/sites\/12\/2026\/01\/paulo-teixeira-300x199.jpg\" alt=\"\" width=\"300\" height=\"199\" srcset=\"https:\/\/blogs.correiobraziliense.com.br\/denise\/wp-content\/uploads\/sites\/12\/2026\/01\/paulo-teixeira-300x199.jpg 300w, https:\/\/blogs.correiobraziliense.com.br\/denise\/wp-content\/uploads\/sites\/12\/2026\/01\/paulo-teixeira-768x510.jpg 768w, https:\/\/blogs.correiobraziliense.com.br\/denise\/wp-content\/uploads\/sites\/12\/2026\/01\/paulo-teixeira-1024x681.jpg 1024w, https:\/\/blogs.correiobraziliense.com.br\/denise\/wp-content\/uploads\/sites\/12\/2026\/01\/paulo-teixeira-1440x957.jpg 1440w, https:\/\/blogs.correiobraziliense.com.br\/denise\/wp-content\/uploads\/sites\/12\/2026\/01\/paulo-teixeira-800x532.jpg 800w, https:\/\/blogs.correiobraziliense.com.br\/denise\/wp-content\/uploads\/sites\/12\/2026\/01\/paulo-teixeira-550x366.jpg 550w, https:\/\/blogs.correiobraziliense.com.br\/denise\/wp-content\/uploads\/sites\/12\/2026\/01\/paulo-teixeira-230x153.jpg 230w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-13014\" class=\"wp-caption-text\">Cr\u00e9dito: Marcelo Ferreira\/CB\/D.A Press<\/figcaption><\/figure>\n<p><strong>Embate\/<\/strong> A regulamenta\u00e7\u00e3o do trabalho para quem presta servi\u00e7o a aplicativos ainda vai demorar. Mesmo com o parecer do projeto entregue em dezembro pelo relator, deputado Augusto Coutinho (Republicanos-PE), as empresas do setor apresentaram um documento de 60 p\u00e1ginas com supostos dados que comprovam o aumento do valor cobrado pelos servi\u00e7os, caso o texto seja aprovado. Contudo, a comiss\u00e3o s\u00f3 vai voltar a se debru\u00e7ar\u00a0sobre a mat\u00e9ria em fevereiro, no retorno dos trabalhos legislativos.<\/p>\n<p><strong>Ficou ruim\/<\/strong> A contar pelo que se diz nos bastidores, deve ficar apenas naquela decis\u00e3o a bronca p\u00fablica que o ministro Dias Toffoli deu na Pol\u00edcia Federal (PF) ao reclamar do n\u00e3o cumprimento do prazo da opera\u00e7\u00e3o\u00a0relacionada ao Banco Master. O foco deve ser a apura\u00e7\u00e3o das fraudes e a puni\u00e7\u00e3o aos culpados.<\/p>\n<blockquote><p>&#8220;Foi uma decis\u00e3o acertada cortar uma parte das emendas. Tem que haver um equil\u00edbrio entre os pedidos dos parlamentares e a execu\u00e7\u00e3o das pol\u00edticas p\u00fablicas\u201d\u00a0<strong><em>Do ministro do Desenvolvimento Agr\u00e1rio e Agricultura Familiar, Paulo Teixeira (foto), em entrevista ao Frente a Frente, da Rede Vida<\/em><\/strong><\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Coluna Bras\u00edlia-DF publicada na quinta-feira, 15 de janeiro de 2026, por Denise Rothenburg com Eduarda Esposito Primeiramente, a Pol\u00edcia Federal (PF) prendeu o pr\u00f3prio Daniel Vorcaro, dono do Banco Master, e seus s\u00f3cios. Agora, foi a vez de parentes e empres\u00e1rios, com destaque para o cunhado de Vorcaro, Fabiano Zettel, e para o investidor Nelson Tanure. Muitos est\u00e3o apreensivos com [&hellip;]<\/p>\n","protected":false},"author":29,"featured_media":13015,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[505,4,78,618,725,10,1448,804,205,5,281,299],"tags":[481,1167,134,1498,47,34,1544,1211],"class_list":["post-13016","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-camara-dos-deputados","category-coluna-brasilia-df","category-congresso","category-crise-entre-os-poderes","category-economia","category-eleicoes","category-eleicoes-2026","category-governo-lula","category-lula","category-politica","category-senado","category-stf","tag-banco-central","tag-banco-master","tag-congresso-nacional","tag-daniel-vorcaro","tag-flavio-bolsonaro","tag-stf","tag-trabalhadores-por-app","tag-uniao-progressistas"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/denise\/wp-json\/wp\/v2\/posts\/13016","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/denise\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/denise\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/denise\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/denise\/wp-json\/wp\/v2\/comments?post=13016"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/denise\/wp-json\/wp\/v2\/posts\/13016\/revisions"}],"predecessor-version":[{"id":13017,"href":"https:\/\/blogs.correiobraziliense.com.br\/denise\/wp-json\/wp\/v2\/posts\/13016\/revisions\/13017"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/denise\/wp-json\/wp\/v2\/media\/13015"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/denise\/wp-json\/wp\/v2\/media?parent=13016"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/denise\/wp-json\/wp\/v2\/categories?post=13016"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/denise\/wp-json\/wp\/v2\/tags?post=13016"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}