{"id":9412,"date":"2014-09-30T13:00:00","date_gmt":"2014-09-30T16:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/erramos-1281\/"},"modified":"2015-11-12T12:45:14","modified_gmt":"2015-11-12T14:45:14","slug":"erramos-1281","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/erramos-1281\/","title":{"rendered":"Erramos"},"content":{"rendered":"<p><br style=\"font-family: Times New Roman,Times,serif\">\u201cO diretor do Banco Central (BC), Carlos Hamilton Ara\u00fajo, n\u00e3o acredita que as proje\u00e7\u00f5es da autarquia sejam otimistas\u201d, escrevemos na p\u00e1g. 7. O texto diz que o BC s\u00f3 tem esse diretor. Engana-nos. que tal fazer as pazes com a verdade? O termo restritivo dispensa v\u00edrgulas: O diretor do Banco Central (BC) Carlos Hamilton Ara\u00fajo n\u00e3o acredita que as proje\u00e7\u00f5es da autarquia sejam otimistas.<br style=\"font-family: Times New Roman,Times,serif\"> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cO diretor do Banco Central (BC), Carlos Hamilton Ara\u00fajo, n\u00e3o acredita que as proje\u00e7\u00f5es da autarquia sejam otimistas\u201d, escrevemos na p\u00e1g. 7. O texto diz que o BC s\u00f3 tem esse diretor. Engana-nos. que tal fazer as pazes com a verdade? O termo restritivo dispensa v\u00edrgulas: O diretor do Banco Central (BC) Carlos Hamilton Ara\u00fajo n\u00e3o acredita que as proje\u00e7\u00f5es da autarquia sejam otimistas.<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,1],"tags":[],"class_list":["post-9412","post","type-post","status-publish","format-standard","hentry","category-erramos","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/9412","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=9412"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/9412\/revisions"}],"predecessor-version":[{"id":9519,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/9412\/revisions\/9519"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=9412"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=9412"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=9412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}