{"id":9391,"date":"2014-09-23T17:00:00","date_gmt":"2014-09-23T20:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/cochilos_da_revisao-76\/"},"modified":"2014-09-23T17:00:00","modified_gmt":"2014-09-23T20:00:00","slug":"cochilos_da_revisao-76","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/cochilos_da_revisao-76\/","title":{"rendered":"Cochilos da revis\u00e3o"},"content":{"rendered":"<div style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">\n<p>Flat\u00f4nio Jos\u00e9 da Silva<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"><br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">No t\u00edtulo &#8220;Mapa para o dia da vota\u00e7\u00e3o&#8221;, saiu este  texto:<\/div>\n<div style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">\n<\/div>\n<div style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&#8220;N\u00e3o \u00e9 necess\u00e1rio o t\u00edtulo de leitor no dia da vota\u00e7\u00e3o, desde que a  pessoa esteja no domic\u00edlio eleitoral. Mas \u00e9 preciso levar o n\u00famero da  <strong>sess\u00e3o<\/strong> e o local de vota\u00e7\u00e3o, al\u00e9m de  um documento oficial com foto&#8221;. <\/div>\n<div style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">\n<p>Corrigindo: <strong>se\u00e7\u00e3o<\/strong>.  <\/div>\n<div style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">\n<p>Explica\u00e7\u00e3o &#8211; Erro de grafia. Veja a diferen\u00e7a entre 1.  <strong>Se\u00e7\u00e3o<\/strong> =&gt; divis\u00e3o, reparti\u00e7\u00e3o, segmento, parte de um todo:  Se\u00e7\u00e3o Eleitoral, Se\u00e7\u00e3o de Tr\u00e1fego, Se\u00e7\u00e3o de Esportes, se\u00e7\u00e3o de metais  (numa orquestra), se\u00e7\u00e3o de brinquedos ou de roupas;  <\/p>\n<p>2.  <strong>Sess\u00e3o<\/strong> =&gt; tempo que dura uma reuni\u00e3o, espet\u00e1culo ou  trabalho: sess\u00e3o de cinema, sess\u00e3o de teatro, sess\u00e3o de fotos, sess\u00e3o do  Congresso Nacional; 3. <strong>Cess\u00e3o<\/strong> =&gt; ato de ceder:  cess\u00e3o de bens, cess\u00e3o de direitos, cess\u00e3o de um pr\u00e9dio.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Flat\u00f4nio Jos\u00e9 da SilvaNo t\u00edtulo &#8220;Mapa para o dia da vota\u00e7\u00e3o&#8221;, saiu este texto: &#8220;N\u00e3o \u00e9 necess\u00e1rio o t\u00edtulo de leitor no dia da vota\u00e7\u00e3o, desde que a pessoa esteja no domic\u00edlio eleitoral. Mas \u00e9 preciso levar o n\u00famero da sess\u00e3o e o local de vota\u00e7\u00e3o, al\u00e9m de um documento oficial com foto&#8221;. Corrigindo: se\u00e7\u00e3o. Explica\u00e7\u00e3o &#8211; Erro de grafia. Veja a diferen\u00e7a entre 1. [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-9391","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/9391","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=9391"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/9391\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=9391"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=9391"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=9391"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}