{"id":9367,"date":"2014-04-24T15:30:00","date_gmt":"2014-04-24T18:30:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/obrigado\/"},"modified":"2014-04-24T15:30:00","modified_gmt":"2014-04-24T18:30:00","slug":"obrigado","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/obrigado\/","title":{"rendered":"Obrigado"},"content":{"rendered":"<p>  <strong> <\/p>\n<p><\/strong>  Ela diz obrigada. Ele, obrigado. Novidade? N\u00e3o. A regra \u00e9  velha como o rascunho da <i>B\u00edblia<\/i>. Mas, na Bienal de Bras\u00edlia, a premiada  escritora Ana Miranda disse &#8220;Aos presentes meu obrigado&#8221;. Ops! N\u00e3o seria  obrigada? Fa\u00e7a a sua aposta. Ela pisou a l\u00edngua?   <\/p>\n<p>N\u00e3o. No caso, a palavra \u00e9 um substantivo. Duvida? Banque o  S\u00e3o Tom\u00e9. Substitua <i>obrigado<\/i> por <i>agradecimento<\/i>: <i>Aos presentes  meu agradecimento<\/i>.  <strong><\/strong>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ela diz obrigada. Ele, obrigado. Novidade? N\u00e3o. A regra \u00e9 velha como o rascunho da B\u00edblia. Mas, na Bienal de Bras\u00edlia, a premiada escritora Ana Miranda disse &#8220;Aos presentes meu obrigado&#8221;. Ops! N\u00e3o seria obrigada? Fa\u00e7a a sua aposta. Ela pisou a l\u00edngua? N\u00e3o. No caso, a palavra \u00e9 um substantivo. Duvida? Banque o S\u00e3o Tom\u00e9. Substitua obrigado por agradecimento: Aos presentes meu agradecimento. &nbsp;<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-9367","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/9367","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=9367"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/9367\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=9367"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=9367"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=9367"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}