{"id":9358,"date":"2014-04-23T10:00:00","date_gmt":"2014-04-23T13:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/a_copa_da_lingua\/"},"modified":"2014-04-23T10:00:00","modified_gmt":"2014-04-23T13:00:00","slug":"a_copa_da_lingua","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/a_copa_da_lingua\/","title":{"rendered":"A Copa da l\u00edngua"},"content":{"rendered":"\n<p>Quem manda neste pa\u00eds tropical? \u00c9 a Fifa. A poderosa  federa\u00e7\u00e3o fala mais alto que presidentes da Rep\u00fablica, primeiros-ministros, reis  e imperadores. Por isso deita e rola nesta alegre Pindorama. Em junho, o Brasil  sedia a Copa do Mundo. Construiu est\u00e1dios, mudou a sinaliza\u00e7\u00e3o das ruas, deu  dec\u00eancia a aeroportos, ampliou o n\u00famero de leitos. E o time? A Sele\u00e7\u00e3o ainda n\u00e3o  mostrou firmeza. Talvez chegue l\u00e1. A l\u00edngua lhe d\u00e1 senhora ajuda. O xis da  vit\u00f3ria: a coes\u00e3o.<b style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">   <\/p>\n<p>Texto e equipe<\/b>   <\/p>\n<p>Imagine a situa\u00e7\u00e3o. Com carta branca, Felip\u00e3o forma o time com os melhores jogadores do mundo.  Todos do n\u00edvel de Cristiano Ronaldo, Messi, Neymar. Confiante no talento  individual, p\u00f5e a equipe em campo antes de  definir a posi\u00e7\u00e3o e&nbsp;a movimenta\u00e7\u00e3o de cada  um pra atingir o objetivo. Qual? O gol, claro. Sem plano que as oriente, as criaturas n\u00e3o formam conjunto. E, claro,  n\u00e3o se entendem. Correm sem rumo, chutam a  esmo, estranham a bola.&nbsp;S\u00e3o 11 Pel\u00e9s  transformados em 11 patetas. O resultado? Fiasco nota 10.    <\/p>\n<p>A imagem vale para a reda\u00e7\u00e3o. Belas ideias, belas palavras e  belas frases n\u00e3o resultam necessariamente em bom texto. Pra chegar \u00e0 unidade de  composi\u00e7\u00e3o, elas precisam se articular \u2014 entrosar-se com clareza, harmonia e  coer\u00eancia. Em bom portugu\u00eas: as palavras t\u00eam de conversar pra formar per\u00edodos.  Os per\u00edodos t\u00eam de conversar pra formar par\u00e1grafos. Os par\u00e1grafos t\u00eam de  conversar pra formar o texto. O bate-papo tem nome. Chama-se coes\u00e3o textual.  <b style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">   <\/p>\n<p>Coes\u00e3o <\/b>  <\/p>\n<p>&#8220;Socooooooooooooooooooooooooorro!&#8221;, gritam os concurseiros  de Europa, Fran\u00e7a e Bahia. O motivo: perdem pontos a rodo num tal item chamado  coes\u00e3o. Eles procuram o assunto nas gram\u00e1ticas. N\u00e3o encontram. Celsos Cunhas,  Becharas, Cegallas n\u00e3o dedicam nenhum cap\u00edtulo ao tema. Por qu\u00ea?    <\/p>\n<p>A raz\u00e3o \u00e9 simples. Coes\u00e3o est\u00e1 presente na morfologia, na  sintaxe, nas figuras de linguagem. Ao estudar substantivos, verbos, pronomes,  conjun\u00e7\u00f5es, preposi\u00e7\u00f5es, coordena\u00e7\u00e3o, subordina\u00e7\u00e3o, etc. e tal, indiretamente  estudamos coes\u00e3o. Eles oferecem recursos pra ligar palavras, ligar per\u00edodos,  ligar par\u00e1grafos. Em suma: juntar partes soltas em unidades coerentes.  <i style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"> <\/i><i>  <\/p>\n<p><\/i><i>Anel<\/i> e <i>ouro<\/i> s\u00e3o duas  palavras que n\u00e3o se conhecem nem de elevador. Mas formam unidade com a ajuda da  preposi\u00e7\u00e3o de: <i>anel de ouro<\/i>. <i style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">   <\/p>\n<p>***   <\/p>\n<p>Cozinho, estamos sem  empregada. <\/i>   <\/p>\n<p>Que rela\u00e7\u00e3o existe entre enunciados assim independentes? A  conjun\u00e7\u00e3o se encarrega de p\u00f4r os pontos nos ii. Ela pode indicar causa (cozinho  porque estamos sem empregada). Pode indicar tempo (cozinho quando estamos sem  empregada). Pode indicar dura\u00e7\u00e3o (cozinho enquanto estamos sem empregada). Pode  indicar condi\u00e7\u00e3o (cozinho se estamos sem empregada). <b style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">   <\/p>\n<p><\/b><b style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"> Mais<\/b>   <\/p>\n<p>Pronomes exercem duplo papel. Al\u00e9m de auxiliar a coes\u00e3o,  contribuem para a eleg\u00e2ncia. Como? Evitam repeti\u00e7\u00f5es. Veja: <i style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"> <\/i><i>  <\/p>\n<p><\/i><i>Rafael e Jo\u00e3o Marcelo s\u00e3o irm\u00e3os. Este estuda medicina;  aquele, direito.<\/i> (Este substitui Jo\u00e3o Marcelo;  aquele, Rafael.)<i style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">   <\/p>\n<p>Neymar foi pra Espanha no ano passado. Ele e a fam\u00edlia se  mudaram para Barcelona.<\/i>   <\/p>\n<p>Nem toda repeti\u00e7\u00e3o \u00e9 m\u00e1. A estil\u00edstica d\u00e1 liga e charme ao  texto. \u00c9 o caso deste trecho: <i style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">   <\/p>\n<p>A cultura do desperd\u00edcio tem de ser desmontada por dentro. \u00c9  preciso que os brasileiros n\u00e3o joguem fora restos de comida aproveit\u00e1veis nem  deixem as l\u00e2mpadas acesas quando saem de um aposento. \u00c9 preciso que os livros  escolares sejam aproveitados pelos irm\u00e3os menores. \u00c9 preciso n\u00e3o destruir os  bens p\u00fablicos. \u00c9 preciso, enfim, martelar insistentemente na necessidade de  poupar.<\/i>   <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quem manda neste pa\u00eds tropical? \u00c9 a Fifa. A poderosa federa\u00e7\u00e3o fala mais alto que presidentes da Rep\u00fablica, primeiros-ministros, reis e imperadores. Por isso deita e rola nesta alegre Pindorama. Em junho, o Brasil sedia a Copa do Mundo. Construiu est\u00e1dios, mudou a sinaliza\u00e7\u00e3o das ruas, deu dec\u00eancia a aeroportos, ampliou o n\u00famero de leitos. E o time? A Sele\u00e7\u00e3o ainda n\u00e3o mostrou firmeza. Talvez [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-9358","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/9358","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=9358"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/9358\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=9358"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=9358"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=9358"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}