{"id":9349,"date":"2014-09-16T10:30:00","date_gmt":"2014-09-16T13:30:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/qual_a_leitura\/"},"modified":"2014-09-16T10:30:00","modified_gmt":"2014-09-16T13:30:00","slug":"qual_a_leitura","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/qual_a_leitura\/","title":{"rendered":"Qual a leitura?"},"content":{"rendered":"<p><b style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"> <\/p>\n<p><\/b> M\u00e1rio Quintana costumava repetir: &#8220;O autor pensa uma coisa,  escreve outra, o leitor entende outra, e a coisa propriamente dita desconfia que  n\u00e3o foi dita&#8221;. Verdade? Esta passagem confirma: &#8220;Celebrando a carreira e a vida,  Eva Wilma estrela espet\u00e1culo latino-americano sobre o of\u00edcio de ator na capital  federal&#8221;. Interessados leram e releram. Com a pulga atr\u00e1s da orelha,  perguntaram: &#8220;O of\u00edcio de ator ser\u00e1 diferente na capital federal?    <\/p>\n<p>N\u00e3o. O texto permite a leitura equivocada. Trata-se de  problema de coloca\u00e7\u00e3o. No lugar onde est\u00e1, o termo &#8220;na capital federal&#8221; parece  se referir a &#8220;of\u00edcio de ator&#8221;. Mas o alvo \u00e9 outro. Como mandar a ambiguidade  plantar batata no asfalto? Basta aproximar l\u00e9 com l\u00e9 e cr\u00e9 com cr\u00e9. Assim:      <i>Celebrando a carreira e a vida, Eva Wilma estrela, na capital federal,  espet\u00e1culo latino-americano sobre o of\u00edcio de ator. <\/i>Simples  assim. <b style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"> &nbsp;<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e1rio Quintana costumava repetir: &#8220;O autor pensa uma coisa, escreve outra, o leitor entende outra, e a coisa propriamente dita desconfia que n\u00e3o foi dita&#8221;. Verdade? Esta passagem confirma: &#8220;Celebrando a carreira e a vida, Eva Wilma estrela espet\u00e1culo latino-americano sobre o of\u00edcio de ator na capital federal&#8221;. Interessados leram e releram. Com a pulga atr\u00e1s da orelha, perguntaram: &#8220;O of\u00edcio de ator ser\u00e1 diferente [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-9349","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/9349","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=9349"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/9349\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=9349"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=9349"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=9349"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}