{"id":9348,"date":"2014-04-21T09:00:00","date_gmt":"2014-04-21T12:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/xo_solidao-2\/"},"modified":"2014-04-21T09:00:00","modified_gmt":"2014-04-21T12:00:00","slug":"xo_solidao-2","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/xo_solidao-2\/","title":{"rendered":"X\u00f4, solid\u00e3o"},"content":{"rendered":"<p><b> <\/b>  <\/p>\n<p>O substantivo P\u00e1scoa se sentiu solit\u00e1rio. Que tal uma  fam\u00edlia jeitosa? Oba! Pediu socorro ao sufixo -al. Com ele, formou os adjetivos  <i style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">pascal<\/i> e <i style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">pascoal<\/i>. As duas letrinhas aparecem em mont\u00f5es de  adjetivos. Em todos, t\u00eam o mesmo significado. Quer dizer <i style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">relacionado com,  pertinente a.<\/i> Pascal e pascoal s\u00e3o relacionados com a  P\u00e1scoa (festa pascal, Monte Pascoal). Campal, com campo (batalha  campal). Matrimonial, com matrim\u00f4nio (festa matrimonial). E por a\u00ed vai.     <\/p>\n","protected":false},"excerpt":{"rendered":"<p>O substantivo P\u00e1scoa se sentiu solit\u00e1rio. Que tal uma fam\u00edlia jeitosa? Oba! Pediu socorro ao sufixo -al. Com ele, formou os adjetivos pascal e pascoal. As duas letrinhas aparecem em mont\u00f5es de adjetivos. Em todos, t\u00eam o mesmo significado. Quer dizer relacionado com, pertinente a. Pascal e pascoal s\u00e3o relacionados com a P\u00e1scoa (festa pascal, Monte Pascoal). Campal, com campo (batalha campal). Matrimonial, com matrim\u00f4nio [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-9348","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/9348","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=9348"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/9348\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=9348"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=9348"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=9348"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}