{"id":9339,"date":"2014-09-15T00:00:00","date_gmt":"2014-09-15T03:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/leitor_pergunta-234\/"},"modified":"2015-11-12T19:43:17","modified_gmt":"2015-11-12T21:43:17","slug":"leitor_pergunta-234","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/leitor_pergunta-234\/","title":{"rendered":"Leitor pergunta"},"content":{"rendered":"<p><br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">    <\/p>\n<p>A palavra est\u00f3ria ainda existe? (Clara Naves) <\/p>\n<p><br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">    <\/p>\n<p>&nbsp;Est\u00f3ria  e hist\u00f3ria est\u00e3o no dicion\u00e1rio. Mas est\u00f3ria caiu em desgra\u00e7a. Est\u00e1 em  desuso. Hist\u00f3ria reina sozinha. Tem a acep\u00e7\u00e3o de fato e fic\u00e7\u00e3o: Hist\u00f3ria  do Brasil, hist\u00f3ria da Branca de Neve.<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">    <\/p>\n","protected":false},"excerpt":{"rendered":"<p>A palavra est\u00f3ria ainda existe? (Clara Naves) &nbsp;Est\u00f3ria e hist\u00f3ria est\u00e3o no dicion\u00e1rio. Mas est\u00f3ria caiu em desgra\u00e7a. Est\u00e1 em desuso. Hist\u00f3ria reina sozinha. Tem a acep\u00e7\u00e3o de fato e fic\u00e7\u00e3o: Hist\u00f3ria do Brasil, hist\u00f3ria da Branca de Neve.<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,14],"tags":[],"class_list":["post-9339","post","type-post","status-publish","format-standard","hentry","category-geral","category-leitor-pergunta"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/9339","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=9339"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/9339\/revisions"}],"predecessor-version":[{"id":11209,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/9339\/revisions\/11209"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=9339"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=9339"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=9339"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}