{"id":9332,"date":"2014-09-12T13:00:00","date_gmt":"2014-09-12T16:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/erramos-1265\/"},"modified":"2015-11-12T12:45:18","modified_gmt":"2015-11-12T14:45:18","slug":"erramos-1265","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/erramos-1265\/","title":{"rendered":"Erramos"},"content":{"rendered":"<div style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">\n<p>&#8220;\u2026\u00e9 preciso mecanismos como o controle social dos meios de comunica\u00e7\u00e3o e os  conselhos populares, que implicam em limita\u00e7\u00f5es \u00f3bvias para a liberdade de  imprensa\u2026&#8221;, escrevemos na p\u00e1g. 3. Viu? O verbo implicar implica e complica. Na  acep\u00e7\u00e3o de acarretar consequ\u00eancias, dispensa a preposi\u00e7\u00e3o. Assim: <i>\u2026\u00e9 preciso  mecanismos como o controle social dos meios de comunica\u00e7\u00e3o e os conselhos  populares, que implicam limita\u00e7\u00f5es \u00f3bvias para a liberdade de  imprensa.<\/i><\/div>\n<div style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;<\/div>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;\u2026\u00e9 preciso mecanismos como o controle social dos meios de comunica\u00e7\u00e3o e os conselhos populares, que implicam em limita\u00e7\u00f5es \u00f3bvias para a liberdade de imprensa\u2026&#8221;, escrevemos na p\u00e1g. 3. Viu? O verbo implicar implica e complica. Na acep\u00e7\u00e3o de acarretar consequ\u00eancias, dispensa a preposi\u00e7\u00e3o. Assim: \u2026\u00e9 preciso mecanismos como o controle social dos meios de comunica\u00e7\u00e3o e os conselhos populares, que implicam limita\u00e7\u00f5es \u00f3bvias para [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,1],"tags":[],"class_list":["post-9332","post","type-post","status-publish","format-standard","hentry","category-erramos","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/9332","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=9332"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/9332\/revisions"}],"predecessor-version":[{"id":9529,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/9332\/revisions\/9529"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=9332"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=9332"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=9332"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}